{"id":21353,"date":"2020-03-24T11:35:01","date_gmt":"2020-03-24T17:35:01","guid":{"rendered":"https:\/\/memberpress.com\/?post_type=cpmu-add-ons&#038;p=21353"},"modified":"2026-07-16T08:21:53","modified_gmt":"2026-07-16T12:21:53","slug":"pdf-invoice","status":"publish","type":"cpmu-add-ons","link":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/","title":{"rendered":"PDF-Rechnung"},"content":{"rendered":"<p>Wahrscheinlich haben Sie bereits Anfragen von Mitgliedern nach PDF-Rechnungen erhalten. Mit dem Add-on \u201ePDF-Rechnung\u201c k\u00f6nnen Sie Ihren Kunden nun die M\u00f6glichkeit geben, f\u00fcr jede Transaktion selbst eine PDF-Rechnung herunterzuladen.<\/p>\n<p>PDF-Rechnung erleichtert Ihren Kunden die Einhaltung von Vorschriften, bietet ihnen ein nahtloses Markenerlebnis und spart ihnen Zeit. Genie\u00dfen Sie ein einfach zu bedienendes Dashboard und w\u00e4hlen Sie aus zwei attraktiven Designs.<\/p>\n<p>Zus\u00e4tzlich erm\u00f6glicht das Add-on <a href=\"https:\/\/memberpress.com\/de\/docs\/memberpress-proforma-invoices\/\" target=\"_blank\" rel=\"noopener\">Proforma-Rechnungen<\/a> f\u00fcr Abonnements, die \u00fcber das Offline-Gateway abgewickelt werden. Diese Rechnungen werden bei jeder Erneuerung automatisch f\u00fcr Ihre Kunden erstellt, um eine nahtlose Erneuerung von Offline-Abonnements zu gew\u00e4hrleisten.<\/p>\n<p>ARTIKEL &gt;&gt; <a href=\"https:\/\/memberpress.com\/de\/blog\/announcing-pdf-invoices\/\" target=\"_blank\" rel=\"noopener\">Bevorzugtes Tool: MemberPress PDF-Rechnungen Add-On<\/a><\/p>\n<p><strong>\u00c4nderungsliste<br \/><\/strong>1.2.2 \u2013 16.07.2026<br \/>* Fehler behoben, durch den bei der Installation\/Aktualisierung ein falsches Add-on heruntergeladen wurde<br \/>1.2.1 \u2013 07.04.2026<br \/>* Problem beim Laden der \u00dcbersetzung beheben<br \/>1.2.0 - 08\/20\/2025<br \/>* Automatische Verl\u00e4ngerungen, PDF-Proforma-Rechnung und E-Mail-Benachrichtigung f\u00fcr Offline-Gateway-Abonnements hinzugef\u00fcgt<br \/>* Behebung des Fehlers bei der Division durch Null in Geschenktransaktionen<br \/>* Haken in Schlangenh\u00fclse \u00e4ndern<br \/>* Verbesserung der Zug\u00e4nglichkeit der Download-Spalte<br \/>1.1.31 - 11\/28\/2024<br \/>* \u00dcbersetzungen korrigieren<br \/>1.1.30 - 09\/25\/2024<br \/>* Behebung der SQL-Injection-Schwachstelle in der Rechnung<br \/>1.1.29 - 05\/03\/2024<br \/>* Zus\u00e4tzliche Korrektur eines Konflikts mit anderen Plugins, die mPDF verwenden<br \/>1.1.28 - 04\/26\/2024<br \/>* Behebung eines fatalen Fehlers bei PHP < 8.0<br \/>1.1.27 - 04\/19\/2024<br \/>* Konflikt mit mPDF behoben<br \/>1.1.26 - 02\/20\/2024<br \/>* Korrigiert den falschen Betrag, der in einigen F\u00e4llen angezeigt wurde, wenn das Abonnement eine Probezeit hatte<strong><br \/><\/strong>1.1.25 - 01\/16\/2024<br \/>* Behebung eines fatalen Fehlers bei Rechnungen mit 100% Coupon<br \/>1.1.24 - 12\/08\/2023<br \/>* Coupon-Rabatt f\u00fcr einmalige Mitgliedschaften funktioniert nicht mehr<br \/>* Rechnung mit negativer Steueroption korrigieren<br \/>1.1.23 - 08\/04\/2023<br \/>* Ersetzen Sie den Produktpreis in der Rechnung durch die Gesamtsumme der Transaktion, um Probleme zu vermeiden, wenn sich der Mitgliedschaftspreis \u00e4ndert.<br \/>1.1.22 - 06\/07\/2023<br \/>* Korrektur der umgekehrten Mehrwertsteuer<br \/>* Behebung des Problems, dass PDF nicht gerendert werden kann, wenn nicht alle Ausgabepuffer gel\u00f6scht wurden<br \/>1.1.21 - 05\/17\/2023<br \/>* Fehlende Position in der Rechnung f\u00fcr den Bestellungssto\u00df Kaufzahlung txn beheben<br \/>* PHP-Warnung behoben, wenn biz country nicht gesetzt ist<br \/>* Korrektur des falschen Preises f\u00fcr Rabattcoupons f\u00fcr die erste Zahlung<br \/>1.1.20 - 04\/25\/2023<br \/>* Hinzuf\u00fcgen von Auftr\u00e4gen zur Rechnung f\u00fcr Order Bumps Add-on<\/p>","protected":false},"excerpt":{"rendered":"<p>Wahrscheinlich haben Sie schon Anfragen von Mitgliedern nach PDF-Rechnungen erhalten. Mit dem PDF-Rechnungs-Add-on k\u00f6nnen Sie Ihren Kunden jetzt erlauben, f\u00fcr jede Transaktion eine PDF-Rechnung herunterzuladen - selbst.<\/p>","protected":false},"featured_media":73060,"parent":0,"template":"","class_list":["post-21353","cpmu-add-ons","type-cpmu-add-ons","status-publish","has-post-thumbnail","cpmu-add-on-category-growth","cpmu-add-on-category-scale","cpmu-integration-tag-downloads","cpmu-integration-tag-extensions","cpmu-integration-tag-payments","entry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Chances are you&#039;ve received requests from members for PDF invoices. Now, with the PDF Invoice Add-on, you can allow your customers to download a PDF invoice...\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"keywords\" content=\"memberpress pdf invoice add on,memberpress and pdf invoice\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"PDF Invoice Add-On | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"Chances are you&#039;ve received requests from members for PDF invoices. Now, with the PDF Invoice Add-on, you can allow your customers to download a PDF invoice...\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2020\/03\/Integrations-MP-PDF-Invoice-1724x970-1.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2020\/03\/Integrations-MP-PDF-Invoice-1724x970-1.svg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1724\" \/>\n\t\t<meta property=\"og:image:height\" content=\"970\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-03-24T17:35:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-16T12:21:53+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"PDF Invoice Add-On | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Chances are you&#039;ve received requests from members for PDF invoices. Now, with the PDF Invoice Add-on, you can allow your customers to download a PDF invoice...\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2020\/03\/Integrations-MP-PDF-Invoice-1724x970-1.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/pdf-invoice\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/#listItem\",\"name\":\"Add-Ons\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/#listItem\",\"position\":2,\"name\":\"Add-Ons\",\"item\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/add-on-category\\\/growth\\\/#listItem\",\"name\":\"Growth\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/add-on-category\\\/growth\\\/#listItem\",\"position\":3,\"name\":\"Growth\",\"item\":\"https:\\\/\\\/memberpress.com\\\/de\\\/add-on-category\\\/growth\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/pdf-invoice\\\/#listItem\",\"name\":\"PDF Invoice\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/#listItem\",\"name\":\"Add-Ons\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/pdf-invoice\\\/#listItem\",\"position\":4,\"name\":\"PDF Invoice\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/add-on-category\\\/growth\\\/#listItem\",\"name\":\"Growth\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/pdf-invoice\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/pdf-invoice\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/pdf-invoice\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/pdf-invoice\\\/\",\"name\":\"PDF Invoice Add-On | MemberPress\",\"description\":\"Chances are you've received requests from members for PDF invoices. Now, with the PDF Invoice Add-on, you can allow your customers to download a PDF invoice...\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/pdf-invoice\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Integrations-MP-PDF-Invoice-1724x970-1.svg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/pdf-invoice\\\/#mainImage\",\"width\":1724,\"height\":970,\"caption\":\"MemberPress PDF Invoice Add-On\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/addons\\\/pdf-invoice\\\/#mainImage\"},\"datePublished\":\"2020-03-24T11:35:01-04:00\",\"dateModified\":\"2026-07-16T08:21:53-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/de\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>PDF Invoice Add-On | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"PDF-Rechnungserweiterung | MemberPress","description":"Wahrscheinlich haben Sie schon Anfragen von Mitgliedern nach PDF-Rechnungen erhalten. Mit dem PDF-Rechnungs-Add-on k\u00f6nnen Sie Ihren Kunden jetzt erm\u00f6glichen, eine PDF-Rechnung herunterzuladen...","canonical_url":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/","robots":"max-image-preview:large","keywords":"memberpress pdf invoice add on,memberpress and pdf invoice","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/addons\/#listItem","name":"Add-Ons"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/addons\/#listItem","position":2,"name":"Add-Ons","item":"https:\/\/memberpress.com\/de\/addons\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/add-on-category\/growth\/#listItem","name":"Growth"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/add-on-category\/growth\/#listItem","position":3,"name":"Growth","item":"https:\/\/memberpress.com\/de\/add-on-category\/growth\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/#listItem","name":"PDF Invoice"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/addons\/#listItem","name":"Add-Ons"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/#listItem","position":4,"name":"PDF Invoice","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/add-on-category\/growth\/#listItem","name":"Growth"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/de\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/#webpage","url":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/","name":"PDF Invoice Add-On | MemberPress","description":"Chances are you've received requests from members for PDF invoices. Now, with the PDF Invoice Add-on, you can allow your customers to download a PDF invoice...","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/memberpress.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2020\/03\/Integrations-MP-PDF-Invoice-1724x970-1.svg","@id":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/#mainImage","width":1724,"height":970,"caption":"MemberPress PDF Invoice Add-On"},"primaryImageOfPage":{"@id":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/#mainImage"},"datePublished":"2020-03-24T11:35:01-04:00","dateModified":"2026-07-16T08:21:53-04:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/de\/#website","url":"https:\/\/memberpress.com\/de\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"de-DE","publisher":{"@id":"https:\/\/memberpress.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"MemberPress","og:type":"article","og:title":"PDF Invoice Add-On | MemberPress","og:description":"Chances are you've received requests from members for PDF invoices. Now, with the PDF Invoice Add-on, you can allow your customers to download a PDF invoice...","og:url":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2020\/03\/Integrations-MP-PDF-Invoice-1724x970-1.svg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2020\/03\/Integrations-MP-PDF-Invoice-1724x970-1.svg","og:image:width":1724,"og:image:height":970,"article:published_time":"2020-03-24T17:35:01+00:00","article:modified_time":"2026-07-16T12:21:53+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"PDF Invoice Add-On | MemberPress","twitter:description":"Chances are you've received requests from members for PDF invoices. Now, with the PDF Invoice Add-on, you can allow your customers to download a PDF invoice...","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2020\/03\/Integrations-MP-PDF-Invoice-1724x970-1.svg"},"aioseo_meta_data":{"post_id":"21353","title":"#post_title Add-On #separator_sa #site_title","description":"Wahrscheinlich haben Sie schon Anfragen von Mitgliedern nach PDF-Rechnungen erhalten. Mit dem PDF-Rechnungs-Add-on k\u00f6nnen Sie Ihren Kunden jetzt erm\u00f6glichen, eine PDF-Rechnung herunterzuladen...","keywords":[{"label":"memberpress pdf invoice add on","value":"memberpress pdf invoice add on"},{"label":"memberpress and pdf invoice","value":"memberpress and pdf invoice"}],"keyphrases":{"focus":{"keyphrase":"pdf invoice","score":100,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":[],"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"proforma invoice","score":67,"analysis":{"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":[],"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"none","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"none","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"book\":[],\"event\":[],\"jobPosting\":[],\"music\":[],\"person\":[],\"restaurant\":[],\"service\":[],\"video\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-07-16 12:33:38","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2020-12-21 16:17:07","updated":"2026-07-16 18:50:18","focus_keyword":"pdf invoice","additional_keywords":[{"word":"proforma invoice","score":67}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/de\/addons\/\" title=\"Add-Ons\">Add-Ons<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/de\/add-on-category\/growth\/\" title=\"Growth\">Growth<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tPDF Invoice\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/de"},{"label":"Add-Ons","link":"https:\/\/memberpress.com\/de\/addons\/"},{"label":"Growth","link":"https:\/\/memberpress.com\/de\/add-on-category\/growth\/"},{"label":"PDF Invoice","link":"https:\/\/memberpress.com\/de\/addons\/pdf-invoice\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/cpmu-add-ons\/21353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/cpmu-add-ons"}],"about":[{"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/types\/cpmu-add-ons"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/media\/73060"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/media?parent=21353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}