{"id":61386,"date":"2024-02-13T07:23:29","date_gmt":"2024-02-13T12:23:29","guid":{"rendered":"https:\/\/memberpress.com\/docs\/protecting-files\/"},"modified":"2026-01-27T08:01:03","modified_gmt":"2026-01-27T13:01:03","slug":"protecting-files","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/","title":{"rendered":"Schutz von Dateien"},"content":{"rendered":"<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\"><strong>Hinweis<\/strong>: Obwohl diese Anweisungen immer noch g\u00fcltig sind, haben wir inzwischen das MemberPress-Download-Add-on ver\u00f6ffentlicht, das das Hochladen und Sch\u00fctzen Ihrer Dateien wesentlich vereinfacht.  <a href=\"https:\/\/memberpress.com\/de\/docs\/mp-downloads-add-on\/\">Klicken Sie hier, um mehr dar\u00fcber zu erfahren<\/a>. <\/p>\n\n\n\n<div class=\"callout\">\n<p id=\"top\"><strong><u> Dieser Artikel behandelt die folgenden Themen:<\/u><\/strong><\/p>\n<ul>\n<li><a href=\"#file-types\">Welche Arten von Dateien kann MemberPress sch\u00fctzen?<\/a><\/li>\n<li><a href=\"#example\">Sch\u00fctzen einer einzelnen Datei<\/a><\/li>\n<li><a href=\"#mulitple\">Mehrere Dateien sch\u00fctzen<\/a><\/li>\n<li><a href=\"#ftp\">Mehrere Dateien mit FTP sch\u00fctzen<\/a><\/li>\n<li><a href=\"#expressions\">Regul\u00e4re Ausdr\u00fccke verwenden<\/a><\/li>\n<li><a href=\"#reqs\">Technische Anforderungen<\/a><\/li>\n<li><a href=\"#add_types\">Zus\u00e4tzliche Dateitypen sch\u00fctzen<\/a><\/li>\n<\/ul>\n<\/div>\n\n\n\n<p>MemberPress verf\u00fcgt \u00fcber einige leistungsstarke Funktionen, die Ihnen helfen, statische Dateien zu sch\u00fctzen. Der Dateischutz von MemberPress funktioniert auf Webserver-Ebene und bietet somit absoluten Schutz f\u00fcr jede Datei. Selbst wenn es beispielsweise einer Person ohne Zugriff auf eine Datei gelingen sollte, einen direkten Link zu ihr zu erhalten, w\u00fcrde MemberPress sie aufhalten und sie auffordern, sich zu registrieren oder einzuloggen (falls sie bereits registriert ist), bevor sie die Datei herunterladen kann.<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-danger\"> <strong>Anmerkung:<\/strong> Diese Form des Dateischutzes setzt voraus, dass Ihr Server .htaccess-Dateien verwendet und den Zugriff darauf erlaubt. Einige Server, insbesondere Ngnix-Server, tun dies nicht. Wenn diese Schritte auf Ihrer Website nicht funktionieren, m\u00fcssen Sie m\u00f6glicherweise unsere <a href=\"https:\/\/memberpress.com\/de\/docs\/mp-downloads-add-on\/\">Downloads Zusatzmodul<\/a> um Dateien zu sch\u00fctzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"file-types\">Welche Arten von Dateien kann MemberPress sch\u00fctzen?<\/h2>\n\n\n\n<p>MemberPress kann jede Datei sch\u00fctzen, die f\u00fcr das ordnungsgem\u00e4\u00dfe Funktionieren Ihrer Website nicht erforderlich ist.<\/p>\n\n\n\n<p>Daher kann MemberPress <em><strong>nur\u00a0<\/strong><\/em>die folgenden Dateitypen sch\u00fctzen:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">zip','gz','tar','rar','doc','docx','xls','xlsx','xlsm','pdf','mp4','m4v','mp3','ts','key','m3u8'<\/pre>\n\n\n\n<p>Wenn Sie einen Dateityp sch\u00fctzen m\u00f6chten, der oben nicht aufgef\u00fchrt ist, empfehlen wir Ihnen, die Dateien zu komprimieren und stattdessen eine einzelne .zip-Datei zu sch\u00fctzen.<\/p>\n\n\n\n<p>Dar\u00fcber hinaus k\u00f6nnen Sie benutzerdefinierten Code zur Datei functions.php Ihres Themes hinzuf\u00fcgen, falls Sie eine solche haben, oder zu einem Plugin, das<br><a href=\"https:\/\/wordpress.org\/plugins\/insert-headers-and-footers\/\">WPCode<\/a> Plugin (Details finden Sie in diesem Artikel: <a href=\"https:\/\/memberpress.com\/de\/docs\/how-to-add-custom-code-snippets-in-wpcode\/\">Hinzuf\u00fcgen von benutzerdefinierten Codefragmenten in WPCode<\/a>). Hier ist ein Beispiel f\u00fcr diesen Code:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">function add_types_protectable($ypes, $rules) {\n  $types[] = 'csv';\n  return $ypes;\n}\nadd_filter('mepr_rewrite_rules_protect_types', 'add_types_protectable', 11, 2);<\/pre>\n\n\n\n<p>Nachdem Sie diesen benutzerdefinierten Code hinzugef\u00fcgt haben, m\u00fcssen Sie Ihre WordPress-Permalinks aktualisieren, indem Sie zu Ihrem WordPress-Dashboard &gt; Einstellungen &gt; Permalinks &gt; gehen und einfach auf die Schaltfl\u00e4che \u2018\u00c4nderungen speichern' unten auf dieser Seite klicken.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\"><strong>Anmerkung: <\/strong>Wir raten davon ab, PHP, HTML, Bilder, Javascript, CSS, Schriftarten oder andere h\u00e4ufig genutzte Dateien zu sch\u00fctzen, da dies die Leistung beeintr\u00e4chtigen w\u00fcrde.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Zur\u00fcck zum Anfang<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"custom-uri-rules\"><a href=\"#custom-uri-rules\" title=\"\">MemberPress Benutzerdefinierte URI-Regeln erkl\u00e4rt<\/a><\/h2>\n\n\n\n<p>Benutzerdefinierte URI-Regeln schlie\u00dfen die L\u00fccken, in denen die Standardregeln nicht ausreichen, und gew\u00e4hrleisten einen umfassenden Schutz der Inhalte Ihrer gesamten Website.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"3xjlrceyYmkJPRTWaZsnXp0FCD6NLbwVvqoI1Gi4AMdU5tOgK7B9\"><div class=\"responsive-video\"><iframe title=\"Wann man benutzerdefinierte URI-Regeln in MemberPress verwendet (und wie man sie erstellt)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/wDoQl7CWR8A?feature=oembed&enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/span>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Allgemeine Anwendungsf\u00e4lle<\/h3>\n\n\n\n<p><strong><a href=\"https:\/\/memberpress.com\/de\/docs\/rules-overview\/#custom-uri-rules\" target=\"_blank\" rel=\"noopener\" title=\"\">Benutzerdefinierte URI-Regeln<\/a><\/strong> sch\u00fctzen Inhalte, die von den Standard-MemberPress-Regeln nicht erreicht werden k\u00f6nnen. Im Gegensatz zu regul\u00e4ren Regeln, die \u00fcber die Inhaltsverarbeitung von WordPress funktionieren, sch\u00fctzen benutzerdefinierte URI-Regeln URLs direkt auf der Serverebene.<\/p>\n\n\n\n<p><strong>1. Spezielle WordPress-Seiten<\/strong><\/p>\n\n\n\n<p>Standardseitenregeln wirken sich nicht auf spezielle Seiten wie die Startseite, die Beitragsseite, Kategoriearchive oder Archivseiten aus. Verwenden Sie benutzerdefinierte URI-Regeln, um diese Bereiche zu sch\u00fctzen, indem Sie auf ihre spezifischen URLs abzielen.<\/p>\n\n\n\n<p><strong>2. Page Builder Inhalt<\/strong><\/p>\n\n\n\n<p>MemberPress-Standardregeln sch\u00fctzen nur den Inhalt, der \u00fcber die WordPress-Inhaltsfunktion hinzugef\u00fcgt wurde (die <strong><code>the_content()<\/code><\/strong> Funktion). Viele Seitenersteller und Themes stellen ihre Inhalte au\u00dferhalb dieser Funktion dar. <\/p>\n\n\n\n<p>Dementsprechend bleibt der auf diese Weise wiedergegebene Inhalt ungesch\u00fctzt, wenn die Standard-MemberPress-Regeln angewendet werden. Stattdessen k\u00f6nnen Sie benutzerdefinierte URI-Regeln verwenden, um die gesamte Seite oder den gesamten Beitrag zu sch\u00fctzen.<\/p>\n\n\n\n<p><strong>3. Verzeichnisschutz<\/strong><\/p>\n\n\n\n<p>Sie k\u00f6nnen auch mehrere Dateien effizient sch\u00fctzen, indem Sie ganze Verzeichnisse mit einer einzigen Regel unter Verwendung von Platzhaltern anvisieren (z. B., <code>\/downloads\/*<\/code>).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"example\"><a href=\"#example\" title=\"\">Sch\u00fctzen einer einzelnen Datei<\/a><\/h2>\n\n\n\n<p>Wenn Sie nur eine Datei zu sch\u00fctzen haben, gehen Sie folgenderma\u00dfen vor:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Laden Sie die Datei mit dem WordPress Media Uploader hoch.<\/li>\n\n\n\n<li>Erstellen Sie eine benutzerdefinierte URI-Regel, um die Datei zu sch\u00fctzen.<\/li>\n<\/ol>\n\n\n\n<p>Angenommen, die von Ihnen hochgeladene Datei hat diese URL:<br><a href=\"http:\/\/example.com\/wp-content\/uploads\/2015\/10\/report.pdf\">http:\/\/example.com\/wp-content\/uploads\/2015\/10\/report.pdf<\/a><\/p>\n\n\n\n<p>Die Regel, die Sie f\u00fcr diese Datei erstellen w\u00fcrden, w\u00e4re ein benutzerdefinierter URI-Typ, der nur auf den Pfad zeigt (Teil nach<br><a href=\"http:\/\/example.com\">http:\/\/example.com<\/a>) in die Datei. In das Textfeld f\u00fcr diese Regel w\u00fcrden Sie also Folgendes eingeben:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">\/wp-content\/uploads\/2014\/12\/bericht.pdf<\/pre>\n\n\n\n<p>Obwohl dies bei einer kleinen Anzahl von Dateien ein relativ einfacher Prozess ist, kann er bei einer gr\u00f6\u00dferen Anzahl von Dateien zeitaufw\u00e4ndig werden. Sehen wir uns also an, wie Sie eine Regel zum Schutz mehrerer Dateien erstellen k\u00f6nnen.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Zur\u00fcck zum Anfang<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"mulitple\"><a href=\"#mulitple\" title=\"\">Mehrere Dateien<\/a><\/h2>\n\n\n\n<p>Nehmen wir an, Sie haben 10 Dateien und m\u00f6chten, dass die gleiche Mitgliedschaftsstufe Zugang zu allen Dateien hat.<\/p>\n\n\n\n<p>Die Idee dahinter ist, dass Sie entweder jede Datei in einem speziellen Ordner mit FTP ablegen (empfohlen) oder sicherstellen, dass jede Datei, die Sie \u00fcber den Media Uploader hochladen, ein gemeinsames Pr\u00e4fix hat (nicht empfohlen, au\u00dfer wenn FTP keine Option ist).<\/p>\n\n\n\n<p>Obwohl wir nicht empfehlen, mehrere Dateien, die mit dem WordPress Media Uploader hochgeladen werden, zu sch\u00fctzen, verstehen wir, dass Sie das manchmal wollen\/brauchen k\u00f6nnen. Wenn Sie diese Dateien also \u00fcber den Media Uploader hochladen, haben sie die folgenden URLs:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">http:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_report.pdf\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_report.doc\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_report.docx\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_analysis.pdf\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_analysis.doc\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_analysis.docx\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_groupings.pdf\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_groupings.doc\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_groupings.docx\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_archive.zip<\/pre>\n\n\n\n<p>Jetzt m\u00fcssen Sie nur noch eine Regel vom Typ Benutzerdefinierter URI mit diesem Pfad erstellen:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">\/wp-content\/uploads\/2015\/10\/bronze_<\/pre>\n\n\n\n<p>Dadurch werden alle Dateien im Ordner \u201c\/wp-content\/uploads\/2015\/10\/\u201d, deren Name mit \u201ebronze_\u201c beginnt, gesch\u00fctzt.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Zur\u00fcck zum Anfang<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ftp\">Mehrere Dateien mit FTP<\/h2>\n\n\n\n<p>FTP\/SFTP ist eine robuste Methode zur \u00dcbertragung von Dateien von Ihrem lokalen Computer zu Ihrer Website. Die meisten Webhoster bieten kostenlose FTP-Dienste an, damit Sie von Ihrem eigenen Computer aus auf die Dateien Ihrer Website zugreifen k\u00f6nnen. Die Verf\u00fcgbarkeit von FTP kann von Webhoster zu Webhoster variieren und unterschiedliche Anforderungen stellen. <\/p>\n\n\n\n<p>Normalerweise ben\u00f6tigen Sie einen FTP-Client wie <a href=\"https:\/\/filezilla-project.org\/\" title=\"Filezilla\">FileZilla<\/a> oder <a href=\"http:\/\/cyberduck.io\/\" title=\"Cyberduck\">Cyberduck<\/a> um eine Verbindung zu Ihrem Server \u00fcber FTP\/SFTP herzustellen. Auf diese Weise haben Sie Zugriff auf das Dateisystem Ihres Webservers, um Ordner zu erstellen und Dateien hochzuladen, \u00e4hnlich wie Sie Dateien zwischen Ordnern auf Ihrem lokalen Computer kopieren w\u00fcrden.<\/p>\n\n\n\n<p>In diesem Beispiel erstellen wir per FTP einen Ordner mit dem Namen protected und importieren unsere Dateien dorthin, so dass wir nun folgende URLs haben:<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-danger\"><strong>Anmerkung:<\/strong>\u00a0Benutzerdefinierte URI-Regeln funktionieren nicht f\u00fcr Dateien, wenn Ihre Website unter<strong> Nginx-Server<\/strong>. Wenn Sie den Ordner unter wp-content\/uploads erstellen, k\u00f6nnen die URI-Regeln f\u00fcr Sie funktionieren. Wir empfehlen die Verwendung der <a href=\"https:\/\/memberpress.com\/de\/docs\/mp-downloads-add-on\/\">MemberPress Downloads Zusatzmodul<\/a> um Dateien auf Ngnix-Servern zu sch\u00fctzen.\u00a0<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">http:\/\/example.com\/protected\/report.pdf\nhttp:\/\/example.com\/protected\/report.doc\nhttp:\/\/example.com\/protected\/report.docx\nhttp:\/\/example.com\/protected\/analysis.pdf\nhttp:\/\/example.com\/protected\/analysis.doc\nhttp:\/\/example.com\/protected\/analysis.docx\nhttp:\/\/example.com\/protected\/groupings.pdf\nhttp:\/\/example.com\/protected\/groupings.doc\nhttp:\/\/example.com\/protected\/groupings.docx\nhttp:\/\/example.com\/protected\/archive.zip<\/pre>\n\n\n\n<p>Dieses Szenario kann der Verwendung des WordPress Media Uploaders \u00fcberlegen sein, wenn Sie planen, Ihrem Ordner sp\u00e4ter Dateien hinzuzuf\u00fcgen, da der Media Uploader von WordPress Dateien, die zu unterschiedlichen Zeiten hochgeladen werden, manchmal in unterschiedlichen Ordnern ablegt.<\/p>\n\n\n\n<p>In diesem Beispiel m\u00fcssen Sie also nur eine Regel vom Typ Benutzerdefinierter URI mit diesem Pfad erstellen (der in das Textfeld f\u00fcr die Regel eingegeben wird):<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">\/gesch\u00fctzt\/<\/pre>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-danger\">\n\t<strong>Anmerkung:<\/strong> Wenn dies nicht funktioniert und Sie einen Apache-Server verwenden. Vergewissern Sie sich, dass die MemberPress-Rewrite-Regeln nicht deaktiviert wurden, indem Sie zu <strong>MemberPress-&gt;Einstellungen-&gt;Allgemein<\/strong> und die Deaktivierung des Feldes <strong>\u201cRewrite-Regeln deaktivieren\u201d<\/strong> und speichern Sie dann die \u00c4nderungen.<\/p>\n\n\n\n<p>Betrachten wir nun einige fortgeschrittenere Abgleiche mit regul\u00e4ren Ausdr\u00fccken.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Zur\u00fcck zum Anfang<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"expressions\">Regul\u00e4re Ausdr\u00fccke<\/h2>\n\n\n\n<p><a title=\"Regul\u00e4re Ausdr\u00fccke\" href=\"https:\/\/memberpress.com\/de\/how-to-become-a-regular-expression-power-user\/\" target=\"_blank\" rel=\"noopener\">Regul\u00e4re Ausdr\u00fccke<\/a> ist eine einzigartige und anschauliche Suchsyntax, die in allen modernen Programmiersprachen zur Auswahl und Verarbeitung von Text verwendet wird. Sie erm\u00f6glicht es Ihnen, sehr spezifische Dateigruppen mit Leichtigkeit zu sch\u00fctzen.<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\">Hinweis: Regul\u00e4re Ausdr\u00fccke eignen sich am besten f\u00fcr F\u00e4lle, in denen Sie mehrere URLs auf einmal sch\u00fctzen m\u00fcssen.<\/p>\n\n\n\n<p>Die Idee dahinter ist, dass es Ihnen erm\u00f6glicht, Muster in einer gegebenen URL abzugleichen und die URL zu sch\u00fctzen, wenn sie einer Ihrer benutzerdefinierten URI-Typ-Regeln mit aktiviertem regul\u00e4rem Ausdruck entspricht.<\/p>\n\n\n\n<p>Wenn Sie beispielsweise im obigen FTP-Beispiel einigen Benutzern nur Zugriff auf PDF-Dateien und anderen Benutzern Zugriff auf Ihre PDF-, DOC-, DOCX- und ZIP-Dateien gew\u00e4hren m\u00f6chten, k\u00f6nnen Sie zwei verschiedene Regeln f\u00fcr regul\u00e4re Ausdr\u00fccke erstellen \u2013 die erste f\u00fcr eine Mitgliedschaftsstufe und die zweite f\u00fcr eine andere.<\/p>\n\n\n\n<p>Die erste Regel f\u00fcr Ihre erste Mitgliedschaftsstufe h\u00e4tte einen Pfad, der etwa so aussieht:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">^\/protected\/.*\\.pdf\n<\/pre>\n\n\n\n<p>Die zweite Regel f\u00fcr Ihre andere Mitgliedschaftsstufe h\u00e4tte einen Pfad, der etwa so aussieht:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">^\/gesch\u00fctzt\/.*\\.(pdf|doc|docx|zip)\n<\/pre>\n\n\n\n<p>Zugegeben, regul\u00e4re Ausdr\u00fccke k\u00f6nnen schwierig zu beherrschen sein, aber sie k\u00f6nnen in MemberPress-Regeln vom Typ \"Benutzerdefinierter URI\" einige leistungsstarke Abgleich- und Dateischutzfunktionen bieten. Wir haben festgestellt, dass<br><a href=\"http:\/\/www.regular-expressions.info\/\">http:\/\/www.regular-expressions.info\/<\/a> ist eine gute Quelle f\u00fcr alle, die sich mit dieser leistungsstarken Technologie vertraut machen m\u00f6chten. Wenn Sie komplexere Anforderungen haben, ist unser Support-Team sehr versiert darin, regul\u00e4re Ausdr\u00fccke f\u00fcr alles zu finden, was Sie sch\u00fctzen m\u00f6chten. Sie k\u00f6nnen also gerne eine Anfrage einreichen. <a class=\"heroickb_exit_link\" href=\"?hkb-redirect&nonce=f4b61b2770&check=6jvcs&redirect=https%3A%2F%2Fmemberpress.com%2Fsupport%2F&otype=unknown&oid=0&source=block-content\" title=\"Premium Support Anfrage\">Support-Anfrage<\/a> wenn Sie Hilfe zu dieser Funktion ben\u00f6tigen.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Zur\u00fcck zum Anfang<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Technische Anforderungen<\/h2>\n\n\n\n<p>Da diese Funktion den Ihrer Website zugrundeliegenden Webserver nutzt, um Dateien zu sch\u00fctzen, gibt es einige technische Voraussetzungen, die erf\u00fcllt sein m\u00fcssen, damit diese Funktion richtig funktioniert. Wir haben MemberPress so geschrieben, dass es mit den g\u00e4ngigsten Serverkonfigurationen funktioniert, aber wenn die Dinge bei Ihnen nicht vollst\u00e4ndig funktionieren, sollten Sie einige Dinge \u00fcberpr\u00fcfen:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Ihre Website muss von Apache oder einem Apache-kompatiblen Webserver wie Litespeed bereitgestellt werden. Die von MemberPress installierten Umschreibungsregeln sind spezifisch f\u00fcr Apache. Wenn Sie sich nicht sicher sind, welchen Webserver Sie verwenden, handelt es sich wahrscheinlich um Apache. Um sicherzugehen, k\u00f6nnen Sie sich an Ihren Webhost wenden. MemberPress unterst\u00fctzt keinen Dateischutz auf anderen Webservern wie Nginx, IIS oder anderen nicht auf Apache basierenden Servern. Wenn Ihr Webserver jedoch Nginx als Proxy (vor Apache) verwendet, k\u00f6nnen Sie m\u00f6glicherweise den Nginx-Proxy-Bypass-Code verwenden, der im Abschnitt \u201eNginx\u201c unter <a href=\"http:\/\/docs.memberpress.com\/article\/179-understanding-rewrite-rules\" target=\"_blank\" rel=\"noopener\">diese Seite<\/a>.<\/li>\n\n\n\n<li>Ihre WordPress-Installation sollte \u00fcber ausreichende Berechtigungen verf\u00fcgen, um \u00c4nderungen an Ihrer .htaccess-Datei vorzunehmen. Wenn Ihre .htaccess-Datei von WordPress nicht beschrieben werden kann, k\u00f6nnen Sie sie manuell bearbeiten, indem Sie unsere <a title=\"Anweisungen umschreiben\" href=\"http:\/\/docs.memberpress.com\/article\/179-understanding-rewrite-rules\" target=\"_blank\" rel=\"noopener\">erweiterte Rewrite-Anweisungen<\/a>.<\/li>\n\n\n\n<li>Ihre WordPress-Installation muss die M\u00f6glichkeit haben, Dateien in den Ordner \/wp-content\/uploads zu schreiben. Dies ist auch eine Voraussetzung daf\u00fcr, dass der WordPress Media Uploader Dateien hochladen kann. Wenn das funktioniert, sollte auch dies funktionieren.<\/li>\n\n\n\n<li>Cloudflare und andere CDNs und Zwischenspeicher haben das Potenzial, den Dateischutz zu behindern. Dies liegt daran, dass sie entweder die Datei zwischenspeichern, so dass sie nicht gesch\u00fctzt werden kann, oder sie st\u00f6ren unsere Schutz-Cookies und verursachen unendliche Umleitungsschleifen. <\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\"><strong>Anmerkung: <\/strong>Aus diesem Grund sollten Sie bei Problemen mit dem Dateischutz alle CDN- und Caching-Funktionen deaktivieren, um zu pr\u00fcfen, ob dies eine m\u00f6gliche Ursache ist. <em>vor <\/em>Kontaktaufnahme mit unserem Support.<\/p>\n\n\n\n<ol start=\"5\" class=\"wp-block-list\">\n<li>Die MemberPress-Umschreibungsregeln m\u00fcssen aktiviert sein. Gehen Sie zu MemberPress-&gt;Einstellungen-&gt;Allgemein, deaktivieren Sie das Kontrollk\u00e4stchen \u201cUmschreibungsregeln deaktivieren\u201d und speichern Sie die \u00c4nderungen.<\/li>\n<\/ol>\n\n\n\n<p>Wir haben auch schon Benutzer mit benutzerdefinierten Rewrite-Regeln gesehen, die mit den MemberPress-Rewrite-Regeln interferierten. Wenn diese Funktion also nicht zu funktionieren scheint und Sie das Gef\u00fchl haben, dass Sie alle diese Schritte durchlaufen haben, wenden Sie sich bitte an unsere <a class=\"heroickb_exit_link\" href=\"?hkb-redirect&nonce=f4b61b2770&check=6jvcs&redirect=https%3A%2F%2Fmemberpress.com%2Fsupport%2F&otype=unknown&oid=0&source=block-content\" title=\"Premium Support Anfrage\">Betreuungsteam<\/a> und wir werden Ihnen helfen.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Zur\u00fcck zum Anfang<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"add_types\">Zus\u00e4tzliche Dateitypen sch\u00fctzen<\/h2>\n\n\n\n<p>MemberPress kann zus\u00e4tzliche Dateitypen sch\u00fctzen. Beachten Sie, dass jede HTTP-Anfrage eines sch\u00fctzbaren Dateityps eine zweite Anfrage an die Website ausl\u00f6st, um zu pr\u00fcfen, ob die Datei gesch\u00fctzt ist oder nicht. Aus diesem Grund empfehlen wir nicht, Dateien wie Bilder (jpg, png, gif usw.), Skripte (css, js) oder Schriftartendateien zu sch\u00fctzen, da dies eine erhebliche Belastung f\u00fcr Ihren Server bedeuten k\u00f6nnte. <\/p>\n\n\n\n<p>Verwenden Sie den folgenden benutzerdefinierten Code in einem Plugin wie dem <a href=\"https:\/\/wordpress.org\/plugins\/insert-headers-and-footers\/\">WPCode<\/a> um zus\u00e4tzliche Dateitypen hinzuzuf\u00fcgen. Bitte lesen Sie diesen Artikel f\u00fcr weitere Details: <a href=\"https:\/\/memberpress.com\/de\/docs\/how-to-add-custom-code-snippets-in-wpcode\/\">Hinzuf\u00fcgen von benutzerdefinierten Codefragmenten in WPCode<\/a>.<\/p>\n\n\n\n<p>Der folgende Code f\u00fcgt die Dateitypen \u201chtml\u201d und \u201chtm\u201d zur Liste der gesch\u00fctzten Dateien hinzu. Nachdem Sie diesen Code hinzugef\u00fcgt haben, m\u00fcssen Sie auch Ihre WordPress-Permalink-Einstellungen aktualisieren, um WordPress zu zwingen, die .htaccess-Datei f\u00fcr Ihre Website zu aktualisieren.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">function add_types_protectable($ypes, $rules) {\n  $types[] = 'htm';\n  $types[] = 'html';\n  return $ypes;\n}\nadd_filter('mepr_rewrite_rules_protect_types', 'add_types_protectable', 11, 2);<\/pre>","protected":false},"excerpt":{"rendered":"<p>Covered in this article: What types of files can MemberPress Protect Protecting a Single File Protecting Multiple Files Protecting Multiple Files with FTP Using Regular Expressions Technical Requirements Protect Additional File-Types MemberPress has some powerful features to help you protect static files. MemberPress\u2019s file protection works at the web-server level which provides absolute protection of [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1322],"ht-kb-tag":[],"class_list":{"0":"post-61386","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-protecting-content","7":"entry"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress&#039;s\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/de\/docs\/protecting-files\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Protecting Files | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress&#039;s\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/de\/docs\/protecting-files\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T12:23:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-27T13:01:03+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Protecting Files | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress&#039;s\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/docs\\\/protecting-files\\\/#article\",\"name\":\"Protecting Files | MemberPress\",\"headline\":\"Protecting Files\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/#articleImage\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"datePublished\":\"2024-02-13T07:23:29-05:00\",\"dateModified\":\"2026-01-27T08:01:03-05:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/docs\\\/protecting-files\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/docs\\\/protecting-files\\\/#webpage\"},\"articleSection\":\"Protecting Content\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/docs\\\/protecting-files\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/doc-categories\\\/general\\\/#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/memberpress.com\\\/de\\\/doc-categories\\\/general\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/doc-categories\\\/protecting-content\\\/#listItem\",\"name\":\"Protecting Content\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/doc-categories\\\/protecting-content\\\/#listItem\",\"position\":3,\"name\":\"Protecting Content\",\"item\":\"https:\\\/\\\/memberpress.com\\\/de\\\/doc-categories\\\/protecting-content\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/docs\\\/protecting-files\\\/#listItem\",\"name\":\"Protecting Files\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/docs\\\/protecting-files\\\/#listItem\",\"position\":4,\"name\":\"Protecting Files\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/doc-categories\\\/protecting-content\\\/#listItem\",\"name\":\"Protecting Content\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/docs\\\/protecting-files\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/docs\\\/protecting-files\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/de\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/docs\\\/protecting-files\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/de\\\/docs\\\/protecting-files\\\/\",\"name\":\"Protecting Files | MemberPress\",\"description\":\"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress's\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/docs\\\/protecting-files\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-02-13T07:23:29-05:00\",\"dateModified\":\"2026-01-27T08:01:03-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/de\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Protecting Files | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Schutz von Dateien | MemberPress","description":"Hinweis: Obwohl diese Anweisungen immer noch g\u00fcltig sind, haben wir inzwischen das MemberPress Downloads Add-on ver\u00f6ffentlicht, das das Hochladen und den Schutz Ihrer Dateien wesentlich vereinfacht. Klicken Sie hier, um mehr dar\u00fcber zu erfahren. H\u00e4ufige Anwendungsf\u00e4lle Benutzerdefinierte URI-Regeln sch\u00fctzen Inhalte, die von Standard-MemberPress-Regeln nicht erreicht werden k\u00f6nnen. Im Gegensatz zu regul\u00e4ren Regeln, die \u00fcber WordPress's","canonical_url":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/#article","name":"Protecting Files | MemberPress","headline":"Protecting Files","author":{"@id":"https:\/\/memberpress.com\/de\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/de\/#articleImage","width":1650,"height":1275,"caption":"memberpress logo icon"},"datePublished":"2024-02-13T07:23:29-05:00","dateModified":"2026-01-27T08:01:03-05:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/#webpage"},"articleSection":"Protecting Content"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/doc-categories\/general\/#listItem","position":2,"name":"General","item":"https:\/\/memberpress.com\/de\/doc-categories\/general\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/doc-categories\/protecting-content\/#listItem","name":"Protecting Content"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/doc-categories\/protecting-content\/#listItem","position":3,"name":"Protecting Content","item":"https:\/\/memberpress.com\/de\/doc-categories\/protecting-content\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/#listItem","name":"Protecting Files"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/#listItem","position":4,"name":"Protecting Files","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/de\/doc-categories\/protecting-content\/#listItem","name":"Protecting Content"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/de\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/de\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/de\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/#webpage","url":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/","name":"Protecting Files | MemberPress","description":"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress's","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/memberpress.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/de\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/de\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-02-13T07:23:29-05:00","dateModified":"2026-01-27T08:01:03-05:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/de\/#website","url":"https:\/\/memberpress.com\/de\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"de-DE","publisher":{"@id":"https:\/\/memberpress.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"MemberPress","og:type":"article","og:title":"Protecting Files | MemberPress","og:description":"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress's","og:url":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-02-13T12:23:29+00:00","article:modified_time":"2026-01-27T13:01:03+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Protecting Files | MemberPress","twitter:description":"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress's","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"61386","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-01-27 13:02:24","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-02-13 12:23:29","updated":"2026-03-03 14:53:49"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/de\/doc-categories\/general\/\" title=\"General\">General<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/de\/doc-categories\/protecting-content\/\" title=\"Protecting Content\">Protecting Content<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tProtecting Files\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/de"},{"label":"General","link":"https:\/\/memberpress.com\/de\/doc-categories\/general\/"},{"label":"Protecting Content","link":"https:\/\/memberpress.com\/de\/doc-categories\/protecting-content\/"},{"label":"Protecting Files","link":"https:\/\/memberpress.com\/de\/docs\/protecting-files\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/ht-kb\/61386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/comments?post=61386"}],"version-history":[{"count":4,"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/ht-kb\/61386\/revisions"}],"predecessor-version":[{"id":78770,"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/ht-kb\/61386\/revisions\/78770"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/media?parent=61386"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/ht-kb-category?post=61386"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/de\/wp-json\/wp\/v2\/ht-kb-tag?post=61386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}