{"id":79605,"date":"2026-03-04T13:03:28","date_gmt":"2026-03-04T18:03:28","guid":{"rendered":"https:\/\/memberpress.com\/?post_type=cpmu-add-ons&#038;p=79605"},"modified":"2026-03-11T13:56:00","modified_gmt":"2026-03-11T17:56:00","slug":"ai-course-generator","status":"publish","type":"cpmu-add-ons","link":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/","title":{"rendered":"Generador de cursos de AI"},"content":{"rendered":"<h4 style=\"text-align: left;\"><em><strong>Chatea y consigue un curso completo en cuesti\u00f3n de minutos.<\/strong><\/em><\/h4>\n<p>Elabore sus planes de estudios, lecciones y cuestionarios a partir de una conversaci\u00f3n natural dentro de MemberPress Courses.<\/p>\n<h4><strong>Planes de estudios completos, creados mientras chatea<\/strong><\/h4>\n<p>Describa el tema, el p\u00fablico y los objetivos en el panel de chat de la izquierda y, a continuaci\u00f3n, vea c\u00f3mo va tomando forma su plan de estudios en el panel de previsualizaci\u00f3n en directo de la derecha:<\/p>\n<ul>\n<li><strong>Estructuras de curso completas generadas:<\/strong>\u00a0Secciones, lecciones, estimaciones de tiempo, objetivos de aprendizaje: todo creado a partir de su descripci\u00f3n y listo para personalizar.<\/li>\n<li><strong>Edici\u00f3n mediante arrastrar y soltar:<\/strong>\u00a0Reordena las secciones y las lecciones en el panel de vista previa, cambia el nombre de lo que no encaje o pide m\u00e1s informaci\u00f3n a la IA a trav\u00e9s del chat.<\/li>\n<li><strong>Contenido que realmente encaja:<\/strong>\u00a0La IA se basa en el tema de tu curso y en los t\u00edtulos de las lecciones, por lo que obtienes material adaptado a lo que est\u00e1s ense\u00f1ando: nada de contenido gen\u00e9rico de relleno.<\/li>\n<\/ul>\n<h4><strong>Contenido de las lecciones y cuestionarios a la carta<\/strong><\/h4>\n<p>Una vez que tengas el esquema preparado, es el momento de completar los detalles:<\/p>\n<ul>\n<li><strong>Asistente de lecciones AI:<\/strong>\u00a0Crea contenidos completos para tus clases o perfecciona los borradores que ya tengas. El resultado se ajusta a tu plan de estudios, ya que la IA trabaja a partir del contexto que t\u00fa mismo has creado.<\/li>\n<li><strong>AI Quiz Builder:<\/strong>\u00a0Cree preguntas de cuestionario extra\u00eddas directamente de sus lecciones. Opci\u00f3n m\u00faltiple, selecci\u00f3n m\u00faltiple, verdadero\/falso, respuesta corta: mezcla y combina para crear evaluaciones que eval\u00faen lo que realmente has ense\u00f1ado.<\/li>\n<\/ul>\n<h4><strong>Cr\u00e9ditos y compatibilidad<\/strong><\/h4>\n<p>Las funciones de IA funcionan con un sencillo sistema de cr\u00e9ditos, y los cursos generados funcionan con todo lo que ya utilizas:<\/p>\n<ul>\n<li><strong>Paga por lo que usas:<\/strong>\u00a0Compre los cr\u00e9ditos AI que necesite y consulte su saldo en cualquier momento en <strong>Panel &gt; MemberPress &gt; Cr\u00e9ditos AI.<\/strong><\/li>\n<li><strong>Se conecta directamente al MemberPress:<\/strong>\u00a0Normas de acceso, protecci\u00f3n de contenidos, plantillas de ReadyLaunch: todo funciona exactamente como cabr\u00eda esperar. Sin necesidad de configuraci\u00f3n adicional.<\/li>\n<\/ul>\n<p><span class=\"apQ78M46NGzgQcnDz8Aulo3CktWsTweKmiod2Ujal5wrrFNx3M0L9dSbPbOnRqkXGhvxmsSYByJDUL\"><\/p>\n<div class=\"responsive-video\"><iframe title=\"C\u00f3mo crear cursos, lecciones y cuestionarios con el AI Course Creator para cursos MemberPress\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/EbR1M_G7yOc?feature=oembed&enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p><\/span><\/p>\n<p>Si llevas tiempo d\u00e1ndole vueltas a una idea para un curso, pero te da el \u00abs\u00edndrome de la p\u00e1gina en blanco\u00bb, o simplemente te falta tiempo para llevarla a cabo: \u00a1esta es tu oportunidad!<\/p>\n<p>Ponga en marcha ese curso hoy mismo con el Generador de cursos AI como copiloto.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Chat your way to a complete course in minutes! Build out your curricula, lessons and quizzes all from a natural conversation right inside MemberPress Courses. Complete Curricula, Built While You Chat Describe your topic, audience, and goals in the chat panel on the left, then watch your curriculum take shape in the live preview panel [\u2026]<\/p>\n","protected":false},"featured_media":79608,"parent":0,"template":"","class_list":["post-79605","cpmu-add-ons","type-cpmu-add-ons","status-publish","has-post-thumbnail","cpmu-add-on-category-growth","cpmu-add-on-category-launch","cpmu-add-on-category-scale","cpmu-integration-tag-extensions","cpmu-integration-tag-lms","entry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Chat your way to a complete course in minutes with an AI-powered course builder that integrates directly into MemberPress Courses.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"AI Course Generator | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"Chat your way to a complete course in minutes with an AI-powered course builder that integrates directly into MemberPress Courses.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2026\/03\/MemberPress-AI-Course-Generator-Logo.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2026\/03\/MemberPress-AI-Course-Generator-Logo.svg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1724\" \/>\n\t\t<meta property=\"og:image:height\" content=\"970\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-03-04T18:03:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-11T17:56:00+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"AI Course Generator | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Chat your way to a complete course in minutes with an AI-powered course builder that integrates directly into MemberPress Courses.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2026\/03\/MemberPress-AI-Course-Generator-Logo.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/ai-course-generator\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/#listItem\",\"name\":\"Add-Ons\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/#listItem\",\"position\":2,\"name\":\"Add-Ons\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/add-on-category\\\/launch\\\/#listItem\",\"name\":\"Launch\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/add-on-category\\\/launch\\\/#listItem\",\"position\":3,\"name\":\"Launch\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/add-on-category\\\/launch\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/ai-course-generator\\\/#listItem\",\"name\":\"AI Course Generator\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/#listItem\",\"name\":\"Add-Ons\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/ai-course-generator\\\/#listItem\",\"position\":4,\"name\":\"AI Course Generator\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/add-on-category\\\/launch\\\/#listItem\",\"name\":\"Launch\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/ai-course-generator\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/ai-course-generator\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/ai-course-generator\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/ai-course-generator\\\/\",\"name\":\"AI Course Generator | MemberPress\",\"description\":\"Chat your way to a complete course in minutes with an AI-powered course builder that integrates directly into MemberPress Courses.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/ai-course-generator\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/MemberPress-AI-Course-Generator-Logo.svg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/ai-course-generator\\\/#mainImage\",\"width\":1724,\"height\":970,\"caption\":\"MemberPress AI Course Generator Logo\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/addons\\\/ai-course-generator\\\/#mainImage\"},\"datePublished\":\"2026-03-04T13:03:28-05:00\",\"dateModified\":\"2026-03-11T13:56:00-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>AI Course Generator | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Generador de cursos AI | MemberPress","description":"Cree un curso completo por chat en cuesti\u00f3n de minutos con un creador de cursos basado en IA que se integra directamente en MemberPress Courses.","canonical_url":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/addons\/#listItem","name":"Add-Ons"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/addons\/#listItem","position":2,"name":"Add-Ons","item":"https:\/\/memberpress.com\/es\/addons\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/add-on-category\/launch\/#listItem","name":"Launch"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/add-on-category\/launch\/#listItem","position":3,"name":"Launch","item":"https:\/\/memberpress.com\/es\/add-on-category\/launch\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/#listItem","name":"AI Course Generator"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/addons\/#listItem","name":"Add-Ons"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/#listItem","position":4,"name":"AI Course Generator","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/add-on-category\/launch\/#listItem","name":"Launch"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/es\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/#webpage","url":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/","name":"AI Course Generator | MemberPress","description":"Chat your way to a complete course in minutes with an AI-powered course builder that integrates directly into MemberPress Courses.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/memberpress.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2026\/03\/MemberPress-AI-Course-Generator-Logo.svg","@id":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/#mainImage","width":1724,"height":970,"caption":"MemberPress AI Course Generator Logo"},"primaryImageOfPage":{"@id":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/#mainImage"},"datePublished":"2026-03-04T13:03:28-05:00","dateModified":"2026-03-11T13:56:00-04:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/es\/#website","url":"https:\/\/memberpress.com\/es\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"es-ES","publisher":{"@id":"https:\/\/memberpress.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"MemberPress","og:type":"article","og:title":"AI Course Generator | MemberPress","og:description":"Chat your way to a complete course in minutes with an AI-powered course builder that integrates directly into MemberPress Courses.","og:url":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2026\/03\/MemberPress-AI-Course-Generator-Logo.svg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2026\/03\/MemberPress-AI-Course-Generator-Logo.svg","og:image:width":1724,"og:image:height":970,"article:published_time":"2026-03-04T18:03:28+00:00","article:modified_time":"2026-03-11T17:56:00+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"AI Course Generator | MemberPress","twitter:description":"Chat your way to a complete course in minutes with an AI-powered course builder that integrates directly into MemberPress Courses.","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2026\/03\/MemberPress-AI-Course-Generator-Logo.svg"},"aioseo_meta_data":{"post_id":"79605","title":null,"description":"Cree un curso completo por chat en cuesti\u00f3n de minutos con un creador de cursos basado en IA que se integra directamente en MemberPress Courses.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-03-11 18:47:57","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-03-04 15:55:24","updated":"2026-04-02 13:49:18","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/addons\/\" title=\"Add-Ons\">Add-Ons<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/add-on-category\/launch\/\" title=\"Launch\">Launch<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tAI Course Generator\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/es"},{"label":"Add-Ons","link":"https:\/\/memberpress.com\/es\/addons\/"},{"label":"Launch","link":"https:\/\/memberpress.com\/es\/add-on-category\/launch\/"},{"label":"AI Course Generator","link":"https:\/\/memberpress.com\/es\/addons\/ai-course-generator\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/cpmu-add-ons\/79605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/cpmu-add-ons"}],"about":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/types\/cpmu-add-ons"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/media\/79608"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/media?parent=79605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}