{"id":61520,"date":"2024-02-13T07:38:00","date_gmt":"2024-02-13T12:38:00","guid":{"rendered":"https:\/\/memberpress.com\/docs\/reminders-case-examples\/"},"modified":"2024-02-13T17:19:05","modified_gmt":"2024-02-13T22:19:05","slug":"reminders-case-examples","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/","title":{"rendered":"Recordatorios Ejemplos de casos"},"content":{"rendered":"<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\">\n\t Antes de leer esta p\u00e1gina, no olvide consultar nuestro <a href=\"http:\/\/docs.memberpress.com\/article\/147-creating-reminders\" target=\"_blank\" rel=\"noopener\">Crear un recordatorio<\/a> para una buena visi\u00f3n general de los ajustes explicados en esta p\u00e1gina.<\/p><p>\n\t A continuaci\u00f3n encontrar\u00e1 un par de ejemplos de c\u00f3mo realizar tareas espec\u00edficas con MemberPress Recordatorios. Haga clic en el ejemplo para acceder directamente a \u00e9l:<\/p><ul class=\"callout\">\n\t<li><a href=\"#drip\">Recordatorios de goteo de contenidos<\/a><\/li>\t<li><a href=\"#abandoned\">Recuperar a un usuario tras un pago abandonado<\/a><\/li>\t<li><a href=\"#failed\">Evitar los impagos causados por tarjetas de cr\u00e9dito caducadas<\/a><\/li>\t<li><a href=\"#instructions\">Instrucciones adicionales para despu\u00e9s de la firma<\/a><\/li>\t<li><a href=\"#upsell\">Ventas estrat\u00e9gicas<\/a><\/li>\t<li><a href=\"#win\">Correos electr\u00f3nicos de recuperaci\u00f3n de usuarios<\/a><\/li><\/ul><h2 id=\"drip\">Recordatorios de goteo de contenidos<\/h2><p>\n\t En <a href=\"http:\/\/docs.memberpress.com\/article\/186-dripping-and-expiring-content\" target=\"_blank\" rel=\"noopener\">contenido de goteo con MemberPress<\/a>, es posible que desee notificar a sus usuarios cu\u00e1ndo estar\u00e1 disponible su contenido por goteo. Esto se puede hacer f\u00e1cilmente creando un recordatorio espec\u00edfico para cada secuencia de goteo que tenga. Esto se puede hacer utilizando el recordatorio \u2018despu\u00e9s de que los miembros se registren'.<\/p><p>\n\t As\u00ed, por ejemplo, si tienes contenido que se gotea cada mes, lo configurar\u00edas as\u00ed:<\/p><ol>\n\t<li>Crea un recordatorio \u2018despu\u00e9s de que el miembro se registre' para cada mes.\n\t<ol>\n\t\t<li>Esto se hace configurando el primero con un activador de \u20181 mes', el segundo con \u20182 meses', etc.<\/li>\t<\/ol><\/li>\t<li>(Opcional) Desactive el correo electr\u00f3nico del administrador para cada recordatorio para evitar recibir estas notificaciones.\u00a0<\/li>\t<li>Utiliza la funci\u00f3n \u2018Enviar solo a miembros espec\u00edficos' en la secci\u00f3n \u2018Correos electr\u00f3nicos' de cada recordatorio para configurarlos de modo que solo se env\u00eden a los suscriptores del miembro correcto.<\/li>\t<li>Edite cada correo electr\u00f3nico recordatorio enviado al usuario con cualquier informaci\u00f3n relevante, enlaces directos, etc.\u00a0<\/li>\t<li>Aseg\u00farate de guardar cada correo electr\u00f3nico de recordatorio utilizando el bot\u00f3n \u2018Actualizar' en la p\u00e1gina de edici\u00f3n de cada recordatorio.<\/li><\/ol><p>\n\t \u00a1Eso es!<\/p><p>\n\t<em>Nota importante: estos recordatorios <strong>no<\/strong> se detiene si la suscripci\u00f3n de un usuario se cancela o se pone en pausa, as\u00ed que aseg\u00farese de no a\u00f1adir contenido activo s\u00f3lo para usuarios a sus correos electr\u00f3nicos. En su lugar, utilice enlaces a contenidos protegidos, de modo que si se produce un lapso en la suscripci\u00f3n del usuario, \u00e9ste no tendr\u00e1 acceso a ning\u00fan contenido protegido.\u00a0<\/em><\/p><p>\n\t<a class=\"callout dashed\" href=\"#top\">Volver arriba<\/a><\/p><h2 id=\"abandoned\">Recuperar a un usuario tras un pago abandonado<\/h2><p>\u00a0Si configura MemberPress para que utilice un proceso de registro en dos pasos, es posible que los usuarios abandonen el proceso de compra despu\u00e9s de enviar su informaci\u00f3n de usuario pero antes de introducir sus datos de pago. A menudo, enviar un correo electr\u00f3nico a un usuario despu\u00e9s de un evento de este tipo puede animarle a volver, pedir m\u00e1s informaci\u00f3n, o hacer otras cosas para ayudar a convertirlos en suscriptores de pago. Tenga en cuenta que aunque configure MemberPress para utilizar un <a href=\"\/es\/Enable a Single Page Checkout (and invoice)\/\" target=\"_blank\" rel=\"noopener\">pago en una sola p\u00e1gina<\/a>puede configurar el mismo recordatorio si utiliza PayPal (est\u00e1ndar o plataforma de comercio) o Stripe Checkout como pasarela de pago.<\/p><p>\n\t \u00a1La soluci\u00f3n es configurar un recordatorio \u2018despu\u00e9s del abandono tras el registro'!<\/p><p>\n\t Cuando configure este recordatorio, tenga en cuenta estas pr\u00e1cticas recomendadas:<\/p><ul>\n\t<li>No configure este recordatorio para menos de 12 horas despu\u00e9s del evento desencadenante. Esto se debe a que el usuario puede volver en breve por su cuenta, etc.<\/li>\t<li>Edite el correo electr\u00f3nico para ofrecer una experiencia m\u00e1s personal a sus usuarios.\u00a0<\/li>\t<li>Aunque el correo electr\u00f3nico predeterminado proporciona algunas instrucciones b\u00e1sicas sobre este proceso, este correo electr\u00f3nico recordatorio est\u00e1 dise\u00f1ado para enviarse mientras el usuario todav\u00eda est\u00e1 conectado (lo que ocurre autom\u00e1ticamente despu\u00e9s del primer paso de registro). Por lo tanto, es posible que desee especificar que el usuario debe iniciar sesi\u00f3n en primer lugar. <em>y luego<\/em> hacer clic en el enlace que colocamos en el correo electr\u00f3nico en caso de que se hayan desconectado autom\u00e1ticamente. A\u00f1adir un enlace directo a tu p\u00e1gina de inicio de sesi\u00f3n puede facilitar mucho esta tarea al usuario.<\/li>\t<li>Considera a\u00f1adir alg\u00fan incentivo para que vuelvan y completen el registro, como <a href=\"http:\/\/docs.memberpress.com\/category\/131-creating-and-managing-coupons\" target=\"_blank\" rel=\"noopener\">un cup\u00f3n<\/a>etc.\u00a0<\/li><\/ul><p>\n\t<a class=\"callout dashed\" href=\"#top\">Volver arriba<\/a><\/p><h2 id=\"failed\">Evitar los impagos causados por tarjetas de cr\u00e9dito caducadas<\/h2><p>\n\t Una raz\u00f3n com\u00fan por la que un usuario deja de renovar su suscripci\u00f3n es un pago fallido debido a una tarjeta de cr\u00e9dito caducada. Para evitar perder pagos y, potencialmente, a tus clientes, considera utilizar nuestro recordatorio \u2018antes de que caduque la tarjeta de cr\u00e9dito'. Solo aseg\u00farate de seguir algunas de estas pr\u00e1cticas recomendadas al crear este recordatorio:<\/p><ul>\n\t<li>Establezca el desencadenante (por ejemplo, 2 semanas, 3 meses, etc.) de forma adecuada a las condiciones de sus precios de afiliaci\u00f3n, por lo general con el mismo marco de tiempo que sus facturaciones es lo mejor.\u00a0\n\t<ul>\n\t\t<li>Por ejemplo, si tu suscripci\u00f3n es mensual, utiliza un recordatorio de este tipo que se active con una configuraci\u00f3n de \u20181 mes'.<\/li>\t<\/ul><\/li>\t<li>No utilices la funci\u00f3n \u2018Enviar solo para membres\u00edas espec\u00edficas' en la secci\u00f3n \u2018Correos electr\u00f3nicos', ya que es probable que desees enviar este recordatorio a todas tus membres\u00edas.\u00a0<\/li>\t<li>Considera la posibilidad de hacer m\u00e1s hincapi\u00e9 en la calidad del contenido de tu sitio web: si no actualizan la informaci\u00f3n de su tarjeta de cr\u00e9dito, perder\u00e1n el acceso a todo el contenido al que est\u00e1n suscritos.<\/li><\/ul><p>\n\t<em>Nota importante: este recordatorio no funciona si el usuario se ha registrado a trav\u00e9s de una cuenta PayPal. Esto se debe a que han pagado con la cuenta, pero MemberPress no tiene forma de ver esa cuenta y conocer la fecha de caducidad de las tarjetas de cr\u00e9dito introducidas.\u00a0<\/em><\/p><p>\n\t<a class=\"callout dashed\" href=\"#top\">Volver arriba<\/a><\/p><h2 id=\"instructions\">Instrucciones adicionales para despu\u00e9s de la firma<\/h2><p>\n\t Es posible que tenga que proporcionar instrucciones adicionales que el usuario necesite conocer despu\u00e9s de registrarse, pero que no desee incluir en la bienvenida al usuario. <a href=\"http:\/\/docs.memberpress.com\/article\/43-emails\" target=\"_blank\" rel=\"noopener\">correo electr\u00f3nico<\/a>. Tales como:\u00a0<\/p><ul>\n\t<li>Su sitio tiene instrucciones de configuraci\u00f3n adicionales para que el usuario pueda empezar.\u00a0<\/li>\t<li>Est\u00e1 ofreciendo contenidos o actividades fuera del sitio que el usuario necesita conocer.<\/li>\t<li>Desea enviar al usuario m\u00e1s informaci\u00f3n sobre a qu\u00e9 tiene acceso con su suscripci\u00f3n.\u00a0<\/li><\/ul><p>\n\t Por cualquiera de estas razones y muchas m\u00e1s, puedes enviar a cada usuario un correo electr\u00f3nico con esa informaci\u00f3n simplemente utilizando un \u00fanico recordatorio \u2018despu\u00e9s de que el miembro se registre' para cada membres\u00eda relevante en tu sitio.\u00a0<\/p><p>\n\t Solo aseg\u00farate de editar el recordatorio como corresponda y de seleccionar la membres\u00eda correcta en la funci\u00f3n \u2018Enviar solo para membres\u00edas espec\u00edficas' en la secci\u00f3n \u2018Correos electr\u00f3nicos'.<\/p><p>\n\t<a class=\"callout dashed\" href=\"#top\">Volver arriba<\/a><\/p><h2 id=\"upsell\">Ventas estrat\u00e9gicas<\/h2><p>\n\t MemberPress no tiene actualmente ninguna funci\u00f3n espec\u00edfica de upsell, pero puede utilizar f\u00e1cilmente nuestros Recordatorios para hacer algo similar.\u00a0<\/p><p>\n\t Para ello, recomendamos utilizar nuestros recordatorios \u2018antes de que caduque la suscripci\u00f3n' o \u2018despu\u00e9s de que caduque la suscripci\u00f3n'. A continuaci\u00f3n, se indican algunas pr\u00e1cticas recomendadas que se deben tener en cuenta al utilizar estos correos electr\u00f3nicos de recordatorio para realizar ventas adicionales.<\/p><ul>\n\t<li>Tenga en cuenta el tipo de recordatorio que utiliza. Dependiendo de tu configuraci\u00f3n, puede ser mejor enviar el correo electr\u00f3nico antes de que caduque la suscripci\u00f3n del usuario, y para otros, puede ser despu\u00e9s de que ya haya caducado.\u00a0<\/li>\t<li>Establezca el activador en el momento que considere m\u00e1s adecuado para obtener las mejores conversiones. Por lo general, este momento es lo suficientemente temprano como para que el usuario tenga tiempo de considerarlo, pero <em>no <\/em>Demasiado tarde, as\u00ed que al usuario ya no le importa.\u00a0<\/li>\t<li>Considere la posibilidad de a\u00f1adir un <a href=\"http:\/\/docs.memberpress.com\/category\/131-creating-and-managing-coupons\" target=\"_blank\" rel=\"noopener\">c\u00f3digo del cup\u00f3n<\/a> al correo electr\u00f3nico de recordatorio al usuario para ofrecerle un descuento especial.\u00a0\n\t<ul>\n\t\t<li>Si lo haces, aseg\u00farate de revisar los art\u00edculos sobre \u2018c\u00f3digos promocionales' en el enlace anterior para asegurarte de que comprendes correctamente c\u00f3mo funcionan nuestros cupones.\u00a0<\/li>\t\t<li>Recuerda que tendr\u00e1s que actualizar este c\u00f3digo de cup\u00f3n peri\u00f3dicamente si decides establecer una fecha de caducidad o un l\u00edmite de uso para el cup\u00f3n (lo cual es recomendable, ya que los c\u00f3digos de cup\u00f3n se pueden compartir f\u00e1cilmente).\u00a0<\/li>\t<\/ul><\/li>\t<li>(Opcional) Desactive el correo electr\u00f3nico del administrador para cada recordatorio de este tipo para evitar recibir estas notificaciones.\u00a0<\/li>\t<li>A\u00f1ada alg\u00fan tipo de contacto (suyo u otro) o p\u00e1gina con la que el usuario pueda ponerse en contacto o utilizar para obtener m\u00e1s informaci\u00f3n sobre por qu\u00e9 deber\u00eda suscribirse a su afiliaci\u00f3n upsell.\u00a0<\/li><\/ul><p>\n\t<a class=\"callout dashed\" href=\"#top\">Volver arriba<\/a><\/p><h2 id=\"win\">Correos electr\u00f3nicos de recuperaci\u00f3n de usuarios<\/h2><p>\n\t Los correos electr\u00f3nicos de recuperaci\u00f3n son correos electr\u00f3nicos que se utilizan para \u2018recuperar' o animar a un usuario a volver a su sitio web, y que suelen enviarse una vez que se alcanza alg\u00fan tipo de fecha de caducidad ( \n\t<a href=\"https:\/\/www.klaviyo.com\/blog\/winback-email-campaign-examples\" target=\"_blank\" rel=\"noopener\">m\u00e1s informaci\u00f3n<\/a>).<\/p><p>\n\t En MemberPress, esto se puede hacer f\u00e1cilmente con nuestro correo electr\u00f3nico recordatorio \u2018Despu\u00e9s de que expire la suscripci\u00f3n'. Solo tienes que tener en cuenta algunas de las siguientes pr\u00e1cticas recomendadas al crear un correo electr\u00f3nico recordatorio \u2018Recuperar':<\/p><ul>\n\t<li>Aseg\u00farese de editar el correo electr\u00f3nico con todas y cada una de sus mejores razones de por qu\u00e9 el usuario deber\u00eda volver a su afiliaci\u00f3n.\u00a0<\/li>\t<li>Establezca el desencadenante adecuadamente. No querr\u00e1s parecer demasiado necesitado envi\u00e1ndolo demasiado pronto despu\u00e9s de que caduque su suscripci\u00f3n, pero tampoco demasiado tarde para que parezca una ocurrencia tard\u00eda.<\/li>\t<li>Considere la posibilidad de a\u00f1adir alg\u00fan tipo de <a href=\"http:\/\/docs.memberpress.com\/category\/131-creating-and-managing-coupons\">c\u00f3digo del cup\u00f3n<\/a> u oferta especial para incitar al usuario a volver.\u00a0\n\t<ul>\n\t\t<li>Si utiliza un cup\u00f3n, aseg\u00farese de revisar los art\u00edculos sobre \u2018c\u00f3digos de cup\u00f3n' en el enlace anterior para asegurarse de que comprende correctamente c\u00f3mo funcionan nuestros cupones.\u00a0<\/li>\t\t<li>Recuerde que tendr\u00e1 que actualizar este c\u00f3digo de cup\u00f3n peri\u00f3dicamente si decide establecer un l\u00edmite de caducidad o de uso del cup\u00f3n (lo cual es aconsejable, ya que los c\u00f3digos de cup\u00f3n pueden compartirse f\u00e1cilmente).\u00a0<\/li>\t<\/ul><\/li>\t<li>(Opcional) Habilite el correo electr\u00f3nico del administrador para cada recordatorio de este tipo si le interesa controlar el porcentaje de \u00e9xito de este recordatorio. O deshabilita el correo electr\u00f3nico del administrador si prefieres que no te molesten. \u00a0<\/li><\/ul><p>\n\t<a class=\"callout dashed\" href=\"#top\">Volver arriba<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content Reminders Getting a User Back After Abandoned Checkout Avoiding Failed Payments Caused by Expired Credit Cards Providing Additional After-Signup Instructions Strategic Upsells User Win-Back Emails [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1321],"ht-kb-tag":[],"class_list":{"0":"post-61520","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-reminders","7":"entry"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Reminders Case Examples | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T12:38:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-13T22:19:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Reminders Case Examples | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/reminders-case-examples\\\/#article\",\"name\":\"Reminders Case Examples | MemberPress\",\"headline\":\"Reminders Case Examples\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#articleImage\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"datePublished\":\"2024-02-13T07:38:00-05:00\",\"dateModified\":\"2024-02-13T17:19:05-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/reminders-case-examples\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/reminders-case-examples\\\/#webpage\"},\"articleSection\":\"Reminders\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/reminders-case-examples\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/general\\\/#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/general\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/emails-and-notifications\\\/#listItem\",\"name\":\"Emails and Notifications\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/emails-and-notifications\\\/#listItem\",\"position\":3,\"name\":\"Emails and Notifications\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/emails-and-notifications\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/reminders\\\/#listItem\",\"name\":\"Reminders\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/reminders\\\/#listItem\",\"position\":4,\"name\":\"Reminders\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/reminders\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/reminders-case-examples\\\/#listItem\",\"name\":\"Reminders Case Examples\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/emails-and-notifications\\\/#listItem\",\"name\":\"Emails and Notifications\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/reminders-case-examples\\\/#listItem\",\"position\":5,\"name\":\"Reminders Case Examples\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/reminders\\\/#listItem\",\"name\":\"Reminders\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/reminders-case-examples\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/reminders-case-examples\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/reminders-case-examples\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/reminders-case-examples\\\/\",\"name\":\"Reminders Case Examples | MemberPress\",\"description\":\"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/reminders-case-examples\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-02-13T07:38:00-05:00\",\"dateModified\":\"2024-02-13T17:19:05-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Reminders Case Examples | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Recordatorios Ejemplos de casos | MemberPress","description":"Antes de leer esta p\u00e1gina, aseg\u00farese de revisar nuestra p\u00e1gina Crear un Recordatorio para obtener una buena visi\u00f3n general de los ajustes que se explican en esta p\u00e1gina. A continuaci\u00f3n encontrar\u00e1 un par de ejemplos de c\u00f3mo realizar tareas espec\u00edficas con MemberPress Recordatorios. Haga clic en el ejemplo para acceder directamente a \u00e9l: Goteo de Contenido","canonical_url":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/#article","name":"Reminders Case Examples | MemberPress","headline":"Reminders Case Examples","author":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/es\/#articleImage","width":1650,"height":1275,"caption":"memberpress logo icon"},"datePublished":"2024-02-13T07:38:00-05:00","dateModified":"2024-02-13T17:19:05-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/#webpage"},"articleSection":"Reminders"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/general\/#listItem","position":2,"name":"General","item":"https:\/\/memberpress.com\/es\/doc-categories\/general\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/emails-and-notifications\/#listItem","name":"Emails and Notifications"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/emails-and-notifications\/#listItem","position":3,"name":"Emails and Notifications","item":"https:\/\/memberpress.com\/es\/doc-categories\/emails-and-notifications\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/reminders\/#listItem","name":"Reminders"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/reminders\/#listItem","position":4,"name":"Reminders","item":"https:\/\/memberpress.com\/es\/doc-categories\/reminders\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/#listItem","name":"Reminders Case Examples"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/emails-and-notifications\/#listItem","name":"Emails and Notifications"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/#listItem","position":5,"name":"Reminders Case Examples","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/reminders\/#listItem","name":"Reminders"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/es\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/#webpage","url":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/","name":"Reminders Case Examples | MemberPress","description":"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/memberpress.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-02-13T07:38:00-05:00","dateModified":"2024-02-13T17:19:05-05:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/es\/#website","url":"https:\/\/memberpress.com\/es\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"es-ES","publisher":{"@id":"https:\/\/memberpress.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"MemberPress","og:type":"article","og:title":"Reminders Case Examples | MemberPress","og:description":"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content","og:url":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-02-13T12:38:00+00:00","article:modified_time":"2024-02-13T22:19:05+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Reminders Case Examples | MemberPress","twitter:description":"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"61520","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-09 21:38:12","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2024-02-13 12:38:01","updated":"2026-03-03 14:53:49"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/general\/\" title=\"General\">General<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/emails-and-notifications\/\" title=\"Emails and Notifications\">Emails and Notifications<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/reminders\/\" title=\"Reminders\">Reminders<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tReminders Case Examples\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/es"},{"label":"General","link":"https:\/\/memberpress.com\/es\/doc-categories\/general\/"},{"label":"Emails and Notifications","link":"https:\/\/memberpress.com\/es\/doc-categories\/emails-and-notifications\/"},{"label":"Reminders","link":"https:\/\/memberpress.com\/es\/doc-categories\/reminders\/"},{"label":"Reminders Case Examples","link":"https:\/\/memberpress.com\/es\/docs\/reminders-case-examples\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/61520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/comments?post=61520"}],"version-history":[{"count":0,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/61520\/revisions"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/media?parent=61520"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb-category?post=61520"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb-tag?post=61520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}