{"id":61787,"date":"2024-02-13T08:14:06","date_gmt":"2024-02-13T13:14:06","guid":{"rendered":"https:\/\/memberpress.com\/docs\/available-gutenberg-blocks\/"},"modified":"2025-06-02T09:20:26","modified_gmt":"2025-06-02T13:20:26","slug":"available-gutenberg-blocks","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/","title":{"rendered":"Bloques Gutenberg disponibles"},"content":{"rendered":"<p>MemberPress viene con m\u00faltiples bloques Gutenberg. Puede utilizar estos bloques en cualquier \u00e1rea de su sitio de WordPress que se pueda editar con el editor de bloques predeterminado (Gutenberg).<\/p>\n\n\n\n<p>Este documento le dar\u00e1 una visi\u00f3n general de los Bloques MemberPress y detalles sobre c\u00f3mo puede utilizarse cada uno de ellos.<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\"><strong>Nota<\/strong>: Para utilizar la integraci\u00f3n de Gutenberg con MemberPress, debe utilizar WordPress 5.2.1 o superior y MemberPress 1.4.7 o superior.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tutorial en v\u00eddeo<\/h2>\n\n\n\n<p><iframe title=\"Reproductor de v\u00eddeo YouTube\" src=\"https:\/\/www.youtube.com\/embed\/teqGKfqZpxc?enablejsapi=1\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MemberPress Visi\u00f3n general de los bloques Gutenberg<\/h2>\n\n\n\n<p>Los bloques MemberPress se pueden utilizar para a\u00f1adir formularios MemberPress cl\u00e1sicos y otra informaci\u00f3n relacionada con los miembros a tus p\u00e1ginas y entradas personalizadas. Tambi\u00e9n puedes a\u00f1adir bloques MemberPress a tus \u00e1reas de widgets.<\/p>\n\n\n\n<p>Actualmente, los bloques MemberPress disponibles son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#login-block\"><strong>Formulario de acceso<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#account-block\"><strong>Formulario de cuenta<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#account-links\"><strong>Enlaces a cuentas<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#account-info\"><strong>Informaci\u00f3n de la cuenta<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#registration-block\"><strong>Formulario de inscripci\u00f3n<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#subscriptions-block\"><strong>Suscripciones<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#protected-block\"><strong>Contenido protegido<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p><span style=\"margin: 0px; padding: 0px;\">Adem\u00e1s, puede utilizar los bloques ReadyLaunch\u2122 si\u00a0<a href=\"https:\/\/memberpress.com\/es\/docs\/designing-pages-with-readylaunch\/\" target=\"_blank\"><strong>activar las plantillas ReadyLaunch\u2122.<\/strong><\/a>.<\/span> En este caso, el <a href=\"https:\/\/memberpress.com\/es\/docs\/customizing-the-login-page-with-readylaunch\/\" target=\"_blank\" rel=\"noopener\"><strong>Inicio de sesi\u00f3n<\/strong><\/a>, <a href=\"https:\/\/memberpress.com\/es\/docs\/customizing-the-account-page-with-readylaunch\/\" target=\"_blank\" rel=\"noopener\"><strong>Cuenta<\/strong><\/a>, <a href=\"https:\/\/memberpress.com\/es\/docs\/customizing-the-registration-page-with-readylaunch\/\" target=\"_blank\" rel=\"noopener\"><strong>Inscripci\u00f3n<\/strong><\/a>y <a href=\"https:\/\/memberpress.com\/es\/docs\/customizing-the-pricing-page-with-ready-launch\/\" target=\"_blank\" rel=\"noopener\"><strong>Tabla de precios<\/strong><\/a> (Grupos) estar\u00e1n disponibles en su lista.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"login-block\">Bloque de formulario de inicio de sesi\u00f3n<\/h3>\n\n\n\n<p>El cl\u00e1sico formulario de inicio de sesi\u00f3n de MemberPress puede a\u00f1adirse f\u00e1cilmente en cualquier lugar con el bloque Formulario de inicio de sesi\u00f3n.\u00a0<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8c2e4eb9\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8c2e4eb9\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1917\" height=\"969\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28.png\" alt=\"\" class=\"wp-image-73122\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28.png 1917w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-300x152.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-1024x518.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-1536x776.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-336x170.png 336w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-840x425.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-1216x615.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-1832x926.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-700x354.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-1080x546.png 1080w\" sizes=\"(max-width: 1917px) 100vw, 1917px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>El bloque viene con el \"<b>URL de redirecci\u00f3n de inicio de sesi\u00f3n<\/b>\". Si activa esta opci\u00f3n, los usuarios no autorizados ser\u00e1n redirigidos a la URL de redirecci\u00f3n que haya configurado en los ajustes de MemberPress. Por otro lado, si se desactiva, este bloqueo permitir\u00e1 a los usuarios iniciar sesi\u00f3n y permanecer en la misma p\u00e1gina (donde se ha a\u00f1adido el bloqueo) despu\u00e9s de iniciar sesi\u00f3n.<\/p>\n\n\n\n<p>Si el usuario ya ha iniciado sesi\u00f3n, el bloque mostrar\u00e1 el \u201c<i>Ya has iniciado sesi\u00f3n<\/i>\u201d con un enlace para cerrar sesi\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"account-block\">Bloque de formulario de cuenta<\/h3>\n\n\n\n<p>Puede a\u00f1adir el cl\u00e1sico formulario de cuenta MemberPress a cualquier lugar de su sitio web utilizando el bloque Cuenta MemberPress. De esta forma, por ejemplo, puede dise\u00f1ar una p\u00e1gina de cuenta personalizada como desee y a\u00f1adir el bloque Cuenta para mostrar el formulario de cuenta en esa p\u00e1gina.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8c2e552e\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8c2e552e\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1903\" height=\"954\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29.png\" alt=\"\" class=\"wp-image-73123\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29.png 1903w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-300x150.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-1024x513.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-768x385.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-1536x770.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-339x170.png 339w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-840x421.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-1216x610.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-1832x918.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-700x351.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-156x78.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-1080x541.png 1080w\" sizes=\"(max-width: 1903px) 100vw, 1903px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"account-links\">Bloque de enlaces a cuentas<\/h3>\n\n\n\n<p>El bloque Enlaces a cuentas mostrar\u00e1 dos enlaces en la p\u00e1gina, entrada o \u00e1rea de widget donde se a\u00f1ada el bloque:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>el <b>Cuenta <\/b>enlace a la p\u00e1gina de la cuenta MemberPress del usuario (establecida en <i>Panel de control &gt; MemberPress &gt; Configuraci\u00f3n &gt; Pesta\u00f1a P\u00e1ginas<\/i>);<\/li>\n\n\n\n<li>el <b>Cierre de sesi\u00f3n <\/b>enlace.<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8c2e5bf8\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8c2e5bf8\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1903\" height=\"555\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30.png\" alt=\"\" class=\"wp-image-73124\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30.png 1903w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-300x87.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-1024x299.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-768x224.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-50x15.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-1536x448.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-583x170.png 583w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-840x245.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-1216x355.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-1832x534.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-700x204.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-156x45.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-1080x315.png 1080w\" sizes=\"(max-width: 1903px) 100vw, 1903px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"account-info\">Bloque de informaci\u00f3n de la cuenta<\/h3>\n\n\n\n<p>Este bloque te permite mostrar cualquiera de los datos de la cuenta del usuario que se encuentran en la pesta\u00f1a Cuenta &gt; Inicio.<\/p>\n\n\n\n<p>En la configuraci\u00f3n del bloque, ver\u00e1 el icono \"<b>Babosa de campo<\/b>\" donde puede elegir el slug de cualquier campo de la Cuenta.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8c2e6196\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8c2e6196\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1917\" height=\"969\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31.png\" alt=\"\" class=\"wp-image-73125\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31.png 1917w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-300x152.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-1024x518.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-1536x776.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-336x170.png 336w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-840x425.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-1216x615.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-1832x926.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-700x354.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-1080x546.png 1080w\" sizes=\"(max-width: 1917px) 100vw, 1917px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Al seleccionar el slug del campo, est\u00e1 eligiendo qu\u00e9 datos del usuario se mostrar\u00e1n en el front-end.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8c2e6622\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8c2e6622\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1902\" height=\"508\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33.png\" alt=\"\" class=\"wp-image-73127\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33.png 1902w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-300x80.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-1024x273.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-768x205.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-50x13.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-1536x410.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-636x170.png 636w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-840x224.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-1216x325.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-1832x489.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-700x187.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-156x42.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-1080x288.png 1080w\" sizes=\"(max-width: 1902px) 100vw, 1902px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"registration-block\">Bloque del formulario de inscripci\u00f3n<\/h3>\n\n\n\n<p>Con este bloque, puede a\u00f1adir f\u00e1cilmente un formulario de inscripci\u00f3n cl\u00e1sico MemberPress en cualquier lugar de su sitio web.<\/p>\n\n\n\n<p>Una vez que a\u00f1adas el bloque, por ejemplo, a una publicaci\u00f3n, ver\u00e1s el \u201c<b>Seleccione un formulario de inscripci\u00f3n para mostrar<\/b>\u201d en el men\u00fa desplegable debajo de la configuraci\u00f3n del bloque.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8c2e6b50\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8c2e6b50\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1917\" height=\"968\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32.png\" alt=\"\" class=\"wp-image-73126\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32.png 1917w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-300x151.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-1024x517.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-1536x776.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-337x170.png 337w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-840x424.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-1216x614.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-1832x925.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-700x353.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-1080x545.png 1080w\" sizes=\"(max-width: 1917px) 100vw, 1917px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Aqu\u00ed puede seleccionar la afiliaci\u00f3n cuyo formulario de inscripci\u00f3n desea a\u00f1adir mediante este bloque.<\/p>\n\n\n\n<p>Similar al bloque Cuenta, permite crear p\u00e1ginas de registro personalizadas, promocionales o de aterrizaje con el formulario de registro incrustado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"subscriptions-block\">Bloque de suscripciones<\/h3>\n\n\n\n<p>Este bloque a\u00f1adir\u00e1 la lista de todas las afiliaciones a las que el usuario conectado est\u00e1 suscrito actualmente. El bloque incluye varias opciones de clasificaci\u00f3n y \u00e1reas de texto personalizables.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8c2e7142\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8c2e7142\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1902\" height=\"968\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34.png\" alt=\"\" class=\"wp-image-73128\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34.png 1902w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-300x153.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-1024x521.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-768x391.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-1536x782.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-334x170.png 334w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-840x428.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-1216x619.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-1832x932.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-700x356.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-1080x550.png 1080w\" sizes=\"(max-width: 1902px) 100vw, 1902px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Las opciones disponibles para este bloque son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><b>Ordenar por:<\/b> Las opciones de clasificaci\u00f3n disponibles son por \u201c<b>Fecha<\/b>\u201d (cuando se cre\u00f3 la membres\u00eda), o por \u201c<b>T\u00edtulo<\/b>\u201d (por orden alfab\u00e9tico);<\/li>\n\n\n\n<li><b>Orden de clasificaci\u00f3n<\/b>: Elija el <b>Descendente <\/b>o <b>Ascendente <\/b>orden;<\/li>\n\n\n\n<li><b>Mensaje de no conectado:<\/b> Este mensaje se mostrar\u00e1 para este bloque cuando el usuario desconectado visite esa entrada o p\u00e1gina.<\/li>\n\n\n\n<li><b>No hay suscripciones Mensaje:<\/b> Este mensaje se mostrar\u00e1 para este bloque si el usuario conectado no tiene ninguna suscripci\u00f3n activa.<\/li>\n\n\n\n<li><b>Utilizar URL de acceso a los miembros<\/b>: Al habilitar esta opci\u00f3n, las suscripciones de membres\u00eda enumeradas ser\u00e1n clicables. Estos nombres de membres\u00eda apuntar\u00e1n a \u201c<i>URL de acceso para miembros<\/i>\u201d que hayas establecido en tu configuraci\u00f3n de membres\u00eda (<i>Opciones de afiliaci\u00f3n &gt; pesta\u00f1a Avanzado<\/i>).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"protected-block\">Bloque de contenido protegido<\/h3>\n\n\n\n<p>El bloque de contenido protegido MemberPress se utiliza como bloque de grupo para contenido protegido. Puedes a\u00f1adir cualquier bloque de Gutenberg a los bloques de contenido protegido.<\/p>\n\n\n\n<p>Puede aplicar un <a href=\"https:\/\/memberpress.com\/es\/docs\/rules-overview\/\" target=\"_blank\" rel=\"noopener\"><strong>Regla MemberPress<\/strong><\/a> al bloque Contenido protegido para <strong><a href=\"https:\/\/memberpress.com\/es\/docs\/protect-gutenberg-blocks-with-memberpress\/#protected-content-block\" target=\"_blank\" rel=\"noopener\" title=\"\">proteger su contenido<\/a><\/strong>. En funci\u00f3n de la configuraci\u00f3n del bloque, puede <strong>Mostrar <\/strong>o <strong>ocultar <\/strong>el contenido protegido.<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\"><strong>Nota: <\/strong>Utilizaci\u00f3n del MemberPress <strong><a href=\"https:\/\/memberpress.com\/es\/docs\/protect-gutenberg-blocks-with-memberpress\/#partial-rules\" target=\"_blank\" rel=\"noopener\" title=\"\">Tipo de regla parcial<\/a><\/strong> con el Bloque de Contenido Protegido es <strong>recomendado<\/strong>.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8c2e81a1\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8c2e81a1\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1918\" height=\"968\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35.png\" alt=\"\" class=\"wp-image-73129\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35.png 1918w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-300x151.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-1024x517.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-1536x775.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-337x170.png 337w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-840x424.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-1216x614.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-1832x925.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-700x353.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-1080x545.png 1080w\" sizes=\"(max-width: 1918px) 100vw, 1918px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Adem\u00e1s, puede elegir qu\u00e9 acci\u00f3n <span style=\"margin: 0px; padding: 0px;\">que se tomar\u00e1 si un usuario no autorizado intenta acceder al contenido protegido. La opci\u00f3n predeterminada es \u201c<strong>S\u00f3lo ocultar<\/strong>, que significa<\/span> el contenido protegido no se mostrar\u00e1. Tambi\u00e9n puede optar por <strong>mostrar un mensaje personalizado<\/strong>el MemberPress <strong>formulario de acceso<\/strong>o <strong>ambos<\/strong>.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8c2e8662\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8c2e8662\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1917\" height=\"968\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36.png\" alt=\"\" class=\"wp-image-73130\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36.png 1917w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-300x151.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-1024x517.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-1536x776.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-337x170.png 337w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-840x424.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-1216x614.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-1832x925.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-700x353.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-1080x545.png 1080w\" sizes=\"(max-width: 1917px) 100vw, 1917px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">C\u00f3mo encontrar y a\u00f1adir bloques MemberPress<\/h2>\n\n\n\n<p>Los bloques MemberPress estar\u00e1n disponibles en cualquier entrada o \u00e1rea del sitio donde est\u00e9 activado el editor de bloques por defecto. Para encontrar y a\u00f1adir bloques MemberPress, sigue estos pasos:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Inicie el Editor de bloques en la entrada o \u00e1rea que desee editar.<\/li>\n\n\n\n<li>Haga clic en el bot\u00f3n <strong>Icono \"+\".<\/strong> para abrir el insertador de bloques.<\/li>\n\n\n\n<li>Busque o despl\u00e1cese por la lista de bloques para encontrar el que necesita.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8c2e8ccb\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8c2e8ccb\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1917\" height=\"968\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38.png\" alt=\"\" class=\"wp-image-73132\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38.png 1917w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-300x151.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-1024x517.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-1536x776.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-337x170.png 337w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-840x424.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-1216x614.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-1832x925.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-700x353.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-1080x545.png 1080w\" sizes=\"(max-width: 1917px) 100vw, 1917px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><p>Haz clic en el bloque para a\u00f1adirlo.<\/p><\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Video Tutorial MemberPress Gutenberg Blocks Overview [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1318],"ht-kb-tag":[1488],"class_list":{"0":"post-61787","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-look-and-feel","7":"ht_kb_tag-kadence","8":"entry","9":"has-post-thumbnail"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Available Gutenberg Blocks | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T13:14:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-06-02T13:20:26+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Available Gutenberg Blocks | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/#article\",\"name\":\"Available Gutenberg Blocks | MemberPress\",\"headline\":\"Available Gutenberg Blocks\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/image-28.png\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/#articleImage\",\"width\":1917,\"height\":969},\"datePublished\":\"2024-02-13T08:14:06-05:00\",\"dateModified\":\"2025-06-02T09:20:26-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/#webpage\"},\"articleSection\":\"Look and Feel, kadence\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/general\\\/#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/general\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/look-and-feel\\\/#listItem\",\"name\":\"Look and Feel\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/look-and-feel\\\/#listItem\",\"position\":3,\"name\":\"Look and Feel\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/look-and-feel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/#listItem\",\"name\":\"Available Gutenberg Blocks\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/#listItem\",\"position\":4,\"name\":\"Available Gutenberg Blocks\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/look-and-feel\\\/#listItem\",\"name\":\"Look and Feel\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/\",\"name\":\"Available Gutenberg Blocks | MemberPress\",\"description\":\"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/available-gutenberg-blocks\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-02-13T08:14:06-05:00\",\"dateModified\":\"2025-06-02T09:20:26-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Available Gutenberg Blocks | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Bloques Gutenberg disponibles | MemberPress","description":"MemberPress viene con m\u00faltiples bloques Gutenberg. Puede utilizar estos bloques en cualquier \u00e1rea de su sitio de WordPress que se pueda editar con el editor de bloques predeterminado (Gutenberg). Este documento le dar\u00e1 una visi\u00f3n general de los Bloques MemberPress y detalles sobre c\u00f3mo se puede utilizar cada uno de ellos. Nota: Para utilizar los","canonical_url":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/#article","name":"Available Gutenberg Blocks | MemberPress","headline":"Available Gutenberg Blocks","author":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28.png","@id":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/#articleImage","width":1917,"height":969},"datePublished":"2024-02-13T08:14:06-05:00","dateModified":"2025-06-02T09:20:26-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/#webpage"},"articleSection":"Look and Feel, kadence"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/general\/#listItem","position":2,"name":"General","item":"https:\/\/memberpress.com\/es\/doc-categories\/general\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/look-and-feel\/#listItem","name":"Look and Feel"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/look-and-feel\/#listItem","position":3,"name":"Look and Feel","item":"https:\/\/memberpress.com\/es\/doc-categories\/look-and-feel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/#listItem","name":"Available Gutenberg Blocks"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/#listItem","position":4,"name":"Available Gutenberg Blocks","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/look-and-feel\/#listItem","name":"Look and Feel"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/es\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/#webpage","url":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/","name":"Available Gutenberg Blocks | MemberPress","description":"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/memberpress.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-02-13T08:14:06-05:00","dateModified":"2025-06-02T09:20:26-04:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/es\/#website","url":"https:\/\/memberpress.com\/es\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"es-ES","publisher":{"@id":"https:\/\/memberpress.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"MemberPress","og:type":"article","og:title":"Available Gutenberg Blocks | MemberPress","og:description":"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the","og:url":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-02-13T13:14:06+00:00","article:modified_time":"2025-06-02T13:20:26+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Available Gutenberg Blocks | MemberPress","twitter:description":"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"61787","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-09 21:47:16","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-02-13 13:14:09","updated":"2026-03-03 14:53:48"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/general\/\" title=\"General\">General<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/look-and-feel\/\" title=\"Look and Feel\">Look and Feel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tAvailable Gutenberg Blocks\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/es"},{"label":"General","link":"https:\/\/memberpress.com\/es\/doc-categories\/general\/"},{"label":"Look and Feel","link":"https:\/\/memberpress.com\/es\/doc-categories\/look-and-feel\/"},{"label":"Available Gutenberg Blocks","link":"https:\/\/memberpress.com\/es\/docs\/available-gutenberg-blocks\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/61787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/comments?post=61787"}],"version-history":[{"count":3,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/61787\/revisions"}],"predecessor-version":[{"id":73335,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/61787\/revisions\/73335"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/media?parent=61787"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb-category?post=61787"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb-tag?post=61787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}