{"id":62746,"date":"2024-02-13T10:27:54","date_gmt":"2024-02-13T15:27:54","guid":{"rendered":"https:\/\/memberpress.com\/docs\/how-to-use-if-menu-with-memberpress\/"},"modified":"2025-10-23T16:00:38","modified_gmt":"2025-10-23T20:00:38","slug":"how-to-use-if-menu-with-memberpress","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/","title":{"rendered":"C\u00f3mo utilizar el men\u00fa If con MemberPress"},"content":{"rendered":"<p>Puede personalizar la visibilidad de los elementos del men\u00fa con la opci\u00f3n <a href=\"https:\/\/wordpress.org\/plugins\/if-menu\/\" target=\"_blank\" rel=\"noopener\"><strong>If Menu - Control de la visibilidad de los elementos del men\u00fa<\/strong><\/a> plugin. Puede configurar la visibilidad en funci\u00f3n de si sus usuarios han iniciado sesi\u00f3n o est\u00e1n suscritos activamente a una de sus afiliaciones. MemberPress incluye <strong>Integraci\u00f3n del men\u00fa If<\/strong>.<\/p>\n\n\n\n<p>Este documento explica c\u00f3mo <strong>utilizar el plugin If Menu con MemberPress<\/strong> a <strong>establecer la visibilidad de los elementos del men\u00fa<\/strong> en funci\u00f3n de las afiliaciones.<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\"><strong>Nota<\/strong>: Este complemento est\u00e1 disponible para MemberPress <strong>Plan de crecimiento y ampliaci\u00f3n<\/strong> miembros. Si est\u00e1 suscrito al plan Lanzamiento, puede pasar al plan Crecimiento y Escala. Para ello, haga clic en el bot\u00f3n\u00a0<strong>Plan de cambio<\/strong>\u00a0enlace en su\u00a0<strong><a href=\"https:\/\/memberpress.com\/account\/subscriptions\/\">p\u00e1gina de la cuenta<\/a><\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"KNjek7\"><div class=\"responsive-video\"><iframe title=\"C\u00f3mo controlar qu\u00e9 elementos del men\u00fa ven los usuarios en su sitio MemberPress\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/xqeFxYqjKQc?feature=oembed&enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/span>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Instrucciones de instalaci\u00f3n<\/h2>\n\n\n\n<p>Por favor, siga los siguientes pasos para instalar el plugin en su sitio:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Vaya a su panel de WordPress &gt; Plugins &gt; A\u00f1adir nuevo.<\/li>\n\n\n\n<li>Buscar \"<strong>If Menu - Control de la visibilidad de los elementos del men\u00fa<\/strong>\u201cEs el desarrollado por Layered.\u00a0<\/li>\n\n\n\n<li><strong>Instalar y activar <\/strong>el plugin.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Creaci\u00f3n de men\u00fas<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Ir a la <strong>Panel &gt; Apariencia &gt; Men\u00fas<\/strong> p\u00e1gina.\u00a0<\/li>\n\n\n\n<li>Cree su nuevo men\u00fa o seleccione el men\u00fa en el que desea que aparezca el elemento.\n<ul class=\"wp-block-list\">\n<li><em>Crear un nuevo men\u00fa<\/em>\u00a0\u2013 Si necesita crear un nuevo men\u00fa, en la secci\u00f3n\u00a0<strong>Estructura del men\u00fa<\/strong>\u00a0introduzca el nombre del men\u00fa y haga clic en el bot\u00f3n azul\u00a0<strong>Crear men\u00fa<\/strong>\u00a0para empezar.\u00a0<\/li>\n\n\n\n<li><em>Busca tu men\u00fa para editarlo\u00a0<\/em>\u2013 Para editar un men\u00fa existente, utilice el\u00a0<strong>Seleccione un men\u00fa<\/strong> <strong>editar<\/strong>\u00a0y haga clic en Seleccionar.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Dentro del\u00a0<strong>Men\u00fa Ajustes<\/strong>\u00a0para su men\u00fa seleccionado, seleccione las ubicaciones de su men\u00fa. La mayor\u00eda prefiere utilizar el <strong>Men\u00fa horizontal de escritorio<\/strong>.<\/li>\n\n\n\n<li>Con el\u00a0<strong>A\u00f1adir elementos de men\u00fa<\/strong>\u00a0de la izquierda, a\u00f1ada los elementos de men\u00fa que necesite.\u00a0<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Uso del men\u00fa If con MemberPress<\/h2>\n\n\n\n<p>Con el plugin instalado y activo en su sitio y su men\u00fa creado, ya puede empezar a utilizar la l\u00f3gica del plugin If Menu:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Ve a la p\u00e1gina Panel de control de WordPress &gt; Apariencia &gt; Men\u00fas.\u00a0<\/li>\n\n\n\n<li>Compruebe la pesta\u00f1a Opciones de pantalla y active todas las opciones disponibles para su men\u00fa.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/Screen20recording202017-06-0720at2001330820PM.gif\" alt=\"\"\/><\/figure>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>En el <strong>Estructura del men\u00fa <\/strong>busque el elemento de men\u00fa al que desea a\u00f1adir l\u00f3gica condicional.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2019\/12\/Screen-Recording-2019-12-31-at-12.24.13.08-PM.gif\" alt=\"\"\/><\/figure>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li>Haga clic en la flecha hacia abajo situada a la derecha de la opci\u00f3n.\u00a0<\/li>\n\n\n\n<li>Compruebe el <strong>Activar reglas de visibilidad<\/strong> casilla de verificaci\u00f3n.<\/li>\n\n\n\n<li>A\u00f1ada la(s) sentencia(s) condicional(es) que desee y, a continuaci\u00f3n, haga clic en el bot\u00f3n azul <strong>Guardar men\u00fa <\/strong>bot\u00f3n.\u00a0<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">MemberPress L\u00f3gica espec\u00edfica<\/h3>\n\n\n\n<p>El plugin If Menu tendr\u00e1 la condici\u00f3n adicional de <strong>Activo en la afiliaci\u00f3n<\/strong> a su disposici\u00f3n cuando cumpla estas dos condiciones:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Usted <strong><a href=\"https:\/\/memberpress.com\/es\/docs\/how-to-install-memberpress\/\" target=\"_blank\" rel=\"noopener\" title=\"\">instalado <\/a><\/strong>y <strong><a href=\"https:\/\/memberpress.com\/es\/docs\/activate-your-memberpress-license\/#activate-memberpress\" target=\"_blank\" rel=\"noopener\" title=\"\">activado MemberPress<\/a><\/strong>.<\/li>\n\n\n\n<li>Usted tiene <a href=\"https:\/\/memberpress.com\/es\/docs\/creating-memberships\/\" target=\"_blank\" rel=\"noopener\"><strong>creado al menos una Afiliaci\u00f3n<\/strong><\/a> en MemberPress.<\/li>\n<\/ol>\n\n\n\n<p>Para utilizar esta condici\u00f3n, seleccione <strong>\u2014 Cualquier membres\u00eda \u2014<\/strong> o el nombre de una de sus afiliaciones activas para establecer la condici\u00f3n.\u00a0<\/p>\n\n\n\n<p>Desde la versi\u00f3n 1.8.8 de MemberPress, tambi\u00e9n puede seleccionar una regla de la lista <strong>Norma de afiliaci\u00f3n activa<\/strong> grupo.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"429\" height=\"525\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-54.png\" alt=\"\" class=\"wp-image-75577\" style=\"width:453px;height:auto\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-54.png 429w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-54-245x300.png 245w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-54-41x50.png 41w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-54-139x170.png 139w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-54-423x518.png 423w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-54-127x156.png 127w\" sizes=\"(max-width: 429px) 100vw, 429px\" \/><\/figure>\n\n\n\n<p>De esta forma, puede mostrar un elemento del men\u00fa para los usuarios que cumplan las condiciones de acceso de la regla seleccionada sin comprobar cada uno de los miembros individualmente. Tambi\u00e9n puede hacerlo utilizando las opciones y\/o del men\u00fa If para la condici\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>You can customize your menu item visibility with the If Menu \u2013 Visibility control for Menu Items plugin. You can set visibility depending on whether your users are logged in or actively subscribed to one of your memberships. MemberPress includes built-in If Menu integration. This document explains how to use the If Menu plugin with [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1315],"ht-kb-tag":[],"class_list":{"0":"post-62746","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-how-to","7":"entry","8":"has-post-thumbnail"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"This document explains how to use the If Menu plugin with MemberPress to set menu item visibility based on memberships.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"How to Use If Menu with MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"This document explains how to use the If Menu plugin with MemberPress to set menu item visibility based on memberships.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T15:27:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-23T20:00:38+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"How to Use If Menu with MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"This document explains how to use the If Menu plugin with MemberPress to set menu item visibility based on memberships.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/#article\",\"name\":\"How to Use If Menu with MemberPress\",\"headline\":\"How to Use If Menu with MemberPress\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Screen20recording202017-06-0720at2001330820PM.gif\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/#articleImage\",\"width\":1362,\"height\":698},\"datePublished\":\"2024-02-13T10:27:54-05:00\",\"dateModified\":\"2025-10-23T16:00:38-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/#webpage\"},\"articleSection\":\"How To\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/faqs\\\/#listItem\",\"name\":\"FAQs\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/faqs\\\/#listItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/faqs\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/how-to\\\/#listItem\",\"name\":\"How To\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/how-to\\\/#listItem\",\"position\":3,\"name\":\"How To\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/how-to\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/#listItem\",\"name\":\"How to Use If Menu with MemberPress\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/faqs\\\/#listItem\",\"name\":\"FAQs\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/#listItem\",\"position\":4,\"name\":\"How to Use If Menu with MemberPress\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/how-to\\\/#listItem\",\"name\":\"How To\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/\",\"name\":\"How to Use If Menu with MemberPress\",\"description\":\"This document explains how to use the If Menu plugin with MemberPress to set menu item visibility based on memberships.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/how-to-use-if-menu-with-memberpress\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-02-13T10:27:54-05:00\",\"dateModified\":\"2025-10-23T16:00:38-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>How to Use If Menu with MemberPress<\/title>\n\n","aioseo_head_json":{"title":"C\u00f3mo utilizar el men\u00fa If con MemberPress","description":"Este documento explica c\u00f3mo utilizar el plugin If Menu con MemberPress para establecer la visibilidad de los elementos del men\u00fa en funci\u00f3n de las afiliaciones.","canonical_url":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/#article","name":"How to Use If Menu with MemberPress","headline":"How to Use If Menu with MemberPress","author":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/Screen20recording202017-06-0720at2001330820PM.gif","@id":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/#articleImage","width":1362,"height":698},"datePublished":"2024-02-13T10:27:54-05:00","dateModified":"2025-10-23T16:00:38-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/#webpage"},"articleSection":"How To"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/faqs\/#listItem","name":"FAQs"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/faqs\/#listItem","position":2,"name":"FAQs","item":"https:\/\/memberpress.com\/es\/doc-categories\/faqs\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/how-to\/#listItem","name":"How To"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/how-to\/#listItem","position":3,"name":"How To","item":"https:\/\/memberpress.com\/es\/doc-categories\/how-to\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/#listItem","name":"How to Use If Menu with MemberPress"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/faqs\/#listItem","name":"FAQs"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/#listItem","position":4,"name":"How to Use If Menu with MemberPress","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/how-to\/#listItem","name":"How To"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/es\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/#webpage","url":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/","name":"How to Use If Menu with MemberPress","description":"This document explains how to use the If Menu plugin with MemberPress to set menu item visibility based on memberships.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/memberpress.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-02-13T10:27:54-05:00","dateModified":"2025-10-23T16:00:38-04:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/es\/#website","url":"https:\/\/memberpress.com\/es\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"es-ES","publisher":{"@id":"https:\/\/memberpress.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"MemberPress","og:type":"article","og:title":"How to Use If Menu with MemberPress","og:description":"This document explains how to use the If Menu plugin with MemberPress to set menu item visibility based on memberships.","og:url":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-02-13T15:27:54+00:00","article:modified_time":"2025-10-23T20:00:38+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"How to Use If Menu with MemberPress","twitter:description":"This document explains how to use the If Menu plugin with MemberPress to set menu item visibility based on memberships.","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"62746","title":"#post_title","description":"Este documento explica c\u00f3mo utilizar el plugin If Menu con MemberPress para establecer la visibilidad de los elementos del men\u00fa en funci\u00f3n de las afiliaciones.","keywords":null,"keyphrases":{"focus":{"keyphrase":"If Menu","score":82,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"menu item visibility","score":67,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":3},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-23 20:05:42","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-02-13 15:27:54","updated":"2026-03-03 14:52:41"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/faqs\/\" title=\"FAQs\">FAQs<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/how-to\/\" title=\"How To\">How To<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tHow to Use If Menu with MemberPress\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/es"},{"label":"FAQs","link":"https:\/\/memberpress.com\/es\/doc-categories\/faqs\/"},{"label":"How To","link":"https:\/\/memberpress.com\/es\/doc-categories\/how-to\/"},{"label":"How to Use If Menu with MemberPress","link":"https:\/\/memberpress.com\/es\/docs\/how-to-use-if-menu-with-memberpress\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/62746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/comments?post=62746"}],"version-history":[{"count":3,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/62746\/revisions"}],"predecessor-version":[{"id":75580,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/62746\/revisions\/75580"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/media?parent=62746"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb-category?post=62746"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb-tag?post=62746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}