{"id":69107,"date":"2024-10-25T10:20:47","date_gmt":"2024-10-25T14:20:47","guid":{"rendered":"https:\/\/memberpress.com\/?post_type=ht_kb&#038;p=69107"},"modified":"2025-10-23T14:37:04","modified_gmt":"2025-10-23T18:37:04","slug":"memberpress-custom-integrations","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/","title":{"rendered":"MemberPress Integraciones personalizadas"},"content":{"rendered":"<p>Los complementos nativos y de terceros de MemberPress son soluciones listas para usar para ampliar las capacidades de MemberPress. Tambi\u00e9n puede crear integraciones MemberPress Zero Code o desarrollar integraciones personalizadas.<\/p>\n\n\n\n<p>Este documento explica c\u00f3mo funcionan el C\u00f3digo Cero y las integraciones personalizadas para MemberPress y c\u00f3mo puede crearlas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"developer-tools\"><a href=\"#developer-tools\" title=\"\">MemberPress Herramientas para desarrolladores<\/a><\/h2>\n\n\n\n<p>Para crear integraciones personalizadas o algunas de las integraciones de Zero Code, debe <a href=\"https:\/\/memberpress.com\/es\/docs\/overview-of-using-the-developer-tools\/\"><strong>activar el complemento MemberPress Developer Tools<\/strong><\/a> en su sitio web.<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\"><strong>Nota:<\/strong> Este complemento est\u00e1 disponible para MemberPress <strong>Escala<\/strong> miembros del plan. Puedes pasar al plan Escala si est\u00e1s suscrito a otro plan. Para ello, haga clic en el bot\u00f3n\u00a0<strong>Plan de cambio<\/strong>\u00a0enlace en su\u00a0<strong><a href=\"https:\/\/memberpress.com\/account\/subscriptions\/\" title=\"\">p\u00e1gina de la cuenta<\/a><\/strong>.<\/p>\n\n\n\n<p>El complemento Developer Tools permite que su plugin MemberPress se comunique con otras plataformas y plugins. Por lo tanto, las plataformas de terceros que requieren acceso al plugin MemberPress de su sitio web (por ejemplo, Zapier) requerir\u00e1n un complemento Developer Tools activado.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"zero-code\"><a href=\"#zero-code\" title=\"\">Integraciones de c\u00f3digo cero<\/a><\/h2>\n\n\n\n<p>Las integraciones Zero Code le permiten integrar MemberPress con plataformas y plugins de terceros a trav\u00e9s de herramientas de automatizaci\u00f3n que act\u00faan como intermediarias. Aqu\u00ed puede elegir entre las siguientes herramientas de automatizaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/memberpress.com\/es\/addons\/uncanny-automator\/\" target=\"_blank\" rel=\"noopener\"><strong>Uncanny Automator<\/strong><\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/memberpress.com\/es\/addons\/zapier\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>Zapier<\/strong><\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/memberpress.com\/es\/addons\/integrately\/\" target=\"_blank\" rel=\"noopener\"><strong>Integramente<\/strong><\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.make.com\/en\/integrations\/memberpress\" target=\"_blank\" rel=\"noopener\"><strong>Visite<\/strong><\/a>;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.pabbly.com\/connect\/integrations\/memberpress\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>Pabbly<\/strong><\/a>.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\"><strong>Nota:<\/strong> Estos complementos est\u00e1n disponibles para MemberPress <strong>Escala<\/strong> miembros del plan. Puedes pasar al plan Escala si est\u00e1s suscrito a otro plan. Para ello, haga clic en el bot\u00f3n\u00a0<strong>Plan de cambio<\/strong>\u00a0enlace en su\u00a0<strong><a href=\"https:\/\/memberpress.com\/account\/subscriptions\/\" title=\"\">p\u00e1gina de la cuenta<\/a><\/strong>.<\/p>\n\n\n\n<p>Adem\u00e1s, el <a href=\"https:\/\/mailoptin.io\/article\/memberpress-mailchimp-aweber-more\/\"><strong>MailOptin<\/strong><\/a> y <a href=\"https:\/\/memberpress.com\/es\/addons\/mail-mint-email-marketing-automation\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>Mail Mint<\/strong><\/a> Los plugins s\u00f3lo permiten integraciones entre MemberPress y plataformas de marketing. <\/p>\n\n\n\n<p>Al elegir una herramienta de automatizaci\u00f3n, aseg\u00farese de que admite integraciones con el plugin o la plataforma de terceros que necesite.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"automation-tools\"><a href=\"#automation-tools\" title=\"\">Conexi\u00f3n de herramientas de automatizaci\u00f3n<\/a><\/h3>\n\n\n\n<p>Antes de crear integraciones Zero Code, debe pasar por varios procesos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Conecte el plugin MemberPress en su sitio web<\/strong> con la herramienta de automatizaci\u00f3n que elijas;<\/li>\n\n\n\n<li><strong>Conectar la herramienta de automatizaci\u00f3n con el plugin o plataforma de terceros<\/strong> que desea integrar con MemberPress.<\/li>\n<\/ul>\n\n\n\n<p>Para conectar una herramienta de automatizaci\u00f3n con MemberPress, puede utilizar el plugin de herramientas de automatizaci\u00f3n o el complemento MemberPress Developer Tools. Esto depender\u00e1 de la herramienta de automatizaci\u00f3n que elijas. <\/p>\n\n\n\n<p>Por ejemplo, <a href=\"https:\/\/memberpress.com\/es\/docs\/memberpress-uncanny-automator-integrations\/\"><strong>Uncanny Automator<\/strong><\/a> tiene su propio plugin para WordPress, que debes instalar en tu sitio web. En cambio, para <a href=\"https:\/\/memberpress.com\/es\/docs\/official-memberpress-zapier-integration\/#connect-zapier\"><strong>conectar Zapier a MemberPress<\/strong><\/a>necesitar\u00e1 un <strong>Clave API REST<\/strong>disponible a trav\u00e9s de las Herramientas para desarrolladores.<\/p>\n\n\n\n<p>Adem\u00e1s, tendr\u00e1s que abrir una cuenta para la herramienta de automatizaci\u00f3n que hayas elegido para conectarla con otros plugins y plataformas.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\"><strong>Nota<\/strong>: <strong>Sin cuotas ni suscripciones adicionales a MemberPress<\/strong> para crear integraciones de C\u00f3digo Cero. No obstante, <strong>algunas integraciones pueden conllevar el pago de tarifas adicionales por herramientas de automatizaci\u00f3n o requerir suscripciones<\/strong>.<\/p>\n\n\n\n<p>Cuando conecte plugins y plataformas de terceros con herramientas de automatizaci\u00f3n, consulte su soporte y documentaci\u00f3n para obtener informaci\u00f3n y asistencia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"automation-workflow\"><a href=\"#automation-workflow\" title=\"\">Flujo de trabajo de automatizaci\u00f3n<\/a><\/h3>\n\n\n\n<p>Las integraciones Zero Code son automatizaciones que puede crear utilizando activadores y acciones predefinidos para cada plataforma y plugin.<\/p>\n\n\n\n<p>A <strong>desencadenar <\/strong>es un evento que ocurre en un lado de la integraci\u00f3n que inicia y ejecuta un flujo de trabajo de automatizaci\u00f3n.\u00a0<\/p>\n\n\n\n<p>En <strong>acci\u00f3n <\/strong>es un evento que se ejecuta en el otro lado de la misma integraci\u00f3n despu\u00e9s de que se inicie el flujo de trabajo de automatizaci\u00f3n.\u00a0<\/p>\n\n\n\n<p>Para ilustrarlo, podr\u00edamos crear una integraci\u00f3n para <a href=\"https:\/\/memberpress.com\/es\/docs\/memberpress-uncanny-automator-integrations\/#example-1\"><strong>enviar un correo electr\u00f3nico personalizado cuando los usuarios se registren<\/strong><\/a> a trav\u00e9s de MemberPress. Aqu\u00ed, el <strong>desencadenar <\/strong>ser\u00eda un <strong>usuario que se registra para ser miembro de MemberPress<\/strong>. En <strong>acci\u00f3n <\/strong>en este flujo de trabajo ser\u00eda que el sitio web <strong>enviar un correo electr\u00f3nico<\/strong>.<\/p>\n\n\n\n<p>Aunque no necesitas conocimientos de programaci\u00f3n, tendr\u00e1s que crear estas integraciones t\u00fa mismo, siguiendo las directrices generales:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A <strong>desencadenar <\/strong>debe iniciar el flujo de trabajo de automatizaci\u00f3n;<\/li>\n\n\n\n<li>El flujo de trabajo de automatizaci\u00f3n debe contener <strong>al menos una acci\u00f3n<\/strong>;<\/li>\n\n\n\n<li>Puede a\u00f1adir <strong>l\u00f3gica condicional<\/strong> a su flujo de trabajo de automatizaci\u00f3n. Esto significa que puede combinar varios activadores o a\u00f1adir condiciones a sus activadores. En algunos casos, tambi\u00e9n puede a\u00f1adir varias acciones.\u00a0<\/li>\n<\/ul>\n\n\n\n<p>Es importante mencionar que cada herramienta de automatizaci\u00f3n tiene caracter\u00edsticas y capacidades espec\u00edficas. Adem\u00e1s, los disparadores y acciones disponibles difieren para cada plugin y plataforma en cada herramienta de automatizaci\u00f3n. Por lo tanto, aseg\u00farese de que la herramienta de automatizaci\u00f3n y <strong>los desencadenantes y acciones de integraci\u00f3n disponibles satisfacen sus necesidades<\/strong> antes de crear integraciones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"custom-integrations\"><a href=\"#custom-integrations\" title=\"\">Desarrollo de integraciones personalizadas<\/a><\/h2>\n\n\n\n<p>Adem\u00e1s, puede escribir su propio c\u00f3digo y crear casi cualquier integraci\u00f3n personalizada con MemberPress.<\/p>\n\n\n\n<p>Al igual que las integraciones de C\u00f3digo Cero, las integraciones personalizadas utilizan <a href=\"https:\/\/memberpress.com\/es\/docs\/developer-tools-event-triggers\/\"><strong>Disparadores de eventos MemberPress<\/strong><\/a> para ejecutar acciones en un plugin o plataforma de terceros. Igualmente, <a href=\"https:\/\/memberpress.com\/es\/docs\/developer-tools-actions\/\"><strong>Acciones MemberPress<\/strong><\/a> le permite desencadenar acciones en MemberPress siguiendo eventos de un plugin o plataforma de terceros.<\/p>\n\n\n\n<p>Una vez activado el <a href=\"https:\/\/memberpress.com\/es\/docs\/overview-of-using-the-developer-tools\/\"><strong>MemberPress Herramientas para desarrolladores<\/strong><\/a> puede ir a <strong>Panel de control &gt; MemberPress &gt; Desarrollador<\/strong>. Aqu\u00ed encontrar\u00e1 las siguientes opciones necesarias para desarrollar integraciones personalizadas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Webhooks<\/strong>en esta opci\u00f3n puedes encontrar tu Clave Webhook generada autom\u00e1ticamente y configurar las URLs Webhook. La Clave Webhook es \u00fanica para su sitio web y necesaria para autenticar las peticiones POST de webhook. Si es necesario, tambi\u00e9n puede generar una nueva clave Webhook aqu\u00ed;<\/li>\n\n\n\n<li><strong>Eventos<\/strong>: Aqu\u00ed puede ver y probar todos los eventos webhook de MemberPress. Cada evento tiene una descripci\u00f3n y una respuesta JSON de ejemplo;<\/li>\n\n\n\n<li><strong>API REST<\/strong>: Su clave de API est\u00e1 disponible en esta opci\u00f3n. Debe utilizar esta clave de API para la autenticaci\u00f3n de la API REST. Adem\u00e1s, puede ver todas las rutas API disponibles. Cada ruta API tiene un <strong>descripci\u00f3n, definici\u00f3n, lista de argumentos y ejemplos de solicitud y respuesta<\/strong>. Si lo necesita, tambi\u00e9n puede generar una nueva clave API aqu\u00ed.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>MemberPress native and third-party add-ons are out-of-the-box solutions for extending MemberPress capabilities. Alternatively, you can create MemberPress Zero Code integrations or develop custom integrations. This document explains how Zero Code and custom integrations for MemberPress work and how you can create them. MemberPress Developer Tools To create custom or some of the Zero Code integrations, [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1316,1437],"ht-kb-tag":[],"class_list":{"0":"post-69107","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-developer-tools","7":"ht_kb_category-custom-solutions","8":"entry"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"This document covers the basics of creating MemberPress Zero Code integrations and explains the tools available for developing custom integrations.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"MemberPress Custom Integrations\" \/>\n\t\t<meta property=\"og:description\" content=\"This document covers the basics of creating MemberPress Zero Code integrations and explains the tools available for developing custom integrations.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-10-25T14:20:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-23T18:37:04+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"MemberPress Custom Integrations\" \/>\n\t\t<meta name=\"twitter:description\" content=\"This document covers the basics of creating MemberPress Zero Code integrations and explains the tools available for developing custom integrations.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/memberpress-custom-integrations\\\/#article\",\"name\":\"MemberPress Custom Integrations\",\"headline\":\"MemberPress Custom Integrations\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#articleImage\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"datePublished\":\"2024-10-25T10:20:47-04:00\",\"dateModified\":\"2025-10-23T14:37:04-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/memberpress-custom-integrations\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/memberpress-custom-integrations\\\/#webpage\"},\"articleSection\":\"Developer Tools, Custom Solutions\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/memberpress-custom-integrations\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/advanced-topics\\\/#listItem\",\"name\":\"Advanced Topics\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/advanced-topics\\\/#listItem\",\"position\":2,\"name\":\"Advanced Topics\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/advanced-topics\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/developer-tools\\\/#listItem\",\"name\":\"Developer Tools\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/developer-tools\\\/#listItem\",\"position\":3,\"name\":\"Developer Tools\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/developer-tools\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/memberpress-custom-integrations\\\/#listItem\",\"name\":\"MemberPress Custom Integrations\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/advanced-topics\\\/#listItem\",\"name\":\"Advanced Topics\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/memberpress-custom-integrations\\\/#listItem\",\"position\":4,\"name\":\"MemberPress Custom Integrations\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/developer-tools\\\/#listItem\",\"name\":\"Developer Tools\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/memberpress-custom-integrations\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/memberpress-custom-integrations\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/memberpress-custom-integrations\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/memberpress-custom-integrations\\\/\",\"name\":\"MemberPress Custom Integrations\",\"description\":\"This document covers the basics of creating MemberPress Zero Code integrations and explains the tools available for developing custom integrations.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/memberpress-custom-integrations\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-10-25T10:20:47-04:00\",\"dateModified\":\"2025-10-23T14:37:04-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>MemberPress Custom Integrations<\/title>\n\n","aioseo_head_json":{"title":"MemberPress Integraciones personalizadas","description":"Este documento cubre los aspectos b\u00e1sicos de la creaci\u00f3n de integraciones MemberPress Zero Code y explica las herramientas disponibles para desarrollar integraciones personalizadas.","canonical_url":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/#article","name":"MemberPress Custom Integrations","headline":"MemberPress Custom Integrations","author":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/es\/#articleImage","width":1650,"height":1275,"caption":"memberpress logo icon"},"datePublished":"2024-10-25T10:20:47-04:00","dateModified":"2025-10-23T14:37:04-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/#webpage"},"articleSection":"Developer Tools, Custom Solutions"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/advanced-topics\/#listItem","name":"Advanced Topics"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/advanced-topics\/#listItem","position":2,"name":"Advanced Topics","item":"https:\/\/memberpress.com\/es\/doc-categories\/advanced-topics\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/developer-tools\/#listItem","name":"Developer Tools"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/developer-tools\/#listItem","position":3,"name":"Developer Tools","item":"https:\/\/memberpress.com\/es\/doc-categories\/developer-tools\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/#listItem","name":"MemberPress Custom Integrations"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/advanced-topics\/#listItem","name":"Advanced Topics"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/#listItem","position":4,"name":"MemberPress Custom Integrations","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/developer-tools\/#listItem","name":"Developer Tools"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/es\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/#webpage","url":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/","name":"MemberPress Custom Integrations","description":"This document covers the basics of creating MemberPress Zero Code integrations and explains the tools available for developing custom integrations.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/memberpress.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-10-25T10:20:47-04:00","dateModified":"2025-10-23T14:37:04-04:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/es\/#website","url":"https:\/\/memberpress.com\/es\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"es-ES","publisher":{"@id":"https:\/\/memberpress.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"MemberPress","og:type":"article","og:title":"MemberPress Custom Integrations","og:description":"This document covers the basics of creating MemberPress Zero Code integrations and explains the tools available for developing custom integrations.","og:url":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-10-25T14:20:47+00:00","article:modified_time":"2025-10-23T18:37:04+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"MemberPress Custom Integrations","twitter:description":"This document covers the basics of creating MemberPress Zero Code integrations and explains the tools available for developing custom integrations.","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"69107","title":"#post_title","description":"Este documento cubre los aspectos b\u00e1sicos de la creaci\u00f3n de integraciones MemberPress Zero Code y explica las herramientas disponibles para desarrollar integraciones personalizadas.","keywords":null,"keyphrases":{"focus":{"keyphrase":"Custom Integrations","score":90,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":[],"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Zero Code","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":[],"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-23 18:40:19","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-10-25 14:19:00","updated":"2026-03-03 14:51:23"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/advanced-topics\/\" title=\"Advanced Topics\">Advanced Topics<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/developer-tools\/\" title=\"Developer Tools\">Developer Tools<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tMemberPress Custom Integrations\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/es"},{"label":"Advanced Topics","link":"https:\/\/memberpress.com\/es\/doc-categories\/advanced-topics\/"},{"label":"Developer Tools","link":"https:\/\/memberpress.com\/es\/doc-categories\/developer-tools\/"},{"label":"MemberPress Custom Integrations","link":"https:\/\/memberpress.com\/es\/docs\/memberpress-custom-integrations\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/69107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/comments?post=69107"}],"version-history":[{"count":8,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/69107\/revisions"}],"predecessor-version":[{"id":75570,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/69107\/revisions\/75570"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/media?parent=69107"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb-category?post=69107"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb-tag?post=69107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}