{"id":76458,"date":"2025-11-21T10:22:38","date_gmt":"2025-11-21T15:22:38","guid":{"rendered":"https:\/\/memberpress.com\/?post_type=ht_kb&#038;p=76458"},"modified":"2025-12-05T02:48:16","modified_gmt":"2025-12-05T07:48:16","slug":"designing-member-profiles","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/","title":{"rendered":"Dise\u00f1o de perfiles MemberPress"},"content":{"rendered":"<p>Puede dise\u00f1ar perfiles MemberPress <strong>utilizando patrones de inicio predefinidos o creando su propio dise\u00f1o personalizado<\/strong>. Los perfiles MemberPress son <strong>Basado en Gutenberg<\/strong>, lo que significa que puede dise\u00f1ar perfiles con <strong>bloques espec\u00edficos de perfil y cualquier otro bloque de Gutenberg<\/strong>.\u00a0<\/p>\n\n\n\n<p>En este documento se explica c\u00f3mo dise\u00f1ar perfiles MemberPress que se adapten a su sitio web y a su marca, <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"starter-patterns\"><a href=\"#starter-patterns\" title=\"\">Uso de patrones de inicio de perfil<\/a><\/h3>\n\n\n\n<p>MemberPress incluye cuatro patrones de perfil profesional como puntos de partida:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Perfil Cl\u00e1sico<\/strong> coloca la foto de perfil y el nombre del afiliado a la izquierda de la cabecera del perfil. El resto de la informaci\u00f3n del usuario se alinea a la izquierda;<\/li>\n\n\n\n<li><strong>Perfil cl\u00e1sico \u2013 Derecha <\/strong>refleja la cabecera del modelo Classic, con la foto de perfil y el nombre del afiliado. El resto de la informaci\u00f3n de los miembros permanece alineada a la izquierda;<\/li>\n\n\n\n<li><strong>Perfil cl\u00e1sico \u2013 Centrado<\/strong> Alinea la foto de perfil y el nombre del miembro en el centro, con toda la informaci\u00f3n alineada  a la izquierda;<\/li>\n\n\n\n<li><strong>Disposici\u00f3n de la divisi\u00f3n de perfiles<\/strong> divide los perfiles en tres secciones distintas. La cabecera del perfil se encuentra en la parte superior de la p\u00e1gina, y el resto de la p\u00e1gina se divide en dos secciones: izquierda y derecha. Aqu\u00ed, la foto de perfil y el nombre del miembro se encuentran a la izquierda. El resto de la informaci\u00f3n se encuentra a la derecha.<\/li>\n<\/ul>\n\n\n\n<p>Al a\u00f1adir un nuevo tipo de perfil, se le pedir\u00e1 que elija uno de los patrones de inicio disponibles.\u00a0<\/p>\n\n\n\n<p>Si se omiten, puede a\u00f1adir estos patrones a trav\u00e9s del insertador de bloques:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Despl\u00e1cese hasta el tipo de perfil, pase el rat\u00f3n por encima de su nombre y haga clic en <strong>Editar<\/strong>.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f56e32\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f56e32\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1315\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile.png\" alt=\"\" class=\"wp-image-75892\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-1536x790.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-2048x1053.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-331x170.png 331w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-1216x625.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-1832x942.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-1080x555.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li>Haga clic en el Insertador de bloques <strong>+ icono<\/strong>.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f571c9\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f571c9\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter.png\" alt=\"\" class=\"wp-image-75893\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>A continuaci\u00f3n, haga clic en el bot\u00f3n <strong>Patrones <\/strong>y despl\u00e1cese hasta la pesta\u00f1a <strong>Contenido de Strater<\/strong> grupo.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f57542\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f57542\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns.png\" alt=\"\" class=\"wp-image-75894\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><strong>Seleccione <\/strong>su patr\u00f3n preferido para a\u00f1adirlo al Perfil.<\/li>\n<\/ol>\n\n\n\n<p>Los patrones son grupos de bloques de perfil. Puede a\u00f1adir o eliminar bloques de Perfil, a\u00f1adir cualquier bloque Gutneberg adicional y personalizar cada bloque para que coincida con su marca.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"profile-blocks\"><a href=\"#profile-blocks\" title=\"\">Trabajar con bloques de perfil<\/a><\/h3>\n\n\n\n<p>Los bloques Perfil son componentes individuales que puedes utilizar para dise\u00f1ar los perfiles de tus miembros utilizando el editor predeterminado (Gutenberg).\u00a0<\/p>\n\n\n\n<p>Cada bloque de perfil MemberPress se utiliza para mostrar datos espec\u00edficos de los miembros en las p\u00e1ginas de perfil de los usuarios y viene con amplias opciones de personalizaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En <strong>Bloque de cabecera de perfil<\/strong> abarca todo el ancho de la tarjeta de perfil. Configure los colores de fondo, active las im\u00e1genes de portada, controle la altura y a\u00f1ada superposiciones para facilitar la lectura del texto.<\/li>\n\n\n\n<li><strong>Perfil Secci\u00f3n Bloques<\/strong> Organice el contenido en agrupaciones l\u00f3gicas. A\u00f1ada t\u00edtulos, personalice fondos, controle el relleno y aplique bordes para una separaci\u00f3n visual.<\/li>\n\n\n\n<li>En <strong>Bloque de fotos de perfil<\/strong> muestra las im\u00e1genes de los afiliados con controles de tama\u00f1o, opciones de forma (cuadrada, redondeada, circular), tratamientos de bordes e im\u00e1genes de reserva para los afiliados sin foto.<\/li>\n\n\n\n<li><strong>Bloques de cubierta de perfil<\/strong> mostrar im\u00e1genes de banner, permitiendo la expresi\u00f3n personal. Establezca portadas predeterminadas, controle las dimensiones, ajuste el posicionamiento y a\u00f1ada superposiciones, garantizando la visibilidad del contenido.<\/li>\n\n\n\n<li>En <strong>Nombre del perfil Bloque<\/strong> presenta las identidades de los miembros con opciones de formato que van desde s\u00f3lo el nombre de pila hasta los nombres completos formales, adem\u00e1s de controles tipogr\u00e1ficos y texto suplementario para los t\u00edtulos.<\/li>\n\n\n\n<li><strong>Bloques de iconos de perfil<\/strong> A\u00f1ade cualquier icono a tus perfiles. Utiliza este bloque para a\u00f1adir iconos a los encabezados o a cualquier parte de la p\u00e1gina del perfil. Puedes elegir cualquier icono disponible y establecer su tama\u00f1o, espaciado y colores.<\/li>\n\n\n\n<li><strong>Bloques de campos de usuario de perfil<\/strong> mostrar informaci\u00f3n de los perfiles de los afiliados y de los campos personalizados. Seleccione qu\u00e9 campos aparecen, controle las etiquetas, organ\u00edcelos en columnas o listas y gestione los campos vac\u00edos de forma inteligente.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Campos de perfil del usuario<\/h3>\n\n\n\n<p>En <strong>Bloque de campo de perfil de usuario<\/strong> A\u00f1ade din\u00e1micamente datos de usuario a sus perfiles MemberPress. Puede utilizar este bloque dentro de los bloques de la secci\u00f3n Perfil o en cualquier otro lugar de la p\u00e1gina de perfil.<\/p>\n\n\n\n<p>Para importar un \u00fanico dato de informaci\u00f3n del usuario a un perfil, es necesario a\u00f1adir y configurar el bloque:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Al editar un perfil, <strong>A\u00f1adir el bloque Campo de perfil de usuario<\/strong> utilizando el inserto de bloques.<\/li>\n\n\n\n<li><strong>Haga clic en el bloque.<\/strong> que insertaste para abrir su <strong>Ajustes <\/strong>en el panel derecho.<\/li>\n\n\n\n<li>Configure el bloque utilizando el <strong>Configuraci\u00f3n de campo<\/strong> panel:\n<ul class=\"wp-block-list\">\n<li><strong>Campo<\/strong>: seleccione el campo MemberPress en este men\u00fa desplegable. De este modo, el bloque mostrar\u00e1 los datos del campo seleccionado en la p\u00e1gina de perfil. Por ejemplo, para mostrar el nombre de usuario de un usuario en su perfil, seleccione Nombre de usuario en este men\u00fa desplegable.;<\/li>\n\n\n\n<li><strong>Mostrar etiqueta<\/strong>: por defecto, esta opci\u00f3n est\u00e1 habilitada. Por lo tanto, la etiqueta del campo se mostrar\u00e1 en los perfiles de los usuarios junto con los datos del campo. Si desactiva esta opci\u00f3n, este bloque solo mostrar\u00e1 los datos.;<\/li>\n\n\n\n<li><strong>Texto de la etiqueta<\/strong>: puede a\u00f1adir texto personalizado a este campo para que se muestre en lugar de la etiqueta predeterminada.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f57be0\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f57be0\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2556\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings.png\" alt=\"\" class=\"wp-image-76571\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings.png 2556w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-1080x556.png 1080w\" sizes=\"(max-width: 2556px) 100vw, 2556px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><strong>Guardar <\/strong>cambios para aplicarlos a los perfiles de usuario.<\/li>\n<\/ol>\n\n\n\n<p>Con este bloque, puedes a\u00f1adir cualquier <strong>por defecto o <a href=\"https:\/\/memberpress.com\/es\/docs\/fields\/\" target=\"_blank\" rel=\"noopener\" title=\"\">campo personalizado MemberPress<\/a><\/strong> utilizado en sus p\u00e1ginas de registro y cuenta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A\u00f1adir y configurar el encabezado del perfil<\/h2>\n\n\n\n<p>MemberPress <strong>Encabezado del perfil<\/strong> block importa el encabezado de perfil predeterminado a tus perfiles. Ya <strong>incluye portada de perfil<\/strong> y <strong>Foto de perfil<\/strong> bloques y <strong>admite enlaces a redes sociales<\/strong>.<\/p>\n\n\n\n<p>Para a\u00f1adir y configurar el encabezado del perfil, siga estos pasos:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Empieza a editar tu perfil.<\/li>\n\n\n\n<li>Haga clic en el inserto de bloques y busque \u201cCabecera de perfil\u201d. Haga clic en el<strong> Encabezado del perfil <\/strong>bloque para importarlo.<\/li>\n\n\n\n<li>Una vez importado, haz clic en el bloque para abrir su configuraci\u00f3n. En la configuraci\u00f3n del bloque, establece el <strong>Posici\u00f3n de la foto<\/strong> a <strong>Izquierda<\/strong>, <strong>Centro, <\/strong>o <strong>Correcto<\/strong>.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f5813d\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f5813d\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2556\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings.png\" alt=\"\" class=\"wp-image-76577\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings.png 2556w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-1080x556.png 1080w\" sizes=\"(max-width: 2556px) 100vw, 2556px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"5\" class=\"wp-block-list\">\n<li>Adem\u00e1s, puede elegir entre activar o desactivar la opci\u00f3n <strong>Habilitar superposici\u00f3n<\/strong> opci\u00f3n. De forma predeterminada, esta opci\u00f3n estar\u00e1 habilitada, lo que permitir\u00e1 que la foto de perfil se superponga con la imagen de portada.<\/li>\n\n\n\n<li>Por fin, puedes <strong>estilo del encabezado<\/strong>. Haga clic en el bot\u00f3n <strong>Pesta\u00f1a Estilo <\/strong>para acceder a las opciones de estilo.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f584be\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f584be\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2556\" height=\"1315\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles.png\" alt=\"\" class=\"wp-image-76578\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles.png 2556w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-1536x790.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-1080x556.png 1080w\" sizes=\"(max-width: 2556px) 100vw, 2556px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"7\" class=\"wp-block-list\">\n<li>Haga clic en <strong>Publique <\/strong>\/ <strong>Guardar <\/strong>para aplicar los cambios.<\/li>\n<\/ol>\n\n\n\n<p>Como alternativa, puede a\u00f1adir <strong>Perfil Portada<\/strong> y <strong>Foto de perfil<\/strong> bloques individualmente en lugar de utilizar el <strong>Encabezado del perfil<\/strong> bloque. Puede utilizar este m\u00e9todo si est\u00e1 creando un dise\u00f1o de perfil personalizado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dise\u00f1o del encabezado del perfil<\/h3>\n\n\n\n<p>En <strong>Dise\u00f1a el encabezado de tu perfil<\/strong>, puede configurar los siguientes bloques:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Encabezado del perfil<\/strong> bloque:\n<ul class=\"wp-block-list\">\n<li><strong>Estilos<\/strong>: elija uno de los cuatro encabezados disponibles. <strong>estilos <\/strong>(Liso, con sombra, con borde o con borde inferior);<\/li>\n\n\n\n<li><strong>Color<\/strong>: establecer los colores de fondo y del texto del encabezado;<\/li>\n\n\n\n<li><strong>Dimensiones<\/strong>: personalizar encabezado <strong>acolchado <\/strong>y <strong>m\u00e1rgenes<\/strong>;<\/li>\n\n\n\n<li><strong>Sombra<\/strong>: establezca la sombra del encabezado haciendo clic en el <strong>Sombra paralela<\/strong> opci\u00f3n.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f58a77\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f58a77\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design.png\" alt=\"\" class=\"wp-image-76579\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Perfil Portada<\/strong> bloque:\n<ul class=\"wp-block-list\">\n<li><strong>Punto focal<\/strong>: mueva el punto focal a la secci\u00f3n deseada de la imagen de portada;<\/li>\n\n\n\n<li><strong>Dimensiones de la cubierta<\/strong>: colocar la cubierta <strong>Altura <\/strong>(Bajo, mediano o alto);<\/li>\n\n\n\n<li><strong>Configuraci\u00f3n de superposici\u00f3n<\/strong>: a\u00f1adir una superposici\u00f3n configurando el <strong>Opacidad <\/strong>porcentaje.<\/li>\n\n\n\n<li><strong>Configuraci\u00f3n de color<\/strong>: fija el <strong>Color de superposici\u00f3n<\/strong>.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f58e59\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f58e59\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design.png\" alt=\"\" class=\"wp-image-76580\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">A\u00f1adir y configurar secciones y datos<\/h2>\n\n\n\n<p>El MemberPress <strong>Secci\u00f3n de perfil <\/strong>El bloque se utiliza para agrupar campos de datos de usuario y cualquier bloque adicional.<\/p>\n\n\n\n<p>Para a\u00f1adir y configurar la secci\u00f3n de perfil, siga estos pasos:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Empieza a editar tu perfil.<\/li>\n\n\n\n<li>Haga clic en el inserter de bloques y busque \u201cSecci\u00f3n de perfil\u201d. Haga clic en el <strong>Secci\u00f3n de perfil <\/strong>bloque para importarlo.<\/li>\n\n\n\n<li>Haga clic en el bloque que ha importado. En el panel de la derecha, haga clic en el <strong>Ajustes <\/strong>ficha.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f592b3\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f592b3\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings.png\" alt=\"\" class=\"wp-image-76581\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"5\" class=\"wp-block-list\">\n<li>Ampliar el <strong>Configuraci\u00f3n del dise\u00f1o<\/strong> panel y configure el <strong>Dise\u00f1o del campo:<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>En l\u00ednea<\/strong>: esta opci\u00f3n mostrar\u00e1 la etiqueta del campo y los datos en la misma l\u00ednea;<\/li>\n\n\n\n<li><strong>Apilado<\/strong>: esta opci\u00f3n apilar\u00e1 la etiqueta del campo y los datos, mostrando los datos debajo de la etiqueta.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Por defecto, el bloque de la secci\u00f3n de perfil ser\u00e1 <strong>importado con un encabezado predeterminado y varios campos de datos de perfil<\/strong>. Puede modificar el contenido predeterminado si es necesario:\n<ul class=\"wp-block-list\">\n<li>Actualizaci\u00f3n<strong> <\/strong>el <strong>encabezado <\/strong>y <strong>icono de encabezado<\/strong>;<\/li>\n\n\n\n<li><strong>Actualizar los campos de perfil del usuario<\/strong> seleccionando los campos MemberPress que necesite y\/o a\u00f1adiendo los campos personalizados. <strong>texto de la etiqueta<\/strong>;<\/li>\n\n\n\n<li><strong>A\u00f1adir nuevos bloques o eliminar<\/strong> los que no necesitas.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Por \u00faltimo, haga clic en el bot\u00f3n <strong>Estilo<\/strong> <strong>tab<\/strong> a <strong>estilizar la secci\u00f3n<\/strong>.<\/li>\n<\/ol>\n\n\n\n<ol start=\"7\" class=\"wp-block-list\"><\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f597d3\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f597d3\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2556\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles.png\" alt=\"\" class=\"wp-image-76582\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles.png 2556w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-1080x556.png 1080w\" sizes=\"(max-width: 2556px) 100vw, 2556px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"8\" class=\"wp-block-list\">\n<li>Haga clic en <strong>Guardar <\/strong>para aplicar los cambios.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Dise\u00f1o de la secci\u00f3n Perfil<\/h3>\n\n\n\n<p>Al dise\u00f1ar la secci\u00f3n de tu perfil, puedes configurar los siguientes bloques:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Secci\u00f3n de perfil <\/strong>bloque:\n<ul class=\"wp-block-list\">\n<li><strong>Estilos<\/strong>: elija una de las cuatro secciones disponibles <strong>estilos <\/strong>(Liso, con sombra, con borde o con borde inferior);<\/li>\n\n\n\n<li><strong>Color<\/strong>: establecer los colores de fondo y del texto de la secci\u00f3n;<\/li>\n\n\n\n<li><strong>Dimensiones<\/strong>: personalizar secci\u00f3n <strong>acolchado <\/strong>y <strong>m\u00e1rgenes<\/strong>;<\/li>\n\n\n\n<li><strong>Borde y sombra<\/strong>: establecer la secci\u00f3n<strong> Tama\u00f1o y radio del borde<\/strong>.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f59e5b\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f59e5b\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2556\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design.png\" alt=\"\" class=\"wp-image-76583\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design.png 2556w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-1080x556.png 1080w\" sizes=\"(max-width: 2556px) 100vw, 2556px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Campos de perfil del usuario <\/strong>bloque:\n<ul class=\"wp-block-list\">\n<li><strong>Color<\/strong>: establecer los colores de fondo y del texto del campo;<\/li>\n\n\n\n<li><strong>Tipograf\u00eda<\/strong>: establecer la fuente <strong>talla <\/strong>y <strong>altura de l\u00ednea<\/strong>.<\/li>\n\n\n\n<li><strong>Frontera<\/strong>: establecer el campo <strong>tama\u00f1o del borde<\/strong>.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04915f5a200\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04915f5a200\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2558\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design.png\" alt=\"\" class=\"wp-image-76584\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design.png 2558w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-1536x790.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-1832x942.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-1080x556.png 1080w\" sizes=\"(max-width: 2558px) 100vw, 2558px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>","protected":false},"excerpt":{"rendered":"<p>You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block.\u00a0 This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1525],"ht-kb-tag":[1533],"class_list":{"0":"post-76458","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-clubdirectory","7":"ht_kb_tag-community","8":"entry","9":"has-post-thumbnail"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Designing MemberPress Profiles\" \/>\n\t\t<meta property=\"og:description\" content=\"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-11-21T15:22:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-05T07:48:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Designing MemberPress Profiles\" \/>\n\t\t<meta name=\"twitter:description\" content=\"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/#article\",\"name\":\"Designing MemberPress Profiles\",\"headline\":\"Designing MemberPress Profiles\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/mpdir-edit-profile.png\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/#articleImage\",\"width\":2557,\"height\":1315},\"datePublished\":\"2025-11-21T10:22:38-05:00\",\"dateModified\":\"2025-12-05T02:48:16-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/#webpage\"},\"articleSection\":\"ClubDirectory\\u2122, Community\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/add-ons\\\/#listItem\",\"name\":\"Add-ons\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/add-ons\\\/#listItem\",\"position\":2,\"name\":\"Add-ons\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/add-ons\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/community\\\/#listItem\",\"name\":\"Community\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/community\\\/#listItem\",\"position\":3,\"name\":\"Community\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/community\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/clubsuite\\\/#listItem\",\"name\":\"ClubSuite\\u2122\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/add-ons\\\/#listItem\",\"name\":\"Add-ons\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/clubsuite\\\/#listItem\",\"position\":4,\"name\":\"ClubSuite\\u2122\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/clubsuite\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/clubdirectory\\\/#listItem\",\"name\":\"ClubDirectory\\u2122\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/community\\\/#listItem\",\"name\":\"Community\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/clubdirectory\\\/#listItem\",\"position\":5,\"name\":\"ClubDirectory\\u2122\",\"item\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/clubdirectory\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/#listItem\",\"name\":\"Designing MemberPress Profiles\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/clubsuite\\\/#listItem\",\"name\":\"ClubSuite\\u2122\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/#listItem\",\"position\":6,\"name\":\"Designing MemberPress Profiles\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/doc-categories\\\/clubdirectory\\\/#listItem\",\"name\":\"ClubDirectory\\u2122\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/\",\"name\":\"Designing MemberPress Profiles\",\"description\":\"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/docs\\\/designing-member-profiles\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2025-11-21T10:22:38-05:00\",\"dateModified\":\"2025-12-05T02:48:16-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/es\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Designing MemberPress Profiles<\/title>\n\n","aioseo_head_json":{"title":"Dise\u00f1o de perfiles MemberPress","description":"Puedes dise\u00f1ar perfiles MemberPress utilizando Starter Patterns predise\u00f1ados o crear tu propio dise\u00f1o personalizado. Los perfiles MemberPress est\u00e1n basados en Gutenberg, lo que significa que puedes dise\u00f1ar perfiles con bloques espec\u00edficos para perfiles y cualquier otro bloque de Gutenberg. Este documento te explicar\u00e1 c\u00f3mo puedes dise\u00f1ar perfiles MemberPress para que se adapten a tu sitio web y a tu marca, Utilizando Patrones de Inicio de Perfiles MemberPress incluye","canonical_url":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/#article","name":"Designing MemberPress Profiles","headline":"Designing MemberPress Profiles","author":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile.png","@id":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/#articleImage","width":2557,"height":1315},"datePublished":"2025-11-21T10:22:38-05:00","dateModified":"2025-12-05T02:48:16-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/#webpage"},"articleSection":"ClubDirectory\u2122, Community"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/add-ons\/#listItem","name":"Add-ons"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/add-ons\/#listItem","position":2,"name":"Add-ons","item":"https:\/\/memberpress.com\/es\/doc-categories\/add-ons\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/community\/#listItem","name":"Community"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/community\/#listItem","position":3,"name":"Community","item":"https:\/\/memberpress.com\/es\/doc-categories\/community\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/clubsuite\/#listItem","name":"ClubSuite\u2122"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/add-ons\/#listItem","name":"Add-ons"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/clubsuite\/#listItem","position":4,"name":"ClubSuite\u2122","item":"https:\/\/memberpress.com\/es\/doc-categories\/clubsuite\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/clubdirectory\/#listItem","name":"ClubDirectory\u2122"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/community\/#listItem","name":"Community"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/clubdirectory\/#listItem","position":5,"name":"ClubDirectory\u2122","item":"https:\/\/memberpress.com\/es\/doc-categories\/clubdirectory\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/#listItem","name":"Designing MemberPress Profiles"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/clubsuite\/#listItem","name":"ClubSuite\u2122"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/#listItem","position":6,"name":"Designing MemberPress Profiles","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/es\/doc-categories\/clubdirectory\/#listItem","name":"ClubDirectory\u2122"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/es\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/#webpage","url":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/","name":"Designing MemberPress Profiles","description":"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/memberpress.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/es\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2025-11-21T10:22:38-05:00","dateModified":"2025-12-05T02:48:16-05:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/es\/#website","url":"https:\/\/memberpress.com\/es\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"es-ES","publisher":{"@id":"https:\/\/memberpress.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"MemberPress","og:type":"article","og:title":"Designing MemberPress Profiles","og:description":"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes","og:url":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2025-11-21T15:22:38+00:00","article:modified_time":"2025-12-05T07:48:16+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Designing MemberPress Profiles","twitter:description":"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"76458","title":"#post_title","description":"#post_excerpt","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-12-05 07:52:33","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-11-24 15:22:08","updated":"2026-03-03 14:49:46"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/add-ons\/\" title=\"Add-ons\">Add-ons<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/community\/\" title=\"Community\">Community<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/clubsuite\/\" title=\"ClubSuite\u2122\">ClubSuite\u2122<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/es\/doc-categories\/clubdirectory\/\" title=\"ClubDirectory\u2122\">ClubDirectory\u2122<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tDesigning MemberPress Profiles\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/es"},{"label":"Add-ons","link":"https:\/\/memberpress.com\/es\/doc-categories\/add-ons\/"},{"label":"Community","link":"https:\/\/memberpress.com\/es\/doc-categories\/community\/"},{"label":"ClubSuite\u2122","link":"https:\/\/memberpress.com\/es\/doc-categories\/clubsuite\/"},{"label":"ClubDirectory\u2122","link":"https:\/\/memberpress.com\/es\/doc-categories\/clubdirectory\/"},{"label":"Designing MemberPress Profiles","link":"https:\/\/memberpress.com\/es\/docs\/designing-member-profiles\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/76458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/comments?post=76458"}],"version-history":[{"count":3,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/76458\/revisions"}],"predecessor-version":[{"id":76585,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb\/76458\/revisions\/76585"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/media?parent=76458"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb-category?post=76458"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/es\/wp-json\/wp\/v2\/ht-kb-tag?post=76458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}