{"id":1398,"count":2,"description":"","link":"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/","name":"Paiements et abonnements","slug":"payments-and-subscriptions","taxonomy":"ht_kb_category","parent":1327,"meta":[],"acf":[],"term_order":"2","default_preview":"","meta_image":"","attachment_thumb":"","thumbnail_url":"","meta_svg":"","meta_svg_color":"","custom_link":"","meta_color":"","restrict_access":"","category_thumbnail":"","padded_count":2,"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Payments and Subscriptions | MemberPress\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Payments and Subscriptions | MemberPress\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/ht-kb-category\\\/1398\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/advanced-topics\\\/#listItem\",\"name\":\"Advanced Topics\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/advanced-topics\\\/#listItem\",\"position\":2,\"name\":\"Advanced Topics\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/advanced-topics\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/custom-codes\\\/#listItem\",\"name\":\"Custom Codes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/custom-codes\\\/#listItem\",\"position\":3,\"name\":\"Custom Codes\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/custom-codes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/payments-and-subscriptions\\\/#listItem\",\"name\":\"Payments and Subscriptions\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/advanced-topics\\\/#listItem\",\"name\":\"Advanced Topics\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/payments-and-subscriptions\\\/#listItem\",\"position\":4,\"name\":\"Payments and Subscriptions\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/custom-codes\\\/#listItem\",\"name\":\"Custom Codes\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/ht-kb-category\\\/1398\\\/#collectionpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/ht-kb-category\\\/1398\\\/\",\"name\":\"Payments and Subscriptions | MemberPress\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/ht-kb-category\\\/1398\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/ht-kb-category\\\/1398\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/ht-kb-category\\\/1398\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Payments and Subscriptions | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Paiements et abonnements | MemberPress","description":"","canonical_url":"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category\/1398\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/#listItem","name":"Advanced Topics"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/#listItem","position":2,"name":"Advanced Topics","item":"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/#listItem","name":"Custom Codes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/#listItem","position":3,"name":"Custom Codes","item":"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/#listItem","name":"Payments and Subscriptions"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/#listItem","name":"Advanced Topics"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/#listItem","position":4,"name":"Payments and Subscriptions","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/#listItem","name":"Custom Codes"}}]},{"@type":"CollectionPage","@id":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category\/1398\/#collectionpage","url":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category\/1398\/","name":"Payments and Subscriptions | MemberPress","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category\/1398\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/memberpress.com\/fr\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category\/1398\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category\/1398\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/fr\/#website","url":"https:\/\/memberpress.com\/fr\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"MemberPress","og:type":"article","og:title":"Payments and Subscriptions | MemberPress","og:url":"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Payments and Subscriptions | MemberPress","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"term_id":"1398","title":null,"description":null,"keywords":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-08-20 22:58:42","breadcrumb_settings":null,"created":"2024-02-27 14:14:15","updated":"2026-04-02 13:49:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/\" title=\"Advanced Topics\">Advanced Topics<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/\" title=\"Custom Codes\">Custom Codes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tPayments and Subscriptions\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/fr"},{"label":"Advanced Topics","link":"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/"},{"label":"Custom Codes","link":"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/"},{"label":"Payments and Subscriptions","link":"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category\/1398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category"}],"about":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/taxonomies\/ht_kb_category"}],"up":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category\/1327"}],"wp:post_type":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb?ht-kb-category=1398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}