{"id":61386,"date":"2024-02-13T07:23:29","date_gmt":"2024-02-13T12:23:29","guid":{"rendered":"https:\/\/memberpress.com\/docs\/protecting-files\/"},"modified":"2026-01-27T08:01:03","modified_gmt":"2026-01-27T13:01:03","slug":"protecting-files","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/","title":{"rendered":"Protection des fichiers"},"content":{"rendered":"<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\"><strong>Note<\/strong>: Bien que ces instructions soient toujours valables, nous avons depuis publi\u00e9 le module compl\u00e9mentaire de t\u00e9l\u00e9chargement MemberPress qui est un moyen beaucoup plus facile de t\u00e9l\u00e9charger et de prot\u00e9ger vos fichiers.  <a href=\"https:\/\/memberpress.com\/fr\/docs\/mp-downloads-add-on\/\">Cliquez ici pour en savoir plus<\/a>. <\/p>\n\n\n\n<div class=\"callout\">\n<p id=\"top\"><strong><u> Couvert dans cet article :<\/u><\/strong><\/p>\n<ul>\n<li><a href=\"#file-types\">Quels types de fichiers MemberPress peut-il prot\u00e9ger ?<\/a><\/li>\n<li><a href=\"#example\">Protection d'un seul fichier<\/a><\/li>\n<li><a href=\"#mulitple\">Protection de plusieurs fichiers<\/a><\/li>\n<li><a href=\"#ftp\">Protection de plusieurs fichiers avec FTP<\/a><\/li>\n<li><a href=\"#expressions\">Utilisation d'expressions r\u00e9guli\u00e8res<\/a><\/li>\n<li><a href=\"#reqs\">Exigences techniques<\/a><\/li>\n<li><a href=\"#add_types\">Prot\u00e9ger des types de fichiers suppl\u00e9mentaires<\/a><\/li>\n<\/ul>\n<\/div>\n\n\n\n<p>MemberPress dispose de fonctions puissantes pour vous aider \u00e0 prot\u00e9ger les fichiers statiques. La protection des fichiers de MemberPress fonctionne au niveau du serveur web, ce qui assure une protection absolue de chaque fichier. Par exemple, m\u00eame si une personne n'ayant pas acc\u00e8s \u00e0 un fichier parvenait \u00e0 obtenir un lien direct vers celui-ci, MemberPress l'arr\u00eaterait dans son \u00e9lan et lui demanderait de s'enregistrer ou de se connecter (si elle s'est d\u00e9j\u00e0 enregistr\u00e9e) avant de l'autoriser \u00e0 t\u00e9l\u00e9charger ce fichier.<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-danger\"> <strong>Remarque :<\/strong> Cette forme de protection des fichiers n\u00e9cessite que votre serveur utilise et autorise l'acc\u00e8s aux fichiers .htaccess. Certains serveurs, en particulier les serveurs Ngnix, ne le font pas. Si ces \u00e9tapes ne fonctionnent pas sur votre site, il se peut que vous deviez utiliser notre outil <a href=\"https:\/\/memberpress.com\/fr\/docs\/mp-downloads-add-on\/\">T\u00e9l\u00e9chargements Add-On<\/a> pour prot\u00e9ger les fichiers.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"file-types\">Quels types de fichiers MemberPress peut-il prot\u00e9ger ?<\/h2>\n\n\n\n<p>MemberPress peut prot\u00e9ger tout fichier qui n'est pas n\u00e9cessaire au bon fonctionnement de votre site web.<\/p>\n\n\n\n<p>Par cons\u00e9quent, MemberPress peut <em><strong>seulement\u00a0<\/strong><\/em>prot\u00e8ge les types de fichiers suivants :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">zip', 'gz', 'tar', 'rar', 'doc', 'docx', 'xls', 'xlsx', 'xlsm', 'pdf', 'mp4', 'm4v', 'mp3', 'ts', 'key', 'm3u8'<\/pre>\n\n\n\n<p>Si vous souhaitez prot\u00e9ger un type de fichier qui ne figure pas dans la liste ci-dessus, nous vous recommandons de le zipper et de prot\u00e9ger un seul fichier .zip.<\/p>\n\n\n\n<p>De plus, vous pouvez ajouter du code personnalis\u00e9 au fichier functions.php de votre th\u00e8me, si vous en avez un, ou \u00e0 un plugin.<br><a href=\"https:\/\/wordpress.org\/plugins\/insert-headers-and-footers\/\">WPCode<\/a> (veuillez consulter cet article pour plus de d\u00e9tails) : <a href=\"https:\/\/memberpress.com\/fr\/docs\/how-to-add-custom-code-snippets-in-wpcode\/\">Comment ajouter des extraits de code personnalis\u00e9s dans WPCode ?<\/a>). Voici un exemple de ce code :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">function add_types_protectable($types, $rules) {\n  $types[] = 'csv' ;\n  return $types ;\n}\nadd_filter('mepr_rewrite_rules_protect_types', 'add_types_protectable', 11, 2) ;<\/pre>\n\n\n\n<p>Apr\u00e8s avoir ajout\u00e9 ce code personnalis\u00e9, vous devrez actualiser vos permaliens WordPress en vous rendant dans votre tableau de bord WordPress &gt; Param\u00e8tres &gt; Permaliens &gt; et en cliquant simplement sur le bouton \u2018 Enregistrer les modifications ' en bas de cette page.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\"><strong>Remarque : <\/strong>nous ne recommandons pas de prot\u00e9ger les fichiers PHP, HTML, images, javascript, css, polices de caract\u00e8res ou d'autres fichiers de site web fr\u00e9quemment consult\u00e9s, car cela nuirait aux performances.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Retour en haut de la page<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"custom-uri-rules\"><a href=\"#custom-uri-rules\" title=\"\">Explication des r\u00e8gles d'URI personnalis\u00e9es de MemberPress<\/a><\/h2>\n\n\n\n<p>Les r\u00e8gles URI personnalis\u00e9es comblent les lacunes des r\u00e8gles standard, garantissant ainsi une protection compl\u00e8te du contenu sur l'ensemble de votre site.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"snhfC\"><div class=\"responsive-video\"><iframe title=\"Quand utiliser les r\u00e8gles d&#039;URI personnalis\u00e9es dans MemberPress (et comment les cr\u00e9er)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/wDoQl7CWR8A?feature=oembed&enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/span>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Cas d'utilisation courants<\/h3>\n\n\n\n<p><strong><a href=\"https:\/\/memberpress.com\/fr\/docs\/rules-overview\/#custom-uri-rules\" target=\"_blank\" rel=\"noopener\" title=\"\">R\u00e8gles d'URI personnalis\u00e9es<\/a><\/strong> prot\u00e8gent le contenu que les r\u00e8gles standard de MemberPress ne peuvent pas atteindre. Contrairement aux r\u00e8gles normales qui fonctionnent \u00e0 travers le traitement du contenu de WordPress, les r\u00e8gles Custom URI prot\u00e8gent les URL directement au niveau du serveur.<\/p>\n\n\n\n<p><strong>1. Pages sp\u00e9ciales de WordPress<\/strong><\/p>\n\n\n\n<p>Les r\u00e8gles de page standard n'affectent pas les pages sp\u00e9ciales telles que la page d'accueil, la page des articles, les archives des cat\u00e9gories ou les pages d'archives. Utilisez les r\u00e8gles d'URI personnalis\u00e9es pour prot\u00e9ger ces zones en ciblant leurs URL sp\u00e9cifiques.<\/p>\n\n\n\n<p><strong>2. Contenu du constructeur de pages<\/strong><\/p>\n\n\n\n<p>Les r\u00e8gles standard MemberPress ne prot\u00e8gent que le contenu ajout\u00e9 par l'interm\u00e9diaire de la fonction de contenu de WordPress (la fonction <strong><code>le_contenu()<\/code><\/strong> ). De nombreux constructeurs de pages et th\u00e8mes rendent leur contenu en dehors de cette fonction. <\/p>\n\n\n\n<p>Par cons\u00e9quent, le contenu rendu de cette mani\u00e8re ne sera pas prot\u00e9g\u00e9 lorsque les r\u00e8gles MemberPress standard seront appliqu\u00e9es. En revanche, vous pouvez utiliser les r\u00e8gles URI personnalis\u00e9es pour prot\u00e9ger l'ensemble de la page ou de l'article.<\/p>\n\n\n\n<p><strong>3. Protection des r\u00e9pertoires<\/strong><\/p>\n\n\n\n<p>Vous pouvez \u00e9galement prot\u00e9ger efficacement plusieurs fichiers en ciblant des r\u00e9pertoires entiers \u00e0 l'aide d'une seule r\u00e8gle utilisant des caract\u00e8res g\u00e9n\u00e9riques (par ex, <code>\/downloads\/*<\/code>).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"example\"><a href=\"#example\" title=\"\">Protection d'un seul fichier<\/a><\/h2>\n\n\n\n<p>Si vous n'avez qu'un seul fichier \u00e0 prot\u00e9ger, voici comment proc\u00e9der :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>T\u00e9l\u00e9chargez le fichier \u00e0 l'aide du Media Uploader de WordPress.<\/li>\n\n\n\n<li>Cr\u00e9ez une r\u00e8gle URI personnalis\u00e9e pour prot\u00e9ger le fichier.<\/li>\n<\/ol>\n\n\n\n<p>Supposons que le fichier que vous avez t\u00e9l\u00e9charg\u00e9 ait l'URL suivante :<br><a href=\"http:\/\/example.com\/wp-content\/uploads\/2015\/10\/report.pdf\">http:\/\/example.com\/wp-content\/uploads\/2015\/10\/report.pdf<\/a><\/p>\n\n\n\n<p>La r\u00e8gle que vous cr\u00e9eriez pour ce fichier serait un type d'URI personnalis\u00e9 pointant uniquement sur le chemin d'acc\u00e8s (partie apr\u00e8s<br><a href=\"http:\/\/example.com\">http:\/\/example.com<\/a>) dans le fichier. Ainsi, dans la zone de texte de cette r\u00e8gle, vous devez taper ce qui suit :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">\/wp-content\/uploads\/2014\/12\/report.pdf<\/pre>\n\n\n\n<p>Bien qu'il s'agisse d'un processus relativement simple pour un petit nombre de fichiers, il peut prendre beaucoup de temps s'il est appliqu\u00e9 \u00e0 un plus grand nombre de fichiers. Voyons donc comment cr\u00e9er une r\u00e8gle pour prot\u00e9ger plusieurs fichiers.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Retour en haut de la page<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"mulitple\"><a href=\"#mulitple\" title=\"\">Fichiers multiples<\/a><\/h2>\n\n\n\n<p>Supposons maintenant que vous ayez 10 fichiers et que vous souhaitiez que le m\u00eame niveau d'adh\u00e9sion donne acc\u00e8s \u00e0 chacun d'entre eux.<\/p>\n\n\n\n<p>L'id\u00e9e est de placer chaque fichier dans un dossier sp\u00e9cial par FTP (recommand\u00e9), ou de s'assurer que chaque fichier t\u00e9l\u00e9charg\u00e9 via le Media Uploader a un pr\u00e9fixe commun (non recommand\u00e9, sauf si le FTP n'est pas une option).<\/p>\n\n\n\n<p>Bien que nous ne recommandions pas de prot\u00e9ger plusieurs fichiers t\u00e9l\u00e9charg\u00e9s \u00e0 l'aide du Media Uploader de WordPress, nous comprenons qu'il peut y avoir des cas o\u00f9 vous voulez\/devez le faire. Par cons\u00e9quent, si vous t\u00e9l\u00e9chargez ces fichiers via le Media Uploader, ils auront les URL suivantes :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">http:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_report.pdf\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_report.doc\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_report.docx\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_analysis.pdf\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_analysis.doc\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_analysis.docx\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_groupings.pdf\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_groupings.doc\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_groupings.docx\nhttp:\/\/example.com\/wp-content\/uploads\/2015\/10\/bronze_archive.zip<\/pre>\n\n\n\n<p>Il ne vous reste plus qu'\u00e0 cr\u00e9er une r\u00e8gle de type Custom URI avec ce chemin d'acc\u00e8s :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">\/wp-content\/uploads\/2015\/10\/bronze_<\/pre>\n\n\n\n<p>Cela prot\u00e9gera tous les fichiers du dossier \/wp-content\/uploads\/2015\/10\/ dont le nom commence par \u201c bronze_ \u201d.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Retour en haut de la page<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ftp\">Fichiers multiples avec FTP<\/h2>\n\n\n\n<p>FTP\/SFTP est un moyen robuste de transf\u00e9rer des fichiers de votre ordinateur local vers votre site web. La plupart des h\u00e9bergeurs fournissent des services FTP gratuits afin que vous puissiez acc\u00e9der aux fichiers de votre site \u00e0 distance depuis votre propre ordinateur. La disponibilit\u00e9 du FTP peut varier d'un h\u00e9bergeur \u00e0 l'autre et les exigences peuvent \u00eatre diff\u00e9rentes. <\/p>\n\n\n\n<p>En r\u00e8gle g\u00e9n\u00e9rale, vous aurez besoin d'un client FTP tel que <a href=\"https:\/\/filezilla-project.org\/\" title=\"Filezilla\">FileZilla<\/a> ou <a href=\"http:\/\/cyberduck.io\/\" title=\"Cyberduck\">Cyberduck<\/a> pour vous connecter \u00e0 votre serveur via FTP\/SFTP. Cela vous permettra d'acc\u00e9der au syst\u00e8me de fichiers de votre serveur web pour cr\u00e9er des dossiers et t\u00e9l\u00e9charger des fichiers de la m\u00eame mani\u00e8re que vous copieriez des fichiers entre des dossiers sur votre ordinateur local.<\/p>\n\n\n\n<p>Dans cet exemple, nous utiliserons le FTP pour cr\u00e9er un dossier nomm\u00e9 protected et y importer nos fichiers, ce qui nous donnera les URL suivantes :<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-danger\"><strong>Remarque :<\/strong>\u00a0Les r\u00e8gles d'URI personnalis\u00e9es ne fonctionneront pas pour les fichiers si votre site fonctionne sur<strong> Serveurs Nginx<\/strong>. Si vous cr\u00e9ez le dossier sous wp-content\/uploads, les r\u00e8gles URI peuvent fonctionner pour vous. Nous recommandons d'utiliser l'\u00e9l\u00e9ment <a href=\"https:\/\/memberpress.com\/fr\/docs\/mp-downloads-add-on\/\">MemberPress Add-on pour les t\u00e9l\u00e9chargements<\/a> pour prot\u00e9ger les fichiers sur les serveurs Ngnix.\u00a0<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">http:\/\/example.com\/protected\/report.pdf\nhttp:\/\/example.com\/protected\/report.doc\nhttp:\/\/example.com\/protected\/report.docx\nhttp:\/\/example.com\/protected\/analysis.pdf\nhttp:\/\/example.com\/protected\/analysis.doc\nhttp:\/\/example.com\/protected\/analysis.docx\nhttp:\/\/example.com\/protected\/groupings.pdf\nhttp:\/\/example.com\/protected\/groupings.doc\nhttp:\/\/example.com\/protected\/groupings.docx\nhttp:\/\/example.com\/protected\/archive.zip<\/pre>\n\n\n\n<p>Ce sc\u00e9nario peut \u00eatre sup\u00e9rieur \u00e0 l'utilisation du Media Uploader de WordPress si vous pr\u00e9voyez d'ajouter des fichiers \u00e0 votre dossier ult\u00e9rieurement, car le Media Uploader de WordPress place parfois les fichiers t\u00e9l\u00e9charg\u00e9s \u00e0 des moments diff\u00e9rents dans des dossiers diff\u00e9rents.<\/p>\n\n\n\n<p>Dans cet exemple, il suffit donc de cr\u00e9er une r\u00e8gle de type URI personnalis\u00e9 avec le chemin d'acc\u00e8s suivant (saisi dans la zone de texte de la r\u00e8gle) :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">\/prot\u00e9g\u00e9\/<\/pre>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-danger\">\n\t<strong>Remarque :<\/strong> Si cela ne fonctionne pas et que vous \u00eates sur un serveur Apache. Assurez-vous que les r\u00e8gles de r\u00e9\u00e9criture MemberPress n'ont pas \u00e9t\u00e9 d\u00e9sactiv\u00e9es en allant sur <strong>MemberPress-&gt;Param\u00e8tres-&gt;G\u00e9n\u00e9ral<\/strong> et en d\u00e9cochant la case <strong>\u201c D\u00e9sactiver les r\u00e8gles de r\u00e9\u00e9criture \u201d<\/strong> puis enregistrer les modifications.<\/p>\n\n\n\n<p>Voyons maintenant comment utiliser une correspondance plus avanc\u00e9e avec les expressions r\u00e9guli\u00e8res.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Retour en haut de la page<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"expressions\">Expressions r\u00e9guli\u00e8res<\/h2>\n\n\n\n<p><a title=\"Expressions r\u00e9guli\u00e8res\" href=\"https:\/\/memberpress.com\/fr\/how-to-become-a-regular-expression-power-user\/\" target=\"_blank\" rel=\"noopener\">Expressions r\u00e9guli\u00e8res<\/a> est une syntaxe de recherche unique et descriptive couramment utilis\u00e9e dans tous les langages de programmation modernes pour s\u00e9lectionner et traiter du texte. Il vous permettra de prot\u00e9ger facilement des groupes de fichiers tr\u00e8s sp\u00e9cifiques.<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\">Remarque : les expressions r\u00e9guli\u00e8res sont \u00e0 utiliser de pr\u00e9f\u00e9rence dans les cas o\u00f9 vous devez prot\u00e9ger plusieurs URL \u00e0 la fois.<\/p>\n\n\n\n<p>L'id\u00e9e est ici de vous permettre de faire correspondre des motifs dans un URL donn\u00e9 et de prot\u00e9ger l'URL s'il correspond \u00e0 l'une de vos r\u00e8gles de type URI personnalis\u00e9 avec expression r\u00e9guli\u00e8re activ\u00e9e.<\/p>\n\n\n\n<p>Par exemple, dans l'exemple FTP ci-dessus, si vous souhaitez autoriser certains utilisateurs \u00e0 acc\u00e9der uniquement aux fichiers PDF et d'autres \u00e0 acc\u00e9der \u00e0 vos fichiers PDF, doc, docx et zip, vous pouvez cr\u00e9er deux r\u00e8gles d'expression r\u00e9guli\u00e8re diff\u00e9rentes : la premi\u00e8re pour un niveau d'adh\u00e9sion et la seconde pour un autre.<\/p>\n\n\n\n<p>La premi\u00e8re r\u00e8gle de votre premier niveau d'adh\u00e9sion aurait un chemin d'acc\u00e8s similaire :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">^\/protected\/.*\\.pdf\n<\/pre>\n\n\n\n<p>La deuxi\u00e8me r\u00e8gle pour votre autre niveau d'adh\u00e9sion aurait un chemin d'acc\u00e8s de quelque chose comme :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">^\/protected\/.*\\.(pdf|doc|docx|zip)\n<\/pre>\n\n\n\n<p>Il est vrai que les expressions r\u00e9guli\u00e8res peuvent \u00eatre difficiles \u00e0 ma\u00eetriser, mais elles peuvent offrir de puissantes possibilit\u00e9s de correspondance et de protection des fichiers dans les r\u00e8gles de type URI personnalis\u00e9es de MemberPress. Nous avons constat\u00e9 que les<br><a href=\"http:\/\/www.regular-expressions.info\/\">http:\/\/www.regular-expressions.info\/<\/a> est une bonne ressource pour tous ceux qui souhaitent comprendre cette technologie puissante. De plus, si vous avez des besoins plus complexes, notre \u00e9quipe d'assistance est tr\u00e8s comp\u00e9tente pour trouver les expressions r\u00e9guli\u00e8res adapt\u00e9es \u00e0 tout ce que vous devez prot\u00e9ger. N'h\u00e9sitez donc pas \u00e0 envoyer une demande. <a class=\"heroickb_exit_link\" href=\"?hkb-redirect&nonce=f4b61b2770&check=6jvcs&redirect=https%3A%2F%2Fmemberpress.com%2Fsupport%2F&otype=unknown&oid=0&source=block-content\" title=\"Demande de soutien Premium\">demande de soutien<\/a> si vous avez besoin d'aide avec cette fonction.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Retour en haut de la page<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Exigences techniques<\/h2>\n\n\n\n<p>Comme cette fonction utilise le serveur web sous-jacent de votre site pour prot\u00e9ger les fichiers, il y a certaines exigences techniques qui doivent \u00eatre respect\u00e9es pour que cette fonction fonctionne correctement. Nous avons \u00e9crit MemberPress pour qu'il fonctionne avec les configurations de serveur les plus courantes, mais si les choses ne fonctionnent pas parfaitement pour vous, voici quelques points \u00e0 v\u00e9rifier :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Votre site web doit \u00eatre h\u00e9berg\u00e9 par Apache ou un serveur web compatible avec Apache, tel que Litespeed. Les r\u00e8gles de r\u00e9\u00e9criture install\u00e9es par MemberPress sont sp\u00e9cifiques \u00e0 Apache. Si vous n'\u00eates pas s\u00fbr du serveur web que vous utilisez, il s'agit probablement d'Apache, mais pour en \u00eatre certain, vous pouvez contacter votre h\u00e9bergeur web. MemberPress ne prend pas en charge la protection des fichiers sur d'autres serveurs web tels que Nginx, IIS ou d'autres serveurs non bas\u00e9s sur Apache. Toutefois, si votre serveur web utilise Nginx comme proxy (devant Apache), vous pouvez utiliser le code de contournement du proxy Nginx d\u00e9crit dans la section Nginx sur <a href=\"http:\/\/docs.memberpress.com\/article\/179-understanding-rewrite-rules\" target=\"_blank\" rel=\"noopener\">cette page<\/a>.<\/li>\n\n\n\n<li>Votre installation WordPress doit disposer des privil\u00e8ges suffisants pour apporter des modifications \u00e0 votre fichier .htaccess. Si votre fichier .htaccess n'est pas accessible en \u00e9criture par WordPress, vous pouvez le modifier manuellement en suivant nos instructions. <a title=\"Instructions de r\u00e9\u00e9criture\" href=\"http:\/\/docs.memberpress.com\/article\/179-understanding-rewrite-rules\" target=\"_blank\" rel=\"noopener\">instructions de r\u00e9\u00e9criture avanc\u00e9es<\/a>.<\/li>\n\n\n\n<li>Votre installation WordPress doit pouvoir \u00e9crire des fichiers dans le dossier \/wp-content\/uploads. C'est \u00e9galement une condition pour que le WordPress Media Uploader puisse t\u00e9l\u00e9charger des fichiers, donc si cela fonctionne, cela devrait \u00e9galement fonctionner.<\/li>\n\n\n\n<li>Cloudflare et d'autres CDN ainsi que la mise en cache peuvent potentiellement entraver la protection des fichiers. En effet, soit ils mettent le fichier en cache de sorte qu'il ne peut pas \u00eatre prot\u00e9g\u00e9, soit ils interf\u00e8rent avec nos cookies de protection et provoquent des boucles de redirection infinies. <\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\"><strong>Remarque : <\/strong>Pour cette raison, si vous rencontrez des probl\u00e8mes avec la protection des fichiers, vous devez d\u00e9sactiver tout CDN et mise en cache pour voir si cela peut \u00eatre une cause possible. <em>avant <\/em>en contactant notre service d'assistance.<\/p>\n\n\n\n<ol start=\"5\" class=\"wp-block-list\">\n<li>Les r\u00e8gles de r\u00e9\u00e9criture MemberPress doivent \u00eatre activ\u00e9es. Allez dans MemberPress-&gt;Param\u00e8tres-&gt;G\u00e9n\u00e9ral, d\u00e9cochez la case \u201c D\u00e9sactiver les r\u00e8gles de r\u00e9\u00e9criture \u201d et enregistrez les modifications.<\/li>\n<\/ol>\n\n\n\n<p>Nous avons \u00e9galement vu des utilisateurs dont les r\u00e8gles de r\u00e9\u00e9criture personnalis\u00e9es interf\u00e9raient avec les r\u00e8gles de r\u00e9\u00e9criture de MemberPress. Donc, si cette fonctionnalit\u00e9 ne semble pas fonctionner et que vous avez l'impression d'avoir suivi toutes ces \u00e9tapes, veuillez contacter notre \u00e9quipe de <a class=\"heroickb_exit_link\" href=\"?hkb-redirect&nonce=f4b61b2770&check=6jvcs&redirect=https%3A%2F%2Fmemberpress.com%2Fsupport%2F&otype=unknown&oid=0&source=block-content\" title=\"Demande de soutien Premium\">\u00e9quipe de soutien<\/a> et nous vous aiderons.<\/p>\n\n\n\n<p><a class=\"callout dashed\" href=\"#top\">Retour en haut de la page<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"add_types\">Prot\u00e9ger des types de fichiers suppl\u00e9mentaires<\/h2>\n\n\n\n<p>MemberPress peut prot\u00e9ger des types de fichiers suppl\u00e9mentaires. Gardez \u00e0 l'esprit que chaque requ\u00eate HTTP d'un type de fichier prot\u00e9geable entra\u00eenera une deuxi\u00e8me requ\u00eate au site pour v\u00e9rifier si le fichier est prot\u00e9g\u00e9 ou non. Pour cette raison, nous ne recommandons pas de prot\u00e9ger les fichiers tels que les images (jpg, png, gif, etc.), les scripts (css, js) ou les fichiers de police, car cela pourrait entra\u00eener une charge importante pour votre serveur. <\/p>\n\n\n\n<p>Utilisez le code personnalis\u00e9 suivant dans un plugin tel que le <a href=\"https:\/\/wordpress.org\/plugins\/insert-headers-and-footers\/\">WPCode<\/a> pour ajouter des types de fichiers suppl\u00e9mentaires. Veuillez consulter cet article pour plus de d\u00e9tails : <a href=\"https:\/\/memberpress.com\/fr\/docs\/how-to-add-custom-code-snippets-in-wpcode\/\">Comment ajouter des extraits de code personnalis\u00e9s dans WPCode ?<\/a>.<\/p>\n\n\n\n<p>Le code ci-dessous ajoute les types de fichiers \u201c html \u201d et \u201c htm \u201d \u00e0 la liste des fichiers prot\u00e9g\u00e9s. Une fois ce code ajout\u00e9, vous devrez \u00e9galement actualiser les param\u00e8tres de permaliens WordPress afin de forcer WordPress \u00e0 mettre \u00e0 jour le fichier .htaccess de votre site.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">function add_types_protectable($types, $rules) {\n  $types[] = 'htm' ;\n  $types[] = 'html' ;\n  return $types ;\n}\nadd_filter('mepr_rewrite_rules_protect_types', 'add_types_protectable', 11, 2) ;<\/pre>","protected":false},"excerpt":{"rendered":"<p>Covered in this article: What types of files can MemberPress Protect Protecting a Single File Protecting Multiple Files Protecting Multiple Files with FTP Using Regular Expressions Technical Requirements Protect Additional File-Types MemberPress has some powerful features to help you protect static files. MemberPress\u2019s file protection works at the web-server level which provides absolute protection of [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1322],"ht-kb-tag":[],"class_list":{"0":"post-61386","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-protecting-content","7":"entry"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress&#039;s\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Protecting Files | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress&#039;s\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T12:23:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-27T13:01:03+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Protecting Files | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress&#039;s\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/protecting-files\\\/#article\",\"name\":\"Protecting Files | MemberPress\",\"headline\":\"Protecting Files\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#articleImage\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"datePublished\":\"2024-02-13T07:23:29-05:00\",\"dateModified\":\"2026-01-27T08:01:03-05:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/protecting-files\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/protecting-files\\\/#webpage\"},\"articleSection\":\"Protecting Content\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/protecting-files\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/protecting-content\\\/#listItem\",\"name\":\"Protecting Content\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/protecting-content\\\/#listItem\",\"position\":3,\"name\":\"Protecting Content\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/protecting-content\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/protecting-files\\\/#listItem\",\"name\":\"Protecting Files\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/protecting-files\\\/#listItem\",\"position\":4,\"name\":\"Protecting Files\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/protecting-content\\\/#listItem\",\"name\":\"Protecting Content\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/protecting-files\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/protecting-files\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/protecting-files\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/protecting-files\\\/\",\"name\":\"Protecting Files | MemberPress\",\"description\":\"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress's\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/protecting-files\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-02-13T07:23:29-05:00\",\"dateModified\":\"2026-01-27T08:01:03-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Protecting Files | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Protection des fichiers | MemberPress","description":"Note : Bien que ces instructions soient toujours valables, nous avons depuis publi\u00e9 le module compl\u00e9mentaire de t\u00e9l\u00e9chargement MemberPress qui est un moyen beaucoup plus facile de t\u00e9l\u00e9charger et de prot\u00e9ger vos fichiers. Cliquez ici pour en savoir plus. Cas d'utilisation courants Les r\u00e8gles URI personnalis\u00e9es prot\u00e8gent le contenu que les r\u00e8gles MemberPress standard ne peuvent pas atteindre. Contrairement aux r\u00e8gles normales qui fonctionnent \u00e0 travers le syst\u00e8me","canonical_url":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/#article","name":"Protecting Files | MemberPress","headline":"Protecting Files","author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/fr\/#articleImage","width":1650,"height":1275,"caption":"memberpress logo icon"},"datePublished":"2024-02-13T07:23:29-05:00","dateModified":"2026-01-27T08:01:03-05:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/#webpage"},"articleSection":"Protecting Content"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","position":2,"name":"General","item":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/protecting-content\/#listItem","name":"Protecting Content"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/protecting-content\/#listItem","position":3,"name":"Protecting Content","item":"https:\/\/memberpress.com\/fr\/doc-categories\/protecting-content\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/#listItem","name":"Protecting Files"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/#listItem","position":4,"name":"Protecting Files","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/protecting-content\/#listItem","name":"Protecting Content"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/fr\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/#webpage","url":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/","name":"Protecting Files | MemberPress","description":"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress's","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-02-13T07:23:29-05:00","dateModified":"2026-01-27T08:01:03-05:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/fr\/#website","url":"https:\/\/memberpress.com\/fr\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"MemberPress","og:type":"article","og:title":"Protecting Files | MemberPress","og:description":"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress's","og:url":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-02-13T12:23:29+00:00","article:modified_time":"2026-01-27T13:01:03+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Protecting Files | MemberPress","twitter:description":"Note: Though these instructions are still valid, we have since released the MemberPress Downloads Add-on which is a much easier way of uploading and protecting your files. Click here to read more about it. Common Use Cases Custom URI rules protect content that standard MemberPress rules cannot reach. Unlike regular rules that work through WordPress's","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"61386","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-01-27 13:02:24","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-02-13 12:23:29","updated":"2026-03-03 14:53:49"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/general\/\" title=\"General\">General<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/protecting-content\/\" title=\"Protecting Content\">Protecting Content<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tProtecting Files\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/fr"},{"label":"General","link":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/"},{"label":"Protecting Content","link":"https:\/\/memberpress.com\/fr\/doc-categories\/protecting-content\/"},{"label":"Protecting Files","link":"https:\/\/memberpress.com\/fr\/docs\/protecting-files\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/61386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/comments?post=61386"}],"version-history":[{"count":4,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/61386\/revisions"}],"predecessor-version":[{"id":78770,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/61386\/revisions\/78770"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/media?parent=61386"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category?post=61386"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-tag?post=61386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}