{"id":61553,"date":"2024-02-13T07:39:46","date_gmt":"2024-02-13T12:39:46","guid":{"rendered":"https:\/\/memberpress.com\/docs\/pausing-subscriptions\/"},"modified":"2025-06-04T03:50:36","modified_gmt":"2025-06-04T07:50:36","slug":"pausing-subscriptions","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/","title":{"rendered":"Mise en pause des abonnements"},"content":{"rendered":"<div class=\"callout\">\n<p><strong><u>Couvert dans cet article :<\/u><\/strong><\/p>\n<ul>\n<li><a href=\"#admin\">Pause et reprise en tant qu'administrateur<\/a><\/li>\n<li><a href=\"#user\">Pause et reprise en tant qu'abonn\u00e9<\/a><\/li>\n<li><a href=\"#consids\">Consid\u00e9rations sp\u00e9ciales relatives \u00e0 la passerelle lors de la reprise des abonnements<\/a><\/li>\n<li><a href=\"#note\">Note importante concernant le contenu des gouttes<\/a><\/li>\n<\/ul>\n<\/div>\n\n\n\n<p>MemberPress vous permet, en tant qu'administrateur ou en tant qu'utilisateur final (si vous leur en donnez la possibilit\u00e9), de mettre en pause tout abonnement r\u00e9current automatique pris en charge. L'objectif de la mise en pause est d'\u00e9viter un paiement futur sur un abonnement r\u00e9current tout en \u00e9tant en mesure de reprendre les paiements \u00e0 une date ult\u00e9rieure (au lieu de s'inscrire \u00e0 nouveau comme cela aurait \u00e9t\u00e9 n\u00e9cessaire si l'utilisateur avait annul\u00e9). C'est pour cette raison que les abonnements \u00e0 paiement unique <em>ne peut pas <\/em>sont interrompus ou annul\u00e9s, car ils n'ont pas de paiements automatiques \u00e0 \u00e9viter \u00e0 l'avenir.\u00a0<\/p>\n\n\n\n<p>Maintenant que nous avons compris pourquoi la mise en pause est utilis\u00e9e et ce qu'elle fait, voyons comment vous, en tant qu'administrateur, et vos utilisateurs pouvez mettre en pause les abonnements et les reprendre plus tard.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"admin\">Pause et reprise en tant qu'administrateur<\/h2>\n\n\n\n<p>Lorsque vous \u00eates connect\u00e9 en tant qu'administrateur \u00e0 votre tableau de bord WordPress, vous pouvez suivre ces \u00e9tapes de base pour mettre en pause tout abonnement r\u00e9current automatique pris en charge :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Naviguez jusqu'\u00e0 la page WordPress Dashboard &gt; MemberPress &gt; Subscriptions.<\/li>\n\n\n\n<li>Assurez-vous que vous \u00eates dans l'onglet \u2018 R\u00e9current '.<\/li>\n\n\n\n<li>Recherchez l'abonnement \u00e0 l'aide de l'outil de recherche sur la page, ou en naviguant.\u00a0<\/li>\n\n\n\n<li>Passez la souris sur l'identifiant unique de l'abonnement dans la colonne \u2018 Abonnement '.<\/li>\n\n\n\n<li>V\u00e9rifiez que vous \u00eates sur le point de mettre en pause le\u00a0<em>correctes\u00a0<\/em>Abonnement.<\/li>\n\n\n\n<li>Cliquez sur le lien \u2018Pause'.<\/li>\n\n\n\n<li>Cliquez sur \u2018OK' dans la fen\u00eatre pop-up apr\u00e8s avoir v\u00e9rifi\u00e9 que vous mettez en pause le bon abonnement.<\/li>\n<\/ol>\n\n\n\n<p>Pour reprendre l'abonnement, il suffit de suivre exactement les m\u00eames \u00e9tapes. Vous remarquerez qu'\u00e0 l'\u00e9tape 6, le lien \u2018Pause' est d\u00e9sormais intitul\u00e9 \u2018Reprendre'.<\/p>\n\n\n\n<p><strong>A noter<\/strong> que depuis l'introduction de SCA\/3DSecure pour les paiements par carte dans l'UE, il se peut que vous obteniez une bo\u00eete de dialogue suppl\u00e9mentaire lors de la reprise d'un abonnement. Elle se pr\u00e9sente comme suit :<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/file-KCgAcb4VBx.png\" alt=\"\"\/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Si cela se produit, cliquez simplement sur le bouton OK. Un e-mail sera envoy\u00e9 au client avec un lien vers la facture h\u00e9berg\u00e9e par Stripe, o\u00f9 il pourra payer en s'authentifiant. Une fois le paiement effectu\u00e9, l'abonnement sera r\u00e9activ\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"user\">Pause et reprise en tant qu'abonn\u00e9<\/h2>\n\n\n\n<p class=\"callout\"><strong>Rappelez-vous :<\/strong> Avant que vos utilisateurs puissent mettre en pause leurs abonnements r\u00e9currents automatiques, vous devez leur permettre de le faire. Pour ce faire, activez l'option \u201cPermettre aux membres de mettre en pause et de reprendre leurs propres abonnements\u201d qui se trouve dans MemberPress &gt; Param\u00e8tres &gt; onglet Compte &gt; section Permissions.<\/p>\n\n\n\n<p>Si cette fonction est activ\u00e9e, les abonn\u00e9s de votre site peuvent interrompre un abonnement r\u00e9current automatique en suivant les \u00e9tapes suivantes :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Connectez-vous \u00e0 la page Compte de votre site (si vous ne connaissez pas cette URL, veuillez vous r\u00e9f\u00e9rer \u00e0 <a href=\"https:\/\/memberpress.com\/fr\/docs\/account-page\/\" target=\"_blank\" rel=\"noopener\">cette page<\/a>).<\/li>\n\n\n\n<li>Acc\u00e9dez \u00e0 l'onglet \u2018Abonnements' de la page Compte.<\/li>\n\n\n\n<li>Recherchez l'abonnement qui doit \u00eatre mis en pause.\u00a0<\/li>\n\n\n\n<li>Cliquez sur le lien \u2018Pause' \u00e0 droite de l'abonnement.\u00a0<\/li>\n\n\n\n<li>Cliquez sur \u2018OK' dans la fen\u00eatre pop-up apr\u00e8s avoir v\u00e9rifi\u00e9 que l'abonnement correct a \u00e9t\u00e9 s\u00e9lectionn\u00e9.<\/li>\n<\/ol>\n\n\n\n<p>Pour reprendre l'abonnement, il suffit de suivre exactement les m\u00eames \u00e9tapes. Vous remarquerez qu'\u00e0 l'\u00e9tape 4, le lien \u2018Pause' est d\u00e9sormais intitul\u00e9 \u2018Reprendre'.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"consids\">Consid\u00e9rations sp\u00e9ciales relatives \u00e0 la passerelle lors de la reprise des abonnements<\/h2>\n\n\n\n<p>Les consid\u00e9rations suivantes sont propres aux passerelles suivantes de MemberPress lorsqu'il s'agit de reprendre l'abonnement.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rayure<\/h3>\n\n\n\n<p>Avec ces passerelles, lorsqu'un utilisateur reprend <em>avant<\/em>\u00a0si la transaction en cours a expir\u00e9, il sera factur\u00e9 \u00e0 nouveau le jour m\u00eame de la mise en place initiale de son abonnement et ne subira aucune interruption d'acc\u00e8s. Toutefois, si l'utilisateur reprend <em>apr\u00e8s<\/em>\u00a0la transaction en cours expire, il sera factur\u00e9 imm\u00e9diatement ce jour-l\u00e0 et toutes les facturations futures auront lieu ce nouveau jour (l'utilisateur subira une interruption d'acc\u00e8s s'il reprend ses activit\u00e9s apr\u00e8s l'expiration de sa derni\u00e8re transaction).\u00a0<\/p>\n\n\n\n<p>Par exemple, si je mets mon abonnement mensuel en pause le 15, qu'il est normalement factur\u00e9 le 1er du mois et que je le reprends le 20, je serai \u00e0 nouveau factur\u00e9 le 1er. Mais si je reprends le 3 du mois suivant, je serai factur\u00e9 ce jour-l\u00e0, et ma nouvelle date de facturation sera le 3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">PayPal<\/h3>\n\n\n\n<p>Nous ne recommandons pas d'activer la fonction Pause\/Reprise pour les abonnements PayPal, car lorsqu'un utilisateur reprend son abonnement, il est contraint de conserver la m\u00eame date de facturation que celle \u00e0 laquelle il s'est inscrit \u00e0 l'origine.\u00a0<\/p>\n\n\n\n<p>Par exemple, si l'abonnement est mensuel et que l'utilisateur l'a achet\u00e9 le 1er, l'a interrompu le 15 du mois et l'a repris le 3, son abonnement ne sera pas renouvel\u00e9 avant le 1er du mois suivant. Le r\u00e9sultat sera plus long si la dur\u00e9e de facturation est plus longue, comme dans le cas d'un abonnement annuel. C'est pourquoi nous encourageons vivement nos utilisateurs \u00e0 d\u00e9sactiver la possibilit\u00e9 d'interrompre et de reprendre les abonnements r\u00e9currents dans leurs <strong>MemberPress\u00a0<\/strong>>\u00a0<strong>Param\u00e8tres<\/strong>\u00a0>\u00a0<strong>Compte\u00a0<\/strong>en laissant l'onglet\u00a0<strong>Permettre aux membres d'interrompre et de reprendre leurs propres abonnements<\/strong>\u00a0option <em style=\"background-color: initial;\">non v\u00e9rifi\u00e9<\/em>\u00a0(s'applique \u00e0 tous les utilisateurs).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"square\"><a href=\"#square\" title=\"\">Carr\u00e9<\/a><\/h3>\n\n\n\n<p>La passerelle Square vous permet de <strong>pause <strong>seulement <\/strong>l'ensemble des cycles de facturation de l'abonnement. <\/strong>Vous ou vos utilisateurs <strong>peut interrompre les abonnements \u00e0 tout moment<\/strong>. <\/p>\n\n\n\n<p>Lorsqu'un abonnement est mis en pause, le <strong>Passerelle carr\u00e9e <\/strong><span style=\"margin: 0px; padding: 0px;\"><strong>la programmer pour la fin de la p\u00e9riode de facturation en cours<\/strong>.<\/span> Par cons\u00e9quent, faire une pause <strong>ne peut pas \u00eatre appliqu\u00e9e au cycle de facturation qui a d\u00e9j\u00e0 commenc\u00e9<\/strong>Il n'y a plus qu'\u00e0 passer \u00e0 la suivante.<\/p>\n\n\n\n<p>Le programme <strong>la pause ne peut pas \u00eatre annul\u00e9e<\/strong>. Ainsi, un utilisateur peut <strong>reprendre l'abonnement interrompu apr\u00e8s la fin de la p\u00e9riode de facturation en cours<\/strong> et l'abonnement est effectivement interrompu. Apr\u00e8s cette date, les utilisateurs peuvent reprendre leur abonnement \u00e0 tout moment. L'abonnement sera <strong>reprise imm\u00e9diate<\/strong>et le <strong>sera factur\u00e9 \u00e0 la m\u00eame date.<\/strong><\/p>\n\n\n\n<p>De m\u00eame, les abonnements \u00e9tablis avec la passerelle Square<strong> ne peut pas \u00eatre interrompu pendant une phase d'essai gratuit<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Offline Gateway et Authorize.net<\/h3>\n\n\n\n<p>Ces passerelles ne permettent pas actuellement la mise en pause ou la reprise.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Passerelles tierces<\/h3>\n\n\n\n<p>Si vous utilisez une passerelle tierce, vous devrez consulter les d\u00e9veloppeurs de cette option de passerelle pour savoir comment elle fonctionne avec notre fonction Pause\/Reprise.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"note\">Note importante concernant le contenu des gouttes<\/h2>\n\n\n\n<p>Si vous utilisez des fonctions de goutte-\u00e0-goutte dans l'une de vos r\u00e8gles, vous pouvez ou non souhaiter la possibilit\u00e9 de mettre en pause\/reprendre les abonnements r\u00e9currents automatiques.\u00a0<\/p>\n\n\n\n<p>En effet, le MemberPress calcule actuellement le <code>registres des membres<\/code> et le <code>les achats des membres X l'adh\u00e9sion<\/code> sur la base de la date d'inscription de l'utilisateur ou de sa premi\u00e8re transaction, respectivement. <\/p>\n\n\n\n<p>Cela signifie que si un utilisateur interrompt son abonnement et le reprend trois mois plus tard, lorsque son paiement est trait\u00e9, il aura imm\u00e9diatement acc\u00e8s \u00e0 tout le contenu qui a \u00e9t\u00e9 t\u00e9l\u00e9charg\u00e9 pendant ces trois mois. Si vous ne souhaitez pas que cela se produise, ce que vous devez faire d\u00e9pend du type de goutte-\u00e0-goutte que vous utilisez.\u00a0<\/p>\n\n\n\n<p>Si vous utilisez le goutte-\u00e0-goutte \u2018membre s'inscrit', vous devriez d\u00e9sactiver la possibilit\u00e9 de mettre en pause\/reprendre les abonnements puisque WordPress ne permet pas de modifier facilement la date d'inscription de l'utilisateur.\u00a0<\/p>\n\n\n\n<p>Si vous utilisez le type de goutte-\u00e0-goutte \u2018un membre ach\u00e8te une adh\u00e9sion X', vous devrez alors modifier le profil de l'utilisateur. <em>de la premi\u00e8re transaction <\/em>Si vous avez repris une transaction trois mois apr\u00e8s l'avoir interrompue, vous pouvez par exemple avancer de trois mois la date de cr\u00e9ation de la transaction. Vous pouvez \u00e9galement d\u00e9sactiver la possibilit\u00e9 de mettre en pause ou de reprendre une transaction.\u00a0<\/p>\n\n\n\n<p><code>Date fixe<\/code> Les gouttes de type \"goutte \u00e0 goutte\" continueront \u00e0 couler le jour que vous avez d\u00e9fini, ind\u00e9pendamment du fait que l'utilisateur interrompe ou reprenne son abonnement, et l'utilisateur n'aura acc\u00e8s \u00e0 ce contenu que si son abonnement est actif.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Covered in this article: Pausing and Resuming as Administrator Pausing and Resuming as a Subscriber Special Gateway Considerations When Resuming Subscriptions Important Note Regarding Dripped Content MemberPress allows you as admin or your front end users (if you enable them to do this) to pause any supported automatically recurring subscription. The purpose of pausing is [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1319],"ht-kb-tag":[1388,1387],"class_list":{"0":"post-61553","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-subscriptions-and-transactions","7":"ht_kb_tag-subcription","8":"ht_kb_tag-subcriptions","9":"entry","10":"has-post-thumbnail"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Covered in this article: Pausing and Resuming as Administrator Pausing and Resuming as a Subscriber Special Gateway Considerations When Resuming Subscriptions Important Note Regarding Dripped Content MemberPress allows you as admin or your front end users (if you enable them to do this) to pause any supported automatically recurring subscription. The purpose of pausing is\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pausing Subscriptions | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"Covered in this article: Pausing and Resuming as Administrator Pausing and Resuming as a Subscriber Special Gateway Considerations When Resuming Subscriptions Important Note Regarding Dripped Content MemberPress allows you as admin or your front end users (if you enable them to do this) to pause any supported automatically recurring subscription. The purpose of pausing is\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T12:39:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-06-04T07:50:36+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pausing Subscriptions | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Covered in this article: Pausing and Resuming as Administrator Pausing and Resuming as a Subscriber Special Gateway Considerations When Resuming Subscriptions Important Note Regarding Dripped Content MemberPress allows you as admin or your front end users (if you enable them to do this) to pause any supported automatically recurring subscription. The purpose of pausing is\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/#article\",\"name\":\"Pausing Subscriptions | MemberPress\",\"headline\":\"Pausing Subscriptions\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/file-KCgAcb4VBx.png\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/#articleImage\",\"width\":444,\"height\":192},\"datePublished\":\"2024-02-13T07:39:46-05:00\",\"dateModified\":\"2025-06-04T03:50:36-04:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/#webpage\"},\"articleSection\":\"Subscriptions and Transactions, subcription, subcriptions\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/registration-and-payments\\\/#listItem\",\"name\":\"Registration and Payments\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/registration-and-payments\\\/#listItem\",\"position\":3,\"name\":\"Registration and Payments\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/registration-and-payments\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/subscriptions-and-transactions\\\/#listItem\",\"name\":\"Subscriptions and Transactions\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/subscriptions-and-transactions\\\/#listItem\",\"position\":4,\"name\":\"Subscriptions and Transactions\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/subscriptions-and-transactions\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/#listItem\",\"name\":\"Pausing Subscriptions\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/registration-and-payments\\\/#listItem\",\"name\":\"Registration and Payments\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/#listItem\",\"position\":5,\"name\":\"Pausing Subscriptions\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/subscriptions-and-transactions\\\/#listItem\",\"name\":\"Subscriptions and Transactions\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/\",\"name\":\"Pausing Subscriptions | MemberPress\",\"description\":\"Covered in this article: Pausing and Resuming as Administrator Pausing and Resuming as a Subscriber Special Gateway Considerations When Resuming Subscriptions Important Note Regarding Dripped Content MemberPress allows you as admin or your front end users (if you enable them to do this) to pause any supported automatically recurring subscription. The purpose of pausing is\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/pausing-subscriptions\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-02-13T07:39:46-05:00\",\"dateModified\":\"2025-06-04T03:50:36-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Pausing Subscriptions | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Suspendre les abonnements | MemberPress","description":"Couvert dans cet article : Mise en pause et reprise en tant qu'administrateur Mise en pause et reprise en tant qu'abonn\u00e9 Consid\u00e9rations sp\u00e9ciales relatives \u00e0 la passerelle lors de la reprise d'abonnements Remarque importante concernant le contenu perdu MemberPress vous permet, en tant qu'administrateur ou en tant qu'utilisateurs frontaux (si vous les autorisez \u00e0 le faire), de mettre en pause n'importe quel abonnement automatique pris en charge. L'objectif de la mise en pause est le suivant","canonical_url":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/#article","name":"Pausing Subscriptions | MemberPress","headline":"Pausing Subscriptions","author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/file-KCgAcb4VBx.png","@id":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/#articleImage","width":444,"height":192},"datePublished":"2024-02-13T07:39:46-05:00","dateModified":"2025-06-04T03:50:36-04:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/#webpage"},"articleSection":"Subscriptions and Transactions, subcription, subcriptions"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","position":2,"name":"General","item":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/#listItem","name":"Registration and Payments"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/#listItem","position":3,"name":"Registration and Payments","item":"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/subscriptions-and-transactions\/#listItem","name":"Subscriptions and Transactions"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/subscriptions-and-transactions\/#listItem","position":4,"name":"Subscriptions and Transactions","item":"https:\/\/memberpress.com\/fr\/doc-categories\/subscriptions-and-transactions\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/#listItem","name":"Pausing Subscriptions"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/#listItem","name":"Registration and Payments"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/#listItem","position":5,"name":"Pausing Subscriptions","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/subscriptions-and-transactions\/#listItem","name":"Subscriptions and Transactions"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/fr\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/#webpage","url":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/","name":"Pausing Subscriptions | MemberPress","description":"Covered in this article: Pausing and Resuming as Administrator Pausing and Resuming as a Subscriber Special Gateway Considerations When Resuming Subscriptions Important Note Regarding Dripped Content MemberPress allows you as admin or your front end users (if you enable them to do this) to pause any supported automatically recurring subscription. The purpose of pausing is","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-02-13T07:39:46-05:00","dateModified":"2025-06-04T03:50:36-04:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/fr\/#website","url":"https:\/\/memberpress.com\/fr\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"MemberPress","og:type":"article","og:title":"Pausing Subscriptions | MemberPress","og:description":"Covered in this article: Pausing and Resuming as Administrator Pausing and Resuming as a Subscriber Special Gateway Considerations When Resuming Subscriptions Important Note Regarding Dripped Content MemberPress allows you as admin or your front end users (if you enable them to do this) to pause any supported automatically recurring subscription. The purpose of pausing is","og:url":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-02-13T12:39:46+00:00","article:modified_time":"2025-06-04T07:50:36+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Pausing Subscriptions | MemberPress","twitter:description":"Covered in this article: Pausing and Resuming as Administrator Pausing and Resuming as a Subscriber Special Gateway Considerations When Resuming Subscriptions Important Note Regarding Dripped Content MemberPress allows you as admin or your front end users (if you enable them to do this) to pause any supported automatically recurring subscription. The purpose of pausing is","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"61553","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-09 21:41:48","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-02-13 12:39:47","updated":"2026-03-03 14:53:49"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/general\/\" title=\"General\">General<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/\" title=\"Registration and Payments\">Registration and Payments<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/subscriptions-and-transactions\/\" title=\"Subscriptions and Transactions\">Subscriptions and Transactions<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tPausing Subscriptions\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/fr"},{"label":"General","link":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/"},{"label":"Registration and Payments","link":"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/"},{"label":"Subscriptions and Transactions","link":"https:\/\/memberpress.com\/fr\/doc-categories\/subscriptions-and-transactions\/"},{"label":"Pausing Subscriptions","link":"https:\/\/memberpress.com\/fr\/docs\/pausing-subscriptions\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/61553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/comments?post=61553"}],"version-history":[{"count":4,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/61553\/revisions"}],"predecessor-version":[{"id":73380,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/61553\/revisions\/73380"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/media?parent=61553"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category?post=61553"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-tag?post=61553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}