{"id":61787,"date":"2024-02-13T08:14:06","date_gmt":"2024-02-13T13:14:06","guid":{"rendered":"https:\/\/memberpress.com\/docs\/available-gutenberg-blocks\/"},"modified":"2025-06-02T09:20:26","modified_gmt":"2025-06-02T13:20:26","slug":"available-gutenberg-blocks","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/","title":{"rendered":"Blocs Gutenberg disponibles"},"content":{"rendered":"<p>MemberPress est livr\u00e9 avec plusieurs blocs Gutenberg. Vous pouvez utiliser ces blocs sur n'importe quelle zone de votre site WordPress qui peut \u00eatre \u00e9dit\u00e9e avec l'\u00e9diteur de blocs par d\u00e9faut (Gutenberg).<\/p>\n\n\n\n<p>Ce document vous donnera une vue d'ensemble des blocs MemberPress et des d\u00e9tails sur la fa\u00e7on dont chacun d'entre eux peut \u00eatre utilis\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\"><strong>Note<\/strong>: Afin d'utiliser l'int\u00e9gration Gutenberg avec MemberPress, vous devez utiliser WordPress 5.2.1 ou plus et MemberPress 1.4.7 ou plus.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tutoriel vid\u00e9o<\/h2>\n\n\n\n<p><iframe title=\"Lecteur vid\u00e9o YouTube\" src=\"https:\/\/www.youtube.com\/embed\/teqGKfqZpxc?enablejsapi=1\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MemberPress Gutenberg Blocks Vue d'ensemble<\/h2>\n\n\n\n<p>Les blocs MemberPress peuvent \u00eatre utilis\u00e9s pour ajouter des formulaires MemberPress classiques et d'autres informations relatives aux membres \u00e0 vos pages et articles personnalis\u00e9s. Vous pouvez \u00e9galement ajouter des blocs MemberPress \u00e0 vos zones de widgets.<\/p>\n\n\n\n<p>Les blocs MemberPress actuellement disponibles sont les suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#login-block\"><strong>Formulaire de connexion<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#account-block\"><strong>Formulaire de compte<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#account-links\"><strong>Liens vers les comptes<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#account-info\"><strong>Informations sur le compte<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#registration-block\"><strong>Formulaire d'inscription<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#subscriptions-block\"><strong>Abonnements<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"#protected-block\"><strong>Contenu prot\u00e9g\u00e9<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p><span style=\"margin: 0px; padding: 0px;\">En outre, vous pouvez utiliser les blocs ReadyLaunch\u2122 si vous\u00a0<a href=\"https:\/\/memberpress.com\/fr\/docs\/designing-pages-with-readylaunch\/\" target=\"_blank\"><strong>activer les mod\u00e8les ReadyLaunch\u2122<\/strong><\/a>.<\/span> Dans ce cas, le <a href=\"https:\/\/memberpress.com\/fr\/docs\/customizing-the-login-page-with-readylaunch\/\" target=\"_blank\" rel=\"noopener\"><strong>Connexion<\/strong><\/a>, <a href=\"https:\/\/memberpress.com\/fr\/docs\/customizing-the-account-page-with-readylaunch\/\" target=\"_blank\" rel=\"noopener\"><strong>Compte<\/strong><\/a>, <a href=\"https:\/\/memberpress.com\/fr\/docs\/customizing-the-registration-page-with-readylaunch\/\" target=\"_blank\" rel=\"noopener\"><strong>Inscription<\/strong><\/a>et <a href=\"https:\/\/memberpress.com\/fr\/docs\/customizing-the-pricing-page-with-ready-launch\/\" target=\"_blank\" rel=\"noopener\"><strong>Tableau des prix<\/strong><\/a> (Groupes) seront disponibles dans votre liste.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"login-block\">Bloc de formulaires de connexion<\/h3>\n\n\n\n<p>Le formulaire de connexion classique de MemberPress peut \u00eatre facilement ajout\u00e9 n'importe o\u00f9 gr\u00e2ce au bloc Formulaire de connexion.\u00a0<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8d3af5f1\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8d3af5f1\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1917\" height=\"969\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28.png\" alt=\"\" class=\"wp-image-73122\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28.png 1917w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-300x152.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-1024x518.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-1536x776.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-336x170.png 336w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-840x425.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-1216x615.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-1832x926.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-700x354.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28-1080x546.png 1080w\" sizes=\"(max-width: 1917px) 100vw, 1917px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Le bloc est accompagn\u00e9 de la mention \"<b>URL de redirection de la connexion<\/b>\"L'activation de cette option redirigera les utilisateurs non autoris\u00e9s vers l'URL de redirection d\u00e9finie dans les param\u00e8tres de MemberPress. L'activation de cette option redirigera les utilisateurs non autoris\u00e9s vers l'URL de redirection que vous avez d\u00e9finie dans les param\u00e8tres de MemberPress. En revanche, s'il est d\u00e9sactiv\u00e9, ce bloc permettra aux utilisateurs de se connecter et de rester sur la m\u00eame page (o\u00f9 le bloc est ajout\u00e9) apr\u00e8s s'\u00eatre connect\u00e9s.<\/p>\n\n\n\n<p>Si l'utilisateur est d\u00e9j\u00e0 connect\u00e9, le bloc affichera le message \u201c<i>Vous \u00eates d\u00e9j\u00e0 connect\u00e9<\/i>\u201d avec un lien de d\u00e9connexion.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"account-block\">Bloc de formulaires de compte<\/h3>\n\n\n\n<p>Vous pouvez ajouter le formulaire de compte MemberPress classique \u00e0 n'importe quel endroit de votre site en utilisant le bloc Compte MemberPress. Ainsi, par exemple, vous pouvez cr\u00e9er une page de compte personnalis\u00e9e et ajouter le bloc Compte pour afficher le formulaire de compte sur cette page.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8d3af9ac\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8d3af9ac\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1903\" height=\"954\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29.png\" alt=\"\" class=\"wp-image-73123\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29.png 1903w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-300x150.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-1024x513.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-768x385.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-1536x770.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-339x170.png 339w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-840x421.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-1216x610.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-1832x918.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-700x351.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-156x78.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-29-1080x541.png 1080w\" sizes=\"(max-width: 1903px) 100vw, 1903px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"account-links\">Bloc de liens de compte<\/h3>\n\n\n\n<p>Le bloc Liens de compte affiche deux liens sur la page, l'article ou la zone de widget o\u00f9 le bloc est ajout\u00e9 :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les <b>Compte <\/b>lien vers la page du compte MemberPress de l'utilisateur (d\u00e9fini \u00e0 l'adresse <i>Tableau de bord &gt; MemberPress &gt; Param\u00e8tres &gt; Onglet Pages<\/i>);<\/li>\n\n\n\n<li>les <b>D\u00e9connexion <\/b>lien.<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8d3afd43\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8d3afd43\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1903\" height=\"555\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30.png\" alt=\"\" class=\"wp-image-73124\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30.png 1903w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-300x87.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-1024x299.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-768x224.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-50x15.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-1536x448.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-583x170.png 583w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-840x245.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-1216x355.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-1832x534.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-700x204.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-156x45.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-30-1080x315.png 1080w\" sizes=\"(max-width: 1903px) 100vw, 1903px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"account-info\">Bloc d'informations sur le compte<\/h3>\n\n\n\n<p>Ce bloc vous permet d'afficher toutes les donn\u00e9es du compte utilisateur pr\u00e9sentes dans l'onglet Compte &gt; Accueil.<\/p>\n\n\n\n<p>Sous les param\u00e8tres du bloc, vous verrez l'ic\u00f4ne \"<b>Limace de champ<\/b>\"Vous pouvez y choisir le libell\u00e9 de n'importe quel champ du compte.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8d3b008e\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8d3b008e\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1917\" height=\"969\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31.png\" alt=\"\" class=\"wp-image-73125\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31.png 1917w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-300x152.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-1024x518.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-1536x776.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-336x170.png 336w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-840x425.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-1216x615.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-1832x926.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-700x354.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-31-1080x546.png 1080w\" sizes=\"(max-width: 1917px) 100vw, 1917px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>En s\u00e9lectionnant l'intitul\u00e9 du champ, vous choisissez l'affichage des donn\u00e9es de l'utilisateur sur le front-end.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8d3b03e9\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8d3b03e9\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1902\" height=\"508\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33.png\" alt=\"\" class=\"wp-image-73127\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33.png 1902w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-300x80.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-1024x273.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-768x205.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-50x13.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-1536x410.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-636x170.png 636w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-840x224.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-1216x325.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-1832x489.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-700x187.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-156x42.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-33-1080x288.png 1080w\" sizes=\"(max-width: 1902px) 100vw, 1902px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"registration-block\">Bloc de formulaires d'inscription<\/h3>\n\n\n\n<p>Gr\u00e2ce \u00e0 ce bloc, vous pouvez facilement ajouter un formulaire d'adh\u00e9sion classique MemberPress n'importe o\u00f9 sur votre site.<\/p>\n\n\n\n<p>Une fois que vous avez ajout\u00e9 le bloc \u00e0 un article, par exemple, vous verrez appara\u00eetre le \u201c<b>S\u00e9lectionnez un formulaire d'inscription \u00e0 afficher<\/b>\u201d dans le menu d\u00e9roulant sous les param\u00e8tres du bloc.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8d3b0736\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8d3b0736\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1917\" height=\"968\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32.png\" alt=\"\" class=\"wp-image-73126\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32.png 1917w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-300x151.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-1024x517.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-1536x776.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-337x170.png 337w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-840x424.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-1216x614.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-1832x925.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-700x353.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-32-1080x545.png 1080w\" sizes=\"(max-width: 1917px) 100vw, 1917px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Ici, vous pouvez s\u00e9lectionner le membre dont vous souhaitez ajouter le formulaire d'inscription \u00e0 l'aide de ce bloc.<\/p>\n\n\n\n<p>Similaire au bloc Compte, ce bloc vous permet de cr\u00e9er des pages d'inscription personnalis\u00e9es, des pages promotionnelles ou des pages d'atterrissage avec le formulaire d'inscription int\u00e9gr\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"subscriptions-block\">Bloc abonnements<\/h3>\n\n\n\n<p>Ce bloc ajoute la liste de toutes les adh\u00e9sions auxquelles l'utilisateur connect\u00e9 est actuellement abonn\u00e9. Ce bloc propose plusieurs options de tri et des zones de texte personnalisables.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8d3b0aca\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8d3b0aca\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1902\" height=\"968\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34.png\" alt=\"\" class=\"wp-image-73128\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34.png 1902w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-300x153.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-1024x521.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-768x391.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-1536x782.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-334x170.png 334w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-840x428.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-1216x619.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-1832x932.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-700x356.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-34-1080x550.png 1080w\" sizes=\"(max-width: 1902px) 100vw, 1902px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Les options disponibles pour ce bloc sont les suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><b>Trier par :<\/b> Les options de tri disponibles sont les suivantes : \u201c<b>Date<\/b>\u201d (lorsque l'adh\u00e9sion a \u00e9t\u00e9 cr\u00e9\u00e9e), ou par \u201c<b>Titre<\/b>\u201d (par ordre alphab\u00e9tique) ;<\/li>\n\n\n\n<li><b>Ordre de tri<\/b>: Choisissez l'option <b>Descente <\/b>ou <b>Ascendante <\/b>l'ordre ;<\/li>\n\n\n\n<li><b>Non connect\u00e9 Message :<\/b> Ce message sera affich\u00e9 pour ce bloc lorsque l'utilisateur d\u00e9connect\u00e9 visitera cet article ou cette page.<\/li>\n\n\n\n<li><b>Pas d'abonnement Message :<\/b> Ce message sera affich\u00e9 pour ce bloc si l'utilisateur connect\u00e9 n'a pas d'abonnement actif.<\/li>\n\n\n\n<li><b>Utiliser les URL d'acc\u00e8s aux membres<\/b>: L'activation de cette option rendra les abonnements membres r\u00e9pertori\u00e9s cliquables. Ces noms d'abonnements pointeront vers le \u201c<i>URL d'acc\u00e8s aux membres<\/i>\u201d que vous avez d\u00e9fini dans vos param\u00e8tres d'adh\u00e9sion (<i>Options d'adh\u00e9sion &gt; Onglet Avanc\u00e9<\/i>).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"protected-block\">Bloc de contenu prot\u00e9g\u00e9<\/h3>\n\n\n\n<p>Le bloc de contenu prot\u00e9g\u00e9 MemberPress est utilis\u00e9 comme bloc de groupe pour le contenu prot\u00e9g\u00e9. Vous pouvez ajouter n'importe quel bloc Gutenberg aux blocs de contenu prot\u00e9g\u00e9.<\/p>\n\n\n\n<p>Vous pouvez appliquer un <a href=\"https:\/\/memberpress.com\/fr\/docs\/rules-overview\/\" target=\"_blank\" rel=\"noopener\"><strong>R\u00e8gle MemberPress<\/strong><\/a> dans le bloc Contenu prot\u00e9g\u00e9 pour <strong><a href=\"https:\/\/memberpress.com\/fr\/docs\/protect-gutenberg-blocks-with-memberpress\/#protected-content-block\" target=\"_blank\" rel=\"noopener\" title=\"\">prot\u00e9ger le contenu qu'il contient<\/a><\/strong>. En fonction des param\u00e8tres du bloc, vous pouvez <strong>montrer <\/strong>ou <strong>cacher <\/strong>le contenu prot\u00e9g\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\"><strong>Remarque : <\/strong>Utilisation du MemberPress <strong><a href=\"https:\/\/memberpress.com\/fr\/docs\/protect-gutenberg-blocks-with-memberpress\/#partial-rules\" target=\"_blank\" rel=\"noopener\" title=\"\">Type de r\u00e8gle partielle<\/a><\/strong> avec le bloc de contenu prot\u00e9g\u00e9 est <strong>recommand\u00e9<\/strong>.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8d3b135f\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8d3b135f\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1918\" height=\"968\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35.png\" alt=\"\" class=\"wp-image-73129\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35.png 1918w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-300x151.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-1024x517.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-1536x775.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-337x170.png 337w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-840x424.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-1216x614.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-1832x925.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-700x353.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-35-1080x545.png 1080w\" sizes=\"(max-width: 1918px) 100vw, 1918px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>En outre, vous pouvez choisir l'action <span style=\"margin: 0px; padding: 0px;\">\u00e0 prendre si un utilisateur non autoris\u00e9 tente d'acc\u00e9der au contenu prot\u00e9g\u00e9. L'option par d\u00e9faut est \u201c<strong>Cacher seulement<\/strong>, ce qui signifie<\/span> le contenu prot\u00e9g\u00e9 ne sera pas affich\u00e9. Vous pouvez \u00e9galement choisir de <strong>afficher un message personnalis\u00e9<\/strong>, le MemberPress <strong>formulaire de connexion<\/strong>ou <strong>\u00e0 la fois<\/strong>.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8d3b1643\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8d3b1643\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1917\" height=\"968\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36.png\" alt=\"\" class=\"wp-image-73130\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36.png 1917w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-300x151.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-1024x517.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-1536x776.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-337x170.png 337w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-840x424.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-1216x614.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-1832x925.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-700x353.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-36-1080x545.png 1080w\" sizes=\"(max-width: 1917px) 100vw, 1917px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Comment trouver et ajouter des blocs MemberPress<\/h2>\n\n\n\n<p>Les blocs MemberPress seront disponibles dans tout article ou zone de site o\u00f9 l'\u00e9diteur de blocs par d\u00e9faut est activ\u00e9. Pour trouver et ajouter des blocs MemberPress, proc\u00e9dez comme suit :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Lancez l'\u00e9diteur de blocs sur le message ou la zone que vous souhaitez modifier.<\/li>\n\n\n\n<li>Cliquez sur le bouton <strong>Ic\u00f4ne \"+\" (+)<\/strong> pour ouvrir l'inserteur de blocs.<\/li>\n\n\n\n<li>Recherchez ou parcourez la liste des blocs pour trouver le bloc dont vous avez besoin.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04b8d3b19f1\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b8d3b19f1\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"1917\" height=\"968\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38.png\" alt=\"\" class=\"wp-image-73132\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38.png 1917w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-300x151.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-1024x517.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-768x388.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-50x25.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-1536x776.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-337x170.png 337w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-840x424.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-1216x614.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-1832x925.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-700x353.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-156x79.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-38-1080x545.png 1080w\" sizes=\"(max-width: 1917px) 100vw, 1917px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><p>Cliquez sur le bloc pour l'ajouter.<\/p><\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Video Tutorial MemberPress Gutenberg Blocks Overview [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1318],"ht-kb-tag":[1488],"class_list":{"0":"post-61787","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-look-and-feel","7":"ht_kb_tag-kadence","8":"entry","9":"has-post-thumbnail"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Available Gutenberg Blocks | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T13:14:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-06-02T13:20:26+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Available Gutenberg Blocks | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/#article\",\"name\":\"Available Gutenberg Blocks | MemberPress\",\"headline\":\"Available Gutenberg Blocks\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/image-28.png\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/#articleImage\",\"width\":1917,\"height\":969},\"datePublished\":\"2024-02-13T08:14:06-05:00\",\"dateModified\":\"2025-06-02T09:20:26-04:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/#webpage\"},\"articleSection\":\"Look and Feel, kadence\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/look-and-feel\\\/#listItem\",\"name\":\"Look and Feel\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/look-and-feel\\\/#listItem\",\"position\":3,\"name\":\"Look and Feel\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/look-and-feel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/#listItem\",\"name\":\"Available Gutenberg Blocks\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/#listItem\",\"position\":4,\"name\":\"Available Gutenberg Blocks\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/look-and-feel\\\/#listItem\",\"name\":\"Look and Feel\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/\",\"name\":\"Available Gutenberg Blocks | MemberPress\",\"description\":\"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/available-gutenberg-blocks\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-02-13T08:14:06-05:00\",\"dateModified\":\"2025-06-02T09:20:26-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Available Gutenberg Blocks | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Blocs Gutenberg disponibles | MemberPress","description":"MemberPress est livr\u00e9 avec plusieurs blocs Gutenberg. Vous pouvez utiliser ces blocs sur n'importe quelle zone de votre site WordPress qui peut \u00eatre \u00e9dit\u00e9e avec l'\u00e9diteur de blocs par d\u00e9faut (Gutenberg). Ce document vous donnera un aper\u00e7u des blocs MemberPress et des d\u00e9tails sur la fa\u00e7on dont chacun d'entre eux peut \u00eatre utilis\u00e9. Note : Afin d'utiliser les blocs","canonical_url":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/#article","name":"Available Gutenberg Blocks | MemberPress","headline":"Available Gutenberg Blocks","author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/image-28.png","@id":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/#articleImage","width":1917,"height":969},"datePublished":"2024-02-13T08:14:06-05:00","dateModified":"2025-06-02T09:20:26-04:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/#webpage"},"articleSection":"Look and Feel, kadence"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","position":2,"name":"General","item":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/look-and-feel\/#listItem","name":"Look and Feel"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/look-and-feel\/#listItem","position":3,"name":"Look and Feel","item":"https:\/\/memberpress.com\/fr\/doc-categories\/look-and-feel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/#listItem","name":"Available Gutenberg Blocks"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/#listItem","position":4,"name":"Available Gutenberg Blocks","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/look-and-feel\/#listItem","name":"Look and Feel"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/fr\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/#webpage","url":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/","name":"Available Gutenberg Blocks | MemberPress","description":"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-02-13T08:14:06-05:00","dateModified":"2025-06-02T09:20:26-04:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/fr\/#website","url":"https:\/\/memberpress.com\/fr\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"MemberPress","og:type":"article","og:title":"Available Gutenberg Blocks | MemberPress","og:description":"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the","og:url":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-02-13T13:14:06+00:00","article:modified_time":"2025-06-02T13:20:26+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Available Gutenberg Blocks | MemberPress","twitter:description":"MemberPress comes with multiple Gutenberg blocks. You can use these blocks on any area of your WordPress site that can be edited with the default Block Editor (Gutenberg). This document will give you an overview of the MemberPress Blocks and details on how each of them can be used. Note: In order to utilize the","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"61787","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-09 21:47:16","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-02-13 13:14:09","updated":"2026-03-03 14:53:48"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/general\/\" title=\"General\">General<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/look-and-feel\/\" title=\"Look and Feel\">Look and Feel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tAvailable Gutenberg Blocks\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/fr"},{"label":"General","link":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/"},{"label":"Look and Feel","link":"https:\/\/memberpress.com\/fr\/doc-categories\/look-and-feel\/"},{"label":"Available Gutenberg Blocks","link":"https:\/\/memberpress.com\/fr\/docs\/available-gutenberg-blocks\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/61787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/comments?post=61787"}],"version-history":[{"count":3,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/61787\/revisions"}],"predecessor-version":[{"id":73335,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/61787\/revisions\/73335"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/media?parent=61787"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category?post=61787"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-tag?post=61787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}