{"id":62390,"date":"2024-02-13T09:33:02","date_gmt":"2024-02-13T14:33:02","guid":{"rendered":"https:\/\/memberpress.com\/docs\/i-don-t-see-my-currency-can-it-be-added\/"},"modified":"2025-06-17T12:02:33","modified_gmt":"2025-06-17T16:02:33","slug":"add-currency-code-to-memberpress","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/","title":{"rendered":"Ajouter le code devise \u00e0 MemberPress"},"content":{"rendered":"<p>MemberPress accepte les m\u00eames devises que les passerelles de paiement en ligne qui peuvent \u00eatre int\u00e9gr\u00e9es \u00e0 MemberPress (<strong><a href=\"https:\/\/memberpress.com\/fr\/docs\/stripe\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Rayure<\/a><\/strong>, <strong><a href=\"https:\/\/memberpress.com\/fr\/docs\/paypal-standard\/\" target=\"_blank\" rel=\"noopener\" title=\"\">PayPal<\/a><\/strong>, <strong><a href=\"https:\/\/memberpress.com\/fr\/docs\/connect-square-to-memberpress\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Carr\u00e9<\/a>,<\/strong> et <strong><a href=\"https:\/\/memberpress.com\/fr\/docs\/connect-authorize-net-to-memberpress\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Authorize.net<\/a><\/strong>). Vous pouvez ajouter un code de devise \u00e0 la liste des devises de MemberPress en ajoutant un extrait de code \u00e0 votre site web.<\/p>\n\n\n\n<p>Ce document fournit un extrait de code permettant d'ajouter un code de devise \u00e0 la liste des devises de MemberPress. Il explique \u00e9galement comment modifier le code en fonction de vos besoins.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ajouter un code de devise \u00e0 MemberPress \u2013 Extrait de code<\/h2>\n\n\n\n<p>Cet extrait de code ajoutera une devise \u00e0 la liste des devises de MemberPress sous la rubrique <strong>Code devise<\/strong> option. L'option Code devise vous permet de choisir la devise que MemberPress doit utiliser sur votre site web. Cette option est disponible sous l'onglet <strong><a href=\"https:\/\/memberpress.com\/fr\/docs\/general\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Onglet G\u00e9n\u00e9ral<\/a><\/strong> \u00e0 <strong>Tableau de bord &gt; MemberPress &gt; Param\u00e8tres<\/strong>.<\/p>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04a764941c7\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04a764941c7\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2546\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code.png\" alt=\"Ajouter un code de devise \u00e0 la liste des devises de MemberPress\" class=\"wp-image-72812\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code.png 2546w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-300x155.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-1024x529.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-768x397.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-1536x794.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-2048x1059.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-329x170.png 329w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-840x434.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-1216x629.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-1832x947.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-700x362.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-156x81.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code-1080x558.png 1080w\" sizes=\"(max-width: 2546px) 100vw, 2546px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>L'exemple de code ajoute l'\u00e9l\u00e9ment <strong>Livre \u00e9gyptienne (EGP)<\/strong> \u00e0 la liste des devises.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">\/\/Ajouter les codes de devise \u00e0 MemberPress<br><br>function mepr_currency_codes( $codes ) {<br>    array_push( $codes, 'EGP' ) ; \/\/ Ajoute 'EGP' \u00e0 la liste des codes de devises. Pour ajouter une autre devise, remplacez EGP par le code \u00e0 trois lettres de la devise souhait\u00e9e.<br>    return $codes ; \/\/ Retourne la liste modifi\u00e9e des codes des devises.<br>}<br>add_filter( 'mepr-currency-codes', 'mepr_currency_codes' ) ;<\/pre>\n\n\n\n<p>Vous pouvez ajouter l'extrait de code \u00e0 votre site web dans la section <strong>functions.php<\/strong> de votre th\u00e8me enfant. Vous pouvez \u00e9galement utiliser l'option <a href=\"https:\/\/wordpress.org\/plugins\/insert-headers-and-footers\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>WPCode<\/strong><\/a> plugin. Veuillez consulter le document suivant pour obtenir des instructions pas \u00e0 pas sur la fa\u00e7on de proc\u00e9der. <strong><a href=\"https:\/\/memberpress.com\/fr\/docs\/how-to-add-custom-code-snippets-in-wpcode\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Comment ajouter des extraits de code personnalis\u00e9s dans WPCode<\/a><\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Modification de l'extrait de code<\/h2>\n\n\n\n<p>Pour ajouter une autre devise, vous devez remplacer <strong>EGP<\/strong> avec le code \u00e0 trois lettres de la devise requise, sur cette ligne :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">array_push( $codes, 'EGP' ) ;<\/pre>\n\n\n\n<p>Vous pouvez \u00e9galement ajouter plusieurs devises si n\u00e9cessaire. Pour ce faire, ajoutez les codes \u00e0 trois lettres des devises n\u00e9cessaires, en les s\u00e9parant par une virgule. <\/p>\n\n\n\n<p>Par exemple, pour ajouter les deux <strong>Livre \u00e9gyptienne (EGP)<\/strong> et <strong>Roupie indienne (INR)<\/strong>la ligne de code susmentionn\u00e9e ressemblerait \u00e0 ceci :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted has-background\" style=\"background-color:#f5f5f5\">array_push( $codes, 'EGP', 'INR' )<\/pre>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\"><strong>Note<\/strong>: L'extrait de code ajoutera le code de la devise \u00e0 MemberPress. Cependant, le code <strong>La passerelle de paiement que vous avez s\u00e9lectionn\u00e9e doit \u00e9galement prendre en charge la devise<\/strong> de l'utiliser pour les paiements en ligne.<\/p>","protected":false},"excerpt":{"rendered":"<p>MemberPress supports the same currencies as online payment gateways that can be integrated with MemberPress (Stripe, PayPal, Square, and Authorize.net). You can add a currency code to the MemberPress currency list by adding a code snippet to your website. This document provides a code snippet to add a currency code to the MemberPress currency list. [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1328,1398],"ht-kb-tag":[],"class_list":{"0":"post-62390","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-memberships-faqs","7":"ht_kb_category-payments-and-subscriptions","8":"entry","9":"has-post-thumbnail"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"This document provides a code snippet to add a currency code to the MemberPress currency list. It also explains how to modify the code based on your needs.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Add Currency Code to MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"This document provides a code snippet to add a currency code to the MemberPress currency list. It also explains how to modify the code based on your needs.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T14:33:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-06-17T16:02:33+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Add Currency Code to MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"This document provides a code snippet to add a currency code to the MemberPress currency list. It also explains how to modify the code based on your needs.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/#article\",\"name\":\"Add Currency Code to MemberPress\",\"headline\":\"Add Currency Code to MemberPress\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/mepr-currency-code.png\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/#articleImage\",\"width\":2546,\"height\":1316},\"datePublished\":\"2024-02-13T09:33:02-05:00\",\"dateModified\":\"2025-06-17T12:02:33-04:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/#webpage\"},\"articleSection\":\"Memberships FAQs, Payments and Subscriptions\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/advanced-topics\\\/#listItem\",\"name\":\"Advanced Topics\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/advanced-topics\\\/#listItem\",\"position\":2,\"name\":\"Advanced Topics\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/advanced-topics\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/custom-codes\\\/#listItem\",\"name\":\"Custom Codes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/custom-codes\\\/#listItem\",\"position\":3,\"name\":\"Custom Codes\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/custom-codes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/payments-and-subscriptions\\\/#listItem\",\"name\":\"Payments and Subscriptions\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/advanced-topics\\\/#listItem\",\"name\":\"Advanced Topics\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/payments-and-subscriptions\\\/#listItem\",\"position\":4,\"name\":\"Payments and Subscriptions\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/payments-and-subscriptions\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/#listItem\",\"name\":\"Add Currency Code to MemberPress\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/custom-codes\\\/#listItem\",\"name\":\"Custom Codes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/#listItem\",\"position\":5,\"name\":\"Add Currency Code to MemberPress\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/payments-and-subscriptions\\\/#listItem\",\"name\":\"Payments and Subscriptions\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/\",\"name\":\"Add Currency Code to MemberPress\",\"description\":\"This document provides a code snippet to add a currency code to the MemberPress currency list. It also explains how to modify the code based on your needs.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/add-currency-code-to-memberpress\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-02-13T09:33:02-05:00\",\"dateModified\":\"2025-06-17T12:02:33-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Add Currency Code to MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Ajouter le code devise \u00e0 MemberPress","description":"Ce document fournit un extrait de code permettant d'ajouter un code de devise \u00e0 la liste des devises de MemberPress. Il explique \u00e9galement comment modifier le code en fonction de vos besoins.","canonical_url":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/#article","name":"Add Currency Code to MemberPress","headline":"Add Currency Code to MemberPress","author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2024\/02\/mepr-currency-code.png","@id":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/#articleImage","width":2546,"height":1316},"datePublished":"2024-02-13T09:33:02-05:00","dateModified":"2025-06-17T12:02:33-04:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/#webpage"},"articleSection":"Memberships FAQs, Payments and Subscriptions"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/#listItem","name":"Advanced Topics"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/#listItem","position":2,"name":"Advanced Topics","item":"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/#listItem","name":"Custom Codes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/#listItem","position":3,"name":"Custom Codes","item":"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/#listItem","name":"Payments and Subscriptions"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/#listItem","name":"Advanced Topics"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/#listItem","position":4,"name":"Payments and Subscriptions","item":"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/#listItem","name":"Add Currency Code to MemberPress"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/#listItem","name":"Custom Codes"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/#listItem","position":5,"name":"Add Currency Code to MemberPress","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/#listItem","name":"Payments and Subscriptions"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/fr\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/#webpage","url":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/","name":"Add Currency Code to MemberPress","description":"This document provides a code snippet to add a currency code to the MemberPress currency list. It also explains how to modify the code based on your needs.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-02-13T09:33:02-05:00","dateModified":"2025-06-17T12:02:33-04:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/fr\/#website","url":"https:\/\/memberpress.com\/fr\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"MemberPress","og:type":"article","og:title":"Add Currency Code to MemberPress","og:description":"This document provides a code snippet to add a currency code to the MemberPress currency list. It also explains how to modify the code based on your needs.","og:url":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-02-13T14:33:02+00:00","article:modified_time":"2025-06-17T16:02:33+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Add Currency Code to MemberPress","twitter:description":"This document provides a code snippet to add a currency code to the MemberPress currency list. It also explains how to modify the code based on your needs.","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"62390","title":"#post_title","description":"Ce document fournit un extrait de code permettant d'ajouter un code de devise \u00e0 la liste des devises de MemberPress. Il explique \u00e9galement comment modifier le code en fonction de vos besoins.","keywords":null,"keyphrases":{"focus":{"keyphrase":"Currency Code","score":87,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"high","score":0,"maxScore":9,"error":1}}},"additional":[{"keyphrase":"MemberPress Currency","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":{"ht_kb_category":1398},"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-09 22:01:00","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-02-13 14:33:02","updated":"2026-03-03 14:52:42"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/\" title=\"Advanced Topics\">Advanced Topics<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/\" title=\"Custom Codes\">Custom Codes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/\" title=\"Payments and Subscriptions\">Payments and Subscriptions<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tAdd Currency Code to MemberPress\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/fr"},{"label":"Advanced Topics","link":"https:\/\/memberpress.com\/fr\/doc-categories\/advanced-topics\/"},{"label":"Custom Codes","link":"https:\/\/memberpress.com\/fr\/doc-categories\/custom-codes\/"},{"label":"Payments and Subscriptions","link":"https:\/\/memberpress.com\/fr\/doc-categories\/payments-and-subscriptions\/"},{"label":"Add Currency Code to MemberPress","link":"https:\/\/memberpress.com\/fr\/docs\/add-currency-code-to-memberpress\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/62390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/comments?post=62390"}],"version-history":[{"count":8,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/62390\/revisions"}],"predecessor-version":[{"id":73623,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/62390\/revisions\/73623"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/media?parent=62390"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category?post=62390"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-tag?post=62390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}