{"id":73314,"date":"2025-05-30T18:51:31","date_gmt":"2025-05-30T22:51:31","guid":{"rendered":"https:\/\/memberpress.com\/?post_type=ht_kb&#038;p=73314"},"modified":"2025-10-27T10:02:41","modified_gmt":"2025-10-27T14:02:41","slug":"square-sandbox-with-memberpress","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/","title":{"rendered":"Connecter et tester Square Sandbox avec MemberPress"},"content":{"rendered":"<p>Tester le traitement des paiements avant la mise en service permet de s'assurer que votre site d'affiliation fonctionne correctement sans traiter de transactions r\u00e9elles. Square met \u00e0 votre disposition un environnement \"sandbox\" qui vous permet de simuler des paiements et de tester votre int\u00e9gration MemberPress en toute s\u00e9curit\u00e9.\u00a0<\/p>\n\n\n\n<p>Ce document explique comment configurer et tester le mode bac \u00e0 sable de Square avec MemberPress avant d'accepter des paiements r\u00e9els de la part des membres.<\/p>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\"><strong>Remarque :<\/strong>\u00a0Cette int\u00e9gration de paiement est disponible pour MemberPress\u00a0<strong>Croissance<\/strong>\u00a0et\u00a0<strong>\u00c9chelle<\/strong>\u00a0Les membres du plan de lancement peuvent passer au plan de croissance et d'expansion. Si vous \u00eates abonn\u00e9 au plan de lancement, vous pouvez passer au plan de croissance et d'expansion. Pour passer \u00e0 un plan sup\u00e9rieur, cliquez sur l'ic\u00f4ne\u00a0<strong>Plan de changement<\/strong>\u00a0sur votre\u00a0<a href=\"https:\/\/memberpress.com\/account\/subscriptions\/\"><strong>page du compte<\/strong><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"square-sandbox\"><strong><a href=\"#square-sandbox\" title=\"\">Qu'est-ce que <strong>Bac \u00e0 sable carr\u00e9<\/strong>?<\/a><\/strong><\/h2>\n\n\n\n<p>Connecter Square \u00e0 MemberPress vous permet d'accepter des paiements de la part de membres du monde entier. L'int\u00e9gration prend en charge les paiements uniques et r\u00e9currents, ce qui la rend adapt\u00e9e \u00e0 divers mod\u00e8les commerciaux d'adh\u00e9sion.<\/p>\n\n\n\n<p>Square Sandbox est un environnement de test qui imite le syst\u00e8me de paiement en direct de Square sans traiter les frais de carte de cr\u00e9dit r\u00e9els. Le bac \u00e0 sable vous permet de tester les flux de paiement, la gestion des erreurs et les param\u00e8tres d'int\u00e9gration en utilisant des num\u00e9ros de carte de test au lieu des informations de paiement r\u00e9elles.<\/p>\n\n\n\n<p>Vous devez toujours tester votre connexion \u00e0 l'aide de Square Sandbox avant d'accepter des paiements en direct. Cela permet de s'assurer que tout fonctionne correctement et d'\u00e9viter les probl\u00e8mes de traitement des paiements pour vos membres.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"create\"><strong><a href=\"#create\" title=\"\">Cr\u00e9ation d'un bac \u00e0 sable carr\u00e9<\/a><\/strong><\/h2>\n\n\n\n<p>Pour acc\u00e9der \u00e0 l'environnement sandbox et connecter Square \u00e0 MemberPress, vous avez besoin d'un compte d\u00e9veloppeur Square :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Aller \u00e0 la page <a href=\"https:\/\/developer.squareup.com\/\"><strong>Square Develope<\/strong><\/a><strong><a href=\"https:\/\/developer.squareup.com\/\" target=\"_blank\" rel=\"noopener\" title=\"\">r<\/a><\/strong><a href=\"https:\/\/developer.squareup.com\/\"><strong> Tableau de bord<\/strong><\/a>.<\/li>\n\n\n\n<li>Cliquez sur <strong>S'inscrire<\/strong> si vous n'avez pas de compte, ou <strong>S'inscrire<\/strong> avec vos identifiants Square existants.<\/li>\n\n\n\n<li>Compl\u00e9tez la proc\u00e9dure d'enregistrement si vous cr\u00e9ez un nouveau compte.<\/li>\n<\/ol>\n\n\n\n<p>Une fois connect\u00e9, vous verrez la console de d\u00e9veloppement Square. Maintenant, vous pouvez cr\u00e9er votre compte de test sandbox. Vous utiliserez ce compte de test pour les tests en bac \u00e0 sable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"test-account\"><strong><a href=\"#test-account\" title=\"\">Compte de test de l'Environnement de test<\/a><\/strong><\/h3>\n\n\n\n<p>Pour cr\u00e9er votre compte de test sandbox, connectez-vous \u00e0 la console de d\u00e9veloppement Square :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Cliquez sur <strong>Comptes de test dans l'environnement de test<\/strong> dans le menu de gauche.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04a2559ea56\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04a2559ea56\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2558\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account.png\" alt=\"\" class=\"wp-image-73316\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account.png 2558w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-1536x790.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-1832x942.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account-1080x556.png 1080w\" sizes=\"(max-width: 2558px) 100vw, 2558px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li>Ensuite, cliquez sur le bouton <strong>+ Nouveau compte de test sandbox<\/strong> bouton.\u00a0<\/li>\n\n\n\n<li>Une fen\u00eatre contextuelle s'ouvrira. Donnez un compte de test \u00e0 votre bac \u00e0 sable <strong>nom <\/strong>et s\u00e9lectionner un <strong>pays<\/strong>.<\/li>\n\n\n\n<li>Cliquez sur le bouton <strong>Cr\u00e9er <\/strong>bouton.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"connect\"><strong><a href=\"#connect\" title=\"\">Connexion de MemberPress \u00e0 Square Sandbox<\/a><\/strong><\/h2>\n\n\n\n<p>Connectons maintenant MemberPress sur votre site web \u00e0 l'environnement de test de Square. Pour ce faire, vous devez d'abord <a href=\"https:\/\/memberpress.com\/fr\/docs\/connect-square-to-memberpress\/#create-square-gateway\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>cr\u00e9er une passerelle Square en MemberPress<\/strong><\/a> des param\u00e8tres.\u00a0<\/p>\n\n\n\n<p>Vous pouvez maintenant connecter MemberPress \u00e0 votre Square Sandbox :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Retournez \u00e0 la page <a href=\"https:\/\/developer.squareup.com\/console\/en\/sandbox-test-accounts\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>Comptes de test dans l'environnement de test<\/strong><\/a> page. Vous y verrez le compte de test sandbox que vous avez cr\u00e9\u00e9 pr\u00e9c\u00e9demment.\u00a0<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\"><strong>Note<\/strong>: Si vous vous \u00eates d\u00e9connect\u00e9 pr\u00e9c\u00e9demment, reconnectez-vous \u00e0 votre compte. <strong>Console de d\u00e9veloppement Square<\/strong>. Cliquez sur l'ic\u00f4ne <strong>Comptes de test dans l'environnement de test<\/strong> dans le menu de gauche pour acc\u00e9der \u00e0 la rubrique <a href=\"https:\/\/developer.squareup.com\/console\/en\/sandbox-test-accounts\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>Comptes de test dans l'environnement de test<\/strong><\/a> page.<\/p>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li>Cliquez sur le bouton <strong>Tableau de bord carr\u00e9<\/strong> pour ce compte test afin d'acc\u00e9der \u00e0 votre tableau de bord Square Sandbox.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04a2559f451\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04a2559f451\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2558\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard.png\" alt=\"\" class=\"wp-image-73317\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard.png 2558w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-1536x790.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-1832x942.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-sandbox-dashboard-1080x556.png 1080w\" sizes=\"(max-width: 2558px) 100vw, 2558px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-danger\"><strong>Note<\/strong>: Gardez le <strong>avec le tableau de bord Square Sandbox ouvert lors de la connexion<\/strong> MemberPress \u00e0 votre bac \u00e0 sable Square. Sinon, Square affichera un \u00e9cran blanc vierge lors de la tentative de connexion.<\/p>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>Ensuite, ouvrez un autre onglet dans votre navigateur et connectez-vous \u00e0 votre site web.<\/li>\n\n\n\n<li>Acc\u00e9dez \u00e0 votre passerelle de paiement Square \u00e0 l'adresse suivante <strong>Tableau de bord &gt; MemberPress &gt; Param\u00e8tres &gt; Paiements<\/strong> tabulation.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04a2559fc7e\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04a2559fc7e\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox.png\" alt=\"\" class=\"wp-image-73318\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-connect-with-square-sandbox-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"5\" class=\"wp-block-list\">\n<li>Dans le cadre de la <strong>Bac \u00e0 sable <\/strong>Cliquez sur la section <strong>Se connecter avec Square Sandbox<\/strong> bouton.<\/li>\n\n\n\n<li>Ensuite, vous devez autoriser votre plugin MemberPress \u00e0 acc\u00e9der \u00e0 votre Square Sandbox. Cliquez sur <strong>Autoriser <\/strong>pour accepter les autorisations et terminer la connexion.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04a255a000b\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04a255a000b\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2544\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM.png\" alt=\"\" class=\"wp-image-73319\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM.png 2544w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-300x155.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-1024x530.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-768x397.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-1536x795.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-2048x1059.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-329x170.png 329w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-840x435.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-1216x629.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-1832x948.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-700x362.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-156x81.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/Image-2025-05-30-at-111545-PM-1080x559.png 1080w\" sizes=\"(max-width: 2544px) 100vw, 2544px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"7\" class=\"wp-block-list\">\n<li>Vous serez redirig\u00e9 vers la page de configuration de MemberPress. Votre Square Sandbox devrait maintenant \u00eatre connect\u00e9 \u00e0 MemberPress. Si le processus a r\u00e9ussi, vous verrez le statut \"<strong>Connect\u00e9<\/strong>\"<strong> <\/strong>dans la section Sandbox de votre passerelle Square.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04a255a032c\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04a255a032c\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox.png\" alt=\"\" class=\"wp-image-73320\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-use-square-sandbox-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"8\" class=\"wp-block-list\">\n<li>V\u00e9rifier le <strong>Utiliser le bac \u00e0 sable carr\u00e9<\/strong> pour autoriser les paiements de test avec l'Environnement de test.<\/li>\n\n\n\n<li>Cliquez sur le bouton <strong>Options de mise \u00e0 jour<\/strong> pour enregistrer vos param\u00e8tres.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"testing\"><strong><a href=\"#testing\" title=\"\">Test avec Square Sandbox<\/a><\/strong><\/h2>\n\n\n\n<p>Avant d'accepter des paiements en direct, testez votre connexion en utilisant l'environnement Sandbox de Square.<\/p>\n\n\n\n<p>Une fois connect\u00e9 \u00e0 l'Environnement de test, vous pouvez commencer \u00e0 tester les paiements Square :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Cr\u00e9er un <strong>tester l'adh\u00e9sion<\/strong>.<\/li>\n\n\n\n<li><strong>Acc\u00e9der \u00e0 la page d'inscription<\/strong> de votre adh\u00e9sion au test. Ici, <strong>soumettre une inscription \u00e0 un test<\/strong> en utilisant le <strong>Carr\u00e9 <\/strong>option de paiement.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04a255a076c\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04a255a076c\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2543\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1.png\" alt=\"\" class=\"wp-image-73321\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1.png 2543w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-300x155.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-1024x530.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-768x397.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-1536x795.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-2048x1060.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-329x170.png 329w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-840x435.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-1216x629.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-1832x948.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-700x362.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-156x81.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-payments-1-1080x559.png 1080w\" sizes=\"(max-width: 2543px) 100vw, 2543px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>Utilisation <a href=\"https:\/\/developer.squareup.com\/docs\/devtools\/sandbox\/payments#card-not-present-success-state-values\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>Les num\u00e9ros de carte test de Square<\/strong><\/a> pour effectuer le paiement de l'inscription \u00e0 l'examen.<\/li>\n\n\n\n<li>V\u00e9rifier que le <a href=\"https:\/\/memberpress.com\/fr\/docs\/using-the-transactions-page\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>la transaction est enregistr\u00e9e correctement dans MemberPress<\/strong><\/a>. Dans le cas d'abonnements r\u00e9currents, v\u00e9rifiez \u00e9galement que les <a href=\"https:\/\/memberpress.com\/fr\/docs\/using-the-subscriptions-page\/\"><strong>L'abonnement a \u00e9t\u00e9 c<\/strong><\/a><strong><a href=\"https:\/\/memberpress.com\/fr\/docs\/using-the-subscriptions-page\/\" target=\"_blank\" rel=\"noopener\" title=\"\">r<\/a><\/strong><a href=\"https:\/\/memberpress.com\/fr\/docs\/using-the-subscriptions-page\/\"><strong>consomm\u00e9 correctement<\/strong><\/a>.<\/li>\n\n\n\n<li>Ensuite, v\u00e9rifiez que le <strong>est \u00e9galement visible dans votre<\/strong> <a href=\"https:\/\/app.squareupsandbox.com\/dashboard\/sales\/transactions\"><strong>Square S<\/strong><\/a><strong><a href=\"https:\/\/app.squareupsandbox.com\/dashboard\/sales\/transactions\" target=\"_blank\" rel=\"noopener\" title=\"\">a<\/a><\/strong><a href=\"https:\/\/app.squareupsandbox.com\/dashboard\/sales\/transactions\"><strong>Page Transactions ndbox<\/strong><\/a>.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a04a255a0ad0\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04a255a0ad0\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2558\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions.png\" alt=\"\" class=\"wp-image-73322\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions.png 2558w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-1536x790.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-1832x942.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-dashboard-transactions-1080x556.png 1080w\" sizes=\"(max-width: 2558px) 100vw, 2558px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>La connexion fonctionne correctement si les transactions (et les abonnements pour les adh\u00e9sions r\u00e9currentes) sont correctement enregistr\u00e9es dans MemberPress et Square Sandbox.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"switch-to-live\"><strong><a href=\"#switch-to-live\" title=\"\">Passer aux paiements en direct<\/a><\/strong><\/h3>\n\n\n\n<p>Une fois les tests r\u00e9ussis, vous pouvez activer les paiements en direct :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Naviguez jusqu'\u00e0 <strong>Tableau de bord &gt; MemberPress &gt; Param\u00e8tres &gt; Paiements<\/strong> tabulation.<\/li>\n\n\n\n<li>Dans le cadre de la <strong>Production <\/strong>de votre passerelle Square, <a href=\"https:\/\/memberpress.com\/fr\/docs\/connect-square-to-memberpress\/#square-production\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>connecter votre compte marchand Square pour permettre les paiements en direct<\/strong><\/a>.<\/li>\n\n\n\n<li>D\u00e9cochez la case <strong>Utiliser le bac \u00e0 sable carr\u00e9<\/strong> case \u00e0 cocher.<\/li>\n\n\n\n<li>Cliquez sur <strong>Options de mise \u00e0 jour<\/strong> pour enregistrer vos modifications.<\/li>\n<\/ol>\n\n\n\n<p>D\u00e9sormais, les utilisateurs peuvent s'inscrire \u00e0 vos adh\u00e9sions et payer par l'interm\u00e9diaire de Square.<\/p>","protected":false},"excerpt":{"rendered":"<p>Testing payment processing before going live ensures your membership site works correctly without processing real transactions. Square provides a sandbox environment that lets you simulate payments and test your MemberPress integration safely.\u00a0 This document explains how to set up and test Square\u2019s sandbox mode with MemberPress before accepting real payments from members. What Is Square [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1511],"ht-kb-tag":[],"class_list":{"0":"post-73314","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-square","7":"entry","8":"has-post-thumbnail"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Testing payment processing before going live ensures your membership site works correctly without processing real transactions. Square provides a sandbox environment that lets you simulate payments and test your MemberPress integration safely. This document explains how to set up and test Square&#039;s sandbox mode with MemberPress before accepting real payments from members. Note: This payment integration\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Connect and Test Square Sandbox With MemberPress | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"Testing payment processing before going live ensures your membership site works correctly without processing real transactions. Square provides a sandbox environment that lets you simulate payments and test your MemberPress integration safely. This document explains how to set up and test Square&#039;s sandbox mode with MemberPress before accepting real payments from members. Note: This payment integration\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-05-30T22:51:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-27T14:02:41+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Connect and Test Square Sandbox With MemberPress | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Testing payment processing before going live ensures your membership site works correctly without processing real transactions. Square provides a sandbox environment that lets you simulate payments and test your MemberPress integration safely. This document explains how to set up and test Square&#039;s sandbox mode with MemberPress before accepting real payments from members. Note: This payment integration\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/#article\",\"name\":\"Connect and Test Square Sandbox With MemberPress | MemberPress\",\"headline\":\"Connect and Test Square Sandbox With MemberPress\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/mepr-square-new-sandbox-test-account.png\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/#articleImage\",\"width\":2558,\"height\":1316},\"datePublished\":\"2025-05-30T18:51:31-04:00\",\"dateModified\":\"2025-10-27T10:02:41-04:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/#webpage\"},\"articleSection\":\"Square\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/registration-and-payments\\\/#listItem\",\"name\":\"Registration and Payments\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/registration-and-payments\\\/#listItem\",\"position\":3,\"name\":\"Registration and Payments\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/registration-and-payments\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/square\\\/#listItem\",\"name\":\"Square\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/square\\\/#listItem\",\"position\":4,\"name\":\"Square\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/square\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/#listItem\",\"name\":\"Connect and Test Square Sandbox With MemberPress\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/registration-and-payments\\\/#listItem\",\"name\":\"Registration and Payments\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/#listItem\",\"position\":5,\"name\":\"Connect and Test Square Sandbox With MemberPress\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/square\\\/#listItem\",\"name\":\"Square\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/\",\"name\":\"Connect and Test Square Sandbox With MemberPress | MemberPress\",\"description\":\"Testing payment processing before going live ensures your membership site works correctly without processing real transactions. Square provides a sandbox environment that lets you simulate payments and test your MemberPress integration safely. This document explains how to set up and test Square's sandbox mode with MemberPress before accepting real payments from members. Note: This payment integration\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/square-sandbox-with-memberpress\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2025-05-30T18:51:31-04:00\",\"dateModified\":\"2025-10-27T10:02:41-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Connect and Test Square Sandbox With MemberPress | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Connecter et tester Square Sandbox avec MemberPress | MemberPress","description":"Tester le traitement des paiements avant la mise en service permet de s'assurer que votre site d'affiliation fonctionne correctement sans traiter de transactions r\u00e9elles. Square fournit un environnement de bac \u00e0 sable qui vous permet de simuler des paiements et de tester votre int\u00e9gration MemberPress en toute s\u00e9curit\u00e9. Ce document explique comment configurer et tester le mode bac \u00e0 sable de Square avec MemberPress avant d'accepter des paiements r\u00e9els de la part des membres. Note : Cette int\u00e9gration de paiement","canonical_url":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/#article","name":"Connect and Test Square Sandbox With MemberPress | MemberPress","headline":"Connect and Test Square Sandbox With MemberPress","author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/05\/mepr-square-new-sandbox-test-account.png","@id":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/#articleImage","width":2558,"height":1316},"datePublished":"2025-05-30T18:51:31-04:00","dateModified":"2025-10-27T10:02:41-04:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/#webpage"},"articleSection":"Square"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","position":2,"name":"General","item":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/#listItem","name":"Registration and Payments"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/#listItem","position":3,"name":"Registration and Payments","item":"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/square\/#listItem","name":"Square"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/square\/#listItem","position":4,"name":"Square","item":"https:\/\/memberpress.com\/fr\/doc-categories\/square\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/#listItem","name":"Connect and Test Square Sandbox With MemberPress"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/#listItem","name":"Registration and Payments"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/#listItem","position":5,"name":"Connect and Test Square Sandbox With MemberPress","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/square\/#listItem","name":"Square"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/fr\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/#webpage","url":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/","name":"Connect and Test Square Sandbox With MemberPress | MemberPress","description":"Testing payment processing before going live ensures your membership site works correctly without processing real transactions. Square provides a sandbox environment that lets you simulate payments and test your MemberPress integration safely. This document explains how to set up and test Square's sandbox mode with MemberPress before accepting real payments from members. Note: This payment integration","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2025-05-30T18:51:31-04:00","dateModified":"2025-10-27T10:02:41-04:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/fr\/#website","url":"https:\/\/memberpress.com\/fr\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"MemberPress","og:type":"article","og:title":"Connect and Test Square Sandbox With MemberPress | MemberPress","og:description":"Testing payment processing before going live ensures your membership site works correctly without processing real transactions. Square provides a sandbox environment that lets you simulate payments and test your MemberPress integration safely. This document explains how to set up and test Square's sandbox mode with MemberPress before accepting real payments from members. Note: This payment integration","og:url":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2025-05-30T22:51:31+00:00","article:modified_time":"2025-10-27T14:02:41+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Connect and Test Square Sandbox With MemberPress | MemberPress","twitter:description":"Testing payment processing before going live ensures your membership site works correctly without processing real transactions. Square provides a sandbox environment that lets you simulate payments and test your MemberPress integration safely. This document explains how to set up and test Square's sandbox mode with MemberPress before accepting real payments from members. Note: This payment integration","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"73314","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-27 14:03:17","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-05-30 22:34:14","updated":"2026-03-03 14:49:47"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/general\/\" title=\"General\">General<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/\" title=\"Registration and Payments\">Registration and Payments<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/square\/\" title=\"Square\">Square<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tConnect and Test Square Sandbox With MemberPress\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/fr"},{"label":"General","link":"https:\/\/memberpress.com\/fr\/doc-categories\/general\/"},{"label":"Registration and Payments","link":"https:\/\/memberpress.com\/fr\/doc-categories\/registration-and-payments\/"},{"label":"Square","link":"https:\/\/memberpress.com\/fr\/doc-categories\/square\/"},{"label":"Connect and Test Square Sandbox With MemberPress","link":"https:\/\/memberpress.com\/fr\/docs\/square-sandbox-with-memberpress\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/73314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/comments?post=73314"}],"version-history":[{"count":6,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/73314\/revisions"}],"predecessor-version":[{"id":75646,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/73314\/revisions\/75646"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/media?parent=73314"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category?post=73314"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-tag?post=73314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}