{"id":76458,"date":"2025-11-21T10:22:38","date_gmt":"2025-11-21T15:22:38","guid":{"rendered":"https:\/\/memberpress.com\/?post_type=ht_kb&#038;p=76458"},"modified":"2025-12-05T02:48:16","modified_gmt":"2025-12-05T07:48:16","slug":"designing-member-profiles","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/","title":{"rendered":"Conception des profils MemberPress"},"content":{"rendered":"<p>Vous pouvez concevoir des profils MemberPress <strong>en utilisant des mod\u00e8les de d\u00e9part pr\u00e9\u00e9tablis ou en cr\u00e9ant votre propre mod\u00e8le personnalis\u00e9<\/strong>. Les profils MemberPress sont <strong>Bas\u00e9 sur Gutenberg<\/strong>, ce qui signifie que vous pouvez concevoir des profils avec <strong>les blocs sp\u00e9cifiques au profil et tout autre bloc Gutenberg<\/strong>.\u00a0<\/p>\n\n\n\n<p>Ce document explique comment vous pouvez concevoir des profils MemberPress adapt\u00e9s \u00e0 votre site web et \u00e0 votre image de marque, <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"starter-patterns\"><a href=\"#starter-patterns\" title=\"\">Utilisation des mod\u00e8les de d\u00e9part de profil<\/a><\/h3>\n\n\n\n<p>MemberPress comprend quatre mod\u00e8les de profils professionnels comme points de d\u00e9part :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Profil classique<\/strong> positionne la photo et le nom du membre \u00e0 gauche de l'en-t\u00eate du profil. Toutes les autres informations relatives au membre sont align\u00e9es \u00e0 gauche ;<\/li>\n\n\n\n<li><strong>Profil classique \u2013 Droite <\/strong>refl\u00e8te l'en-t\u00eate du mod\u00e8le classique, avec la photo et le nom du membre. Toutes les autres informations relatives aux membres restent align\u00e9es \u00e0 gauche ;<\/li>\n\n\n\n<li><strong>Profil classique \u2013 Centr\u00e9<\/strong> aligne la photo de profil et le nom du membre au centre, toutes les informations \u00e9tant align\u00e9es  \u00e0 gauche ;<\/li>\n\n\n\n<li><strong>Sch\u00e9ma de fractionnement des profils<\/strong> divise les profils en trois sections distinctes. L'en-t\u00eate du profil se trouve en haut de la page, et le reste de la page est divis\u00e9 en deux sections : gauche et droite. Ici, la photo et le nom du membre se trouvent \u00e0 gauche. Les autres informations relatives au membre se trouvent \u00e0 droite.<\/li>\n<\/ul>\n\n\n\n<p>Lors de l'ajout d'un nouveau type de profil, vous serez invit\u00e9 \u00e0 choisir l'un des mod\u00e8les de d\u00e9part disponibles.\u00a0<\/p>\n\n\n\n<p>S'ils sont ignor\u00e9s, vous pouvez ajouter ces motifs \u00e0 l'aide de l'outil d'insertion de blocs :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Naviguez jusqu'au type de profil, survolez son nom et cliquez sur <strong>Editer<\/strong>.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c28748a8\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c28748a8\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1315\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile.png\" alt=\"\" class=\"wp-image-75892\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-1536x790.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-2048x1053.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-331x170.png 331w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-1216x625.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-1832x942.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile-1080x555.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li>Cliquez sur l'outil d'insertion de blocs <strong>+ ic\u00f4ne<\/strong>.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c2874c85\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c2874c85\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter.png\" alt=\"\" class=\"wp-image-75893\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-block-inserter-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>Ensuite, cliquez sur le bouton <strong>Mod\u00e8les <\/strong>et descendez jusqu'\u00e0 l'onglet <strong>Contenu de l'article<\/strong> groupe.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c2874fa9\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c2874fa9\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns.png\" alt=\"\" class=\"wp-image-75894\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-insert-profile-starter-patterns-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><strong>S\u00e9lectionner <\/strong>le motif de votre choix pour l'ajouter au profil.<\/li>\n<\/ol>\n\n\n\n<p>Les motifs sont des groupes de blocs de profil. Vous pouvez ajouter ou supprimer des blocs de profil, ajouter des blocs Gutneberg suppl\u00e9mentaires et personnaliser chaque bloc pour qu'il corresponde \u00e0 votre marque.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"profile-blocks\"><a href=\"#profile-blocks\" title=\"\">Travailler avec des blocs de profil<\/a><\/h3>\n\n\n\n<p>Les blocs Profil sont des composants individuels que vous pouvez utiliser pour concevoir les profils de vos membres \u00e0 l'aide de l'\u00e9diteur par d\u00e9faut (Gutenberg).\u00a0<\/p>\n\n\n\n<p>Chaque bloc de profil MemberPress est utilis\u00e9 pour afficher des donn\u00e9es sp\u00e9cifiques aux membres sur les pages de profil des utilisateurs et est assorti d'options de personnalisation \u00e9tendues :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les <strong>Bloc d'en-t\u00eate de profil<\/strong> s'\u00e9tend sur toute la largeur de la carte de profil. Configurez les couleurs d'arri\u00e8re-plan, activez les images de couverture, contr\u00f4lez la hauteur et ajoutez des superpositions pour la lisibilit\u00e9 du texte.<\/li>\n\n\n\n<li><strong>Blocs de profil\u00e9s<\/strong> organiser le contenu en groupes logiques. Ajoutez des titres, personnalisez les arri\u00e8re-plans, contr\u00f4lez le remplissage et appliquez des bordures pour une s\u00e9paration visuelle.<\/li>\n\n\n\n<li>Les <strong>Bloc photo du profil<\/strong> affiche les images des membres avec des contr\u00f4les de taille, des options de forme (carr\u00e9e, arrondie, circulaire), des traitements de bordure et des images de repli pour les membres sans photo.<\/li>\n\n\n\n<li><strong>Blocs de recouvrement de profil\u00e9s<\/strong> afficher des images de banni\u00e8res, ce qui permet une expression personnelle. D\u00e9finissez des couvertures par d\u00e9faut, contr\u00f4lez les dimensions, ajustez le positionnement et ajoutez des superpositions pour garantir la visibilit\u00e9 du contenu.<\/li>\n\n\n\n<li>Les <strong>Bloc de noms de profil<\/strong> pr\u00e9sente les identit\u00e9s des membres avec des options de format allant du pr\u00e9nom seul aux noms complets formels, ainsi que des contr\u00f4les typographiques et du texte suppl\u00e9mentaire pour les titres.<\/li>\n\n\n\n<li><strong>Blocs d'ic\u00f4nes de profil<\/strong> ajouter n'importe quelle ic\u00f4ne \u00e0 vos profils. Utilisez ce bloc pour ajouter des ic\u00f4nes aux titres ou \u00e0 n'importe quel endroit de la page de profil. Vous pouvez choisir n'importe quelle ic\u00f4ne disponible et d\u00e9finir sa taille, son espacement et ses couleurs.<\/li>\n\n\n\n<li><strong>Profil Champs d'utilisateur Blocs<\/strong> afficher des informations provenant des profils des membres et des champs personnalis\u00e9s. S\u00e9lectionnez les champs qui apparaissent, contr\u00f4lez les \u00e9tiquettes, organisez-les en colonnes ou en listes et g\u00e9rez intelligemment les champs vides.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Champs de l'utilisateur du profil<\/h3>\n\n\n\n<p>Les <strong>Bloc de champs de l'utilisateur du profil<\/strong> ajoute dynamiquement les donn\u00e9es de l'utilisateur \u00e0 son profil MemberPress. Vous pouvez utiliser ce bloc dans les blocs de la section Profil ou \u00e0 tout autre endroit de la page de profil.<\/p>\n\n\n\n<p>Pour importer un seul \u00e9l\u00e9ment d'information sur un utilisateur dans un profil, vous devez ajouter et configurer le bloc :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Lors de la modification d'un profil, <strong>ajouter le bloc Champ d'utilisateur du profil<\/strong> \u00e0 l'aide du dispositif d'insertion de blocs.<\/li>\n\n\n\n<li><strong>Cliquez sur le bloc<\/strong> vous avez ins\u00e9r\u00e9 pour ouvrir son <strong>Param\u00e8tres <\/strong>dans le panneau de droite.<\/li>\n\n\n\n<li>Configurez le bloc \u00e0 l'aide de la fonction <strong>Param\u00e8tres de champ<\/strong> panneau :\n<ul class=\"wp-block-list\">\n<li><strong>Champ d'application<\/strong>: choisissez le champ MemberPress dans cette liste d\u00e9roulante. En cons\u00e9quence, le bloc affichera les donn\u00e9es du champ s\u00e9lectionn\u00e9 sur la page de profil. Par exemple, pour afficher le nom d'utilisateur d'un utilisateur sur son profil, choisissez Nom d'utilisateur dans cette liste d\u00e9roulante ;<\/li>\n\n\n\n<li><strong>Afficher l'\u00e9tiquette<\/strong>Cette option est activ\u00e9e par d\u00e9faut. Ainsi, l'\u00e9tiquette du champ sera affich\u00e9e sur le profil des utilisateurs avec les donn\u00e9es du champ. Si vous d\u00e9sactivez cette option, ce bloc n'affichera que les donn\u00e9es ;<\/li>\n\n\n\n<li><strong>Texte de l'\u00e9tiquette<\/strong>Le texte de l'\u00e9tiquette : vous pouvez ajouter un texte d'\u00e9tiquette personnalis\u00e9 \u00e0 ce champ pour l'afficher \u00e0 la place de l'\u00e9tiquette par d\u00e9faut.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c28755c6\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c28755c6\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2556\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings.png\" alt=\"\" class=\"wp-image-76571\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings.png 2556w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-field-settings-1080x556.png 1080w\" sizes=\"(max-width: 2556px) 100vw, 2556px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><strong>\u00c9conomiser <\/strong>pour les appliquer aux profils des utilisateurs.<\/li>\n<\/ol>\n\n\n\n<p>En utilisant ce bloc, vous pouvez ajouter n'importe quel <strong>par d\u00e9faut ou <a href=\"https:\/\/memberpress.com\/fr\/docs\/fields\/\" target=\"_blank\" rel=\"noopener\" title=\"\">champ personnalis\u00e9 MemberPress<\/a><\/strong> utilis\u00e9e sur vos pages d'inscription et de compte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ajout et configuration de l'en-t\u00eate du profil<\/h2>\n\n\n\n<p>MemberPress <strong>En-t\u00eate de profil<\/strong> importe l'en-t\u00eate de profil par d\u00e9faut dans vos profils. Il a d\u00e9j\u00e0 <strong>comprend une couverture de profil<\/strong> et <strong>Photo de profil<\/strong> blocs et <strong>soutient les liens vers les m\u00e9dias sociaux<\/strong>.<\/p>\n\n\n\n<p>Pour ajouter et configurer l'en-t\u00eate de profil, proc\u00e9dez comme suit :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Commencez \u00e0 modifier votre profil.<\/li>\n\n\n\n<li>Cliquez sur l'outil d'insertion de blocs et recherchez \u201cEn-t\u00eate de profil\u201d. Cliquez sur l'ic\u00f4ne<strong> En-t\u00eate de profil <\/strong>pour l'importer.<\/li>\n\n\n\n<li>Une fois import\u00e9, cliquez sur le bloc pour ouvrir ses param\u00e8tres. Sous les param\u00e8tres du bloc, d\u00e9finissez le param\u00e8tre <strong>Positionnement des photos<\/strong> \u00e0 <strong>Gauche<\/strong>, <strong>Centre, <\/strong>ou <strong>Droit<\/strong>.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c2875a5c\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c2875a5c\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2556\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings.png\" alt=\"\" class=\"wp-image-76577\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings.png 2556w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-settings-1080x556.png 1080w\" sizes=\"(max-width: 2556px) 100vw, 2556px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"5\" class=\"wp-block-list\">\n<li>Vous pouvez \u00e9galement choisir d'activer ou de d\u00e9sactiver la fonction <strong>Activer le chevauchement<\/strong> (option). Par d\u00e9faut, cette option est activ\u00e9e, ce qui permet \u00e0 la photo de profil de se superposer \u00e0 l'image de couverture.<\/li>\n\n\n\n<li>Enfin, vous pouvez <strong>style de l'en-t\u00eate<\/strong>. Cliquez sur le bouton <strong>Onglet Style <\/strong>pour acc\u00e9der aux options de style.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c2875de4\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c2875de4\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2556\" height=\"1315\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles.png\" alt=\"\" class=\"wp-image-76578\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles.png 2556w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-1536x790.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-styles-1080x556.png 1080w\" sizes=\"(max-width: 2556px) 100vw, 2556px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"7\" class=\"wp-block-list\">\n<li>Cliquez sur <strong>Publier <\/strong>\/ <strong>\u00c9conomiser <\/strong>pour appliquer les modifications.<\/li>\n<\/ol>\n\n\n\n<p>Vous pouvez \u00e9galement ajouter <strong>Couverture du profil<\/strong> et <strong>Photo de profil<\/strong> individuellement au lieu d'utiliser les blocs <strong>En-t\u00eate de profil<\/strong> bloc. Vous pouvez utiliser cette m\u00e9thode si vous construisez un profil personnalis\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conception de l'en-t\u00eate du profil<\/h3>\n\n\n\n<p>Quand <strong>styliser l'en-t\u00eate de votre profil<\/strong>, Vous pouvez configurer les blocs suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>En-t\u00eate de profil<\/strong> bloc :\n<ul class=\"wp-block-list\">\n<li><strong>Styles<\/strong>: choisir l'un des quatre en-t\u00eates disponibles <strong>styles <\/strong>(Normal, Avec ombre, Avec bordure ou Bordure inf\u00e9rieure) ;<\/li>\n\n\n\n<li><strong>Couleur<\/strong>: d\u00e9finit les couleurs de l'arri\u00e8re-plan et du texte de l'en-t\u00eate ;<\/li>\n\n\n\n<li><strong>Dimensions<\/strong>: personnaliser l'en-t\u00eate <strong>rembourrage <\/strong>et <strong>marges<\/strong>;<\/li>\n\n\n\n<li><strong>Ombre<\/strong>: d\u00e9finir l'ombre de l'en-t\u00eate en cliquant sur le bouton <strong>Ombre port\u00e9e<\/strong> option.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c287626b\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c287626b\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design.png\" alt=\"\" class=\"wp-image-76579\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-header-design-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Couverture du profil<\/strong> bloc :\n<ul class=\"wp-block-list\">\n<li><strong>Point focal<\/strong>: d\u00e9placez le point focal sur la section souhait\u00e9e de votre image de couverture ;<\/li>\n\n\n\n<li><strong>Dimensions du couvercle<\/strong>: mettre en place le couvercle <strong>Hauteur <\/strong>(court, moyen ou grand) ;<\/li>\n\n\n\n<li><strong>Param\u00e8tres de superposition<\/strong>: ajoutez une superposition en d\u00e9finissant le param\u00e8tre <strong>Opacit\u00e9 <\/strong>pourcentage.<\/li>\n\n\n\n<li><strong>Param\u00e8tres de couleur<\/strong>: d\u00e9finir les <strong>Couleur de la superposition<\/strong>.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c287660f\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c287660f\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design.png\" alt=\"\" class=\"wp-image-76580\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-cover-design-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Ajout et configuration de sections et de donn\u00e9es<\/h2>\n\n\n\n<p>Le MemberPress <strong>Section du profil <\/strong>est utilis\u00e9 pour regrouper les champs de donn\u00e9es utilisateur et tout autre bloc suppl\u00e9mentaire.<\/p>\n\n\n\n<p>Pour ajouter et configurer la section profil, proc\u00e9dez comme suit :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Commencez \u00e0 modifier votre profil.<\/li>\n\n\n\n<li>Cliquez sur l'outil d'insertion de blocs et recherchez \u201cSection du profil\u201d. Cliquez sur l'ic\u00f4ne <strong>Section du profil <\/strong>pour l'importer.<\/li>\n\n\n\n<li>Cliquez sur le bloc que vous avez import\u00e9. Dans le panneau de droite, cliquez sur le bouton <strong>Param\u00e8tres <\/strong>tabulation.<\/li>\n<\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c2876a11\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c2876a11\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2557\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings.png\" alt=\"\" class=\"wp-image-76581\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings.png 2557w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-settings-1080x556.png 1080w\" sizes=\"(max-width: 2557px) 100vw, 2557px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"5\" class=\"wp-block-list\">\n<li>\u00c9largir le <strong>Param\u00e8tres de mise en page<\/strong> et d\u00e9finissez le <strong>Disposition des champs :<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>En ligne<\/strong>: cette option permet d'afficher l'\u00e9tiquette du champ et les donn\u00e9es sur la m\u00eame ligne ;<\/li>\n\n\n\n<li><strong>Empil\u00e9s<\/strong>: cette option permet d'empiler l'\u00e9tiquette et les donn\u00e9es du champ, en affichant les donn\u00e9es sous l'\u00e9tiquette.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Par d\u00e9faut, le bloc de la section profil sera <strong>import\u00e9 avec un titre par d\u00e9faut et plusieurs champs de donn\u00e9es de profil<\/strong>. Vous pouvez modifier le contenu par d\u00e9faut si n\u00e9cessaire :\n<ul class=\"wp-block-list\">\n<li>Mise \u00e0 jour<strong> <\/strong>les <strong>rubrique <\/strong>et <strong>ic\u00f4ne d'en-t\u00eate<\/strong>;<\/li>\n\n\n\n<li><strong>Mettre \u00e0 jour les champs de l'utilisateur du profil<\/strong> en choisissant les champs MemberPress dont vous avez besoin, et\/ou ajoutez les champs personnalis\u00e9s. <strong>texte de l'\u00e9tiquette<\/strong>;<\/li>\n\n\n\n<li><strong>Ajouter de nouveaux blocs ou en supprimer<\/strong> ceux dont vous n'avez pas besoin.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Enfin, cliquez sur le bouton <strong>Style<\/strong> <strong>onglet<\/strong> \u00e0 <strong>le style de la section<\/strong>.<\/li>\n<\/ol>\n\n\n\n<ol start=\"7\" class=\"wp-block-list\"><\/ol>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c2876e7f\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c2876e7f\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2556\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles.png\" alt=\"\" class=\"wp-image-76582\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles.png 2556w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-styles-1080x556.png 1080w\" sizes=\"(max-width: 2556px) 100vw, 2556px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ol start=\"8\" class=\"wp-block-list\">\n<li>Cliquez sur <strong>\u00c9conomiser <\/strong>pour appliquer les modifications.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Conception d'une section de profil<\/h3>\n\n\n\n<p>Lors de la cr\u00e9ation de votre section de profil, vous pouvez configurer les blocs suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Section du profil <\/strong>bloc :\n<ul class=\"wp-block-list\">\n<li><strong>Styles<\/strong>: choisissez l'une des quatre sections disponibles <strong>styles <\/strong>(Normal, Avec ombre, Avec bordure ou Bordure inf\u00e9rieure) ;<\/li>\n\n\n\n<li><strong>Couleur<\/strong>: d\u00e9finit les couleurs de l'arri\u00e8re-plan et du texte de la section ;<\/li>\n\n\n\n<li><strong>Dimensions<\/strong>: personnaliser la section <strong>rembourrage <\/strong>et <strong>marges<\/strong>;<\/li>\n\n\n\n<li><strong>Bordure et ombre<\/strong>: d\u00e9finir la section<strong> taille et rayon de la bordure<\/strong>.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c28772e9\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c28772e9\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2556\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design.png\" alt=\"\" class=\"wp-image-76583\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design.png 2556w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-1536x791.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-1832x943.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-section-design-1080x556.png 1080w\" sizes=\"(max-width: 2556px) 100vw, 2556px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Champs de l'utilisateur du profil <\/strong>bloc :\n<ul class=\"wp-block-list\">\n<li><strong>Couleur<\/strong>: d\u00e9finit les couleurs de l'arri\u00e8re-plan et du texte du champ ;<\/li>\n\n\n\n<li><strong>Typographie<\/strong>: d\u00e9finir la police de caract\u00e8res <strong>taille <\/strong>et <strong>hauteur de la ligne<\/strong>.<\/li>\n\n\n\n<li><strong>Fronti\u00e8re<\/strong>: d\u00e9finir le champ <strong>taille de la bordure<\/strong>.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{\"imageid\":\"6a048c287767b\"}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a048c287767b\" class=\"wp-block-image size-full wp-lightbox-container\"><img decoding=\"async\" width=\"2558\" height=\"1316\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design.png\" alt=\"\" class=\"wp-image-76584\" srcset=\"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design.png 2558w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-300x154.png 300w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-1024x527.png 1024w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-768x395.png 768w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-50x26.png 50w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-1536x790.png 1536w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-2048x1054.png 2048w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-330x170.png 330w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-840x432.png 840w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-1216x626.png 1216w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-1832x942.png 1832w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-700x360.png 700w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-156x80.png 156w, https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-profile-user-fields-design-1080x556.png 1080w\" sizes=\"(max-width: 2558px) 100vw, 2558px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>","protected":false},"excerpt":{"rendered":"<p>You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block.\u00a0 This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1525],"ht-kb-tag":[1533],"class_list":{"0":"post-76458","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-clubdirectory","7":"ht_kb_tag-community","8":"entry","9":"has-post-thumbnail"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Designing MemberPress Profiles\" \/>\n\t\t<meta property=\"og:description\" content=\"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-11-21T15:22:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-05T07:48:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Designing MemberPress Profiles\" \/>\n\t\t<meta name=\"twitter:description\" content=\"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/#article\",\"name\":\"Designing MemberPress Profiles\",\"headline\":\"Designing MemberPress Profiles\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/mpdir-edit-profile.png\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/#articleImage\",\"width\":2557,\"height\":1315},\"datePublished\":\"2025-11-21T10:22:38-05:00\",\"dateModified\":\"2025-12-05T02:48:16-05:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/#webpage\"},\"articleSection\":\"ClubDirectory\\u2122, Community\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/add-ons\\\/#listItem\",\"name\":\"Add-ons\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/add-ons\\\/#listItem\",\"position\":2,\"name\":\"Add-ons\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/add-ons\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/community\\\/#listItem\",\"name\":\"Community\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/community\\\/#listItem\",\"position\":3,\"name\":\"Community\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/community\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/clubsuite\\\/#listItem\",\"name\":\"ClubSuite\\u2122\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/add-ons\\\/#listItem\",\"name\":\"Add-ons\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/clubsuite\\\/#listItem\",\"position\":4,\"name\":\"ClubSuite\\u2122\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/clubsuite\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/clubdirectory\\\/#listItem\",\"name\":\"ClubDirectory\\u2122\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/community\\\/#listItem\",\"name\":\"Community\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/clubdirectory\\\/#listItem\",\"position\":5,\"name\":\"ClubDirectory\\u2122\",\"item\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/clubdirectory\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/#listItem\",\"name\":\"Designing MemberPress Profiles\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/clubsuite\\\/#listItem\",\"name\":\"ClubSuite\\u2122\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/#listItem\",\"position\":6,\"name\":\"Designing MemberPress Profiles\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/doc-categories\\\/clubdirectory\\\/#listItem\",\"name\":\"ClubDirectory\\u2122\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/\",\"name\":\"Designing MemberPress Profiles\",\"description\":\"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/docs\\\/designing-member-profiles\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2025-11-21T10:22:38-05:00\",\"dateModified\":\"2025-12-05T02:48:16-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Designing MemberPress Profiles<\/title>\n\n","aioseo_head_json":{"title":"Conception des profils MemberPress","description":"Vous pouvez concevoir des profils MemberPress \u00e0 l'aide de mod\u00e8les de d\u00e9part pr\u00e9d\u00e9finis ou cr\u00e9er votre propre design personnalis\u00e9. Les profils MemberPress sont bas\u00e9s sur Gutenberg, ce qui signifie que vous pouvez concevoir des profils avec des blocs sp\u00e9cifiques au profil et tout autre bloc Gutenberg. Ce document vous expliquera comment concevoir des profils MemberPress adapt\u00e9s \u00e0 votre site web et \u00e0 votre image de marque, \u00e0 l'aide de mod\u00e8les de d\u00e9part de profil MemberPress comprend","canonical_url":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/#article","name":"Designing MemberPress Profiles","headline":"Designing MemberPress Profiles","author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2025\/11\/mpdir-edit-profile.png","@id":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/#articleImage","width":2557,"height":1315},"datePublished":"2025-11-21T10:22:38-05:00","dateModified":"2025-12-05T02:48:16-05:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/#webpage"},"articleSection":"ClubDirectory\u2122, Community"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/add-ons\/#listItem","name":"Add-ons"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/add-ons\/#listItem","position":2,"name":"Add-ons","item":"https:\/\/memberpress.com\/fr\/doc-categories\/add-ons\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/community\/#listItem","name":"Community"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/community\/#listItem","position":3,"name":"Community","item":"https:\/\/memberpress.com\/fr\/doc-categories\/community\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/clubsuite\/#listItem","name":"ClubSuite\u2122"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/add-ons\/#listItem","name":"Add-ons"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/clubsuite\/#listItem","position":4,"name":"ClubSuite\u2122","item":"https:\/\/memberpress.com\/fr\/doc-categories\/clubsuite\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/clubdirectory\/#listItem","name":"ClubDirectory\u2122"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/community\/#listItem","name":"Community"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/clubdirectory\/#listItem","position":5,"name":"ClubDirectory\u2122","item":"https:\/\/memberpress.com\/fr\/doc-categories\/clubdirectory\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/#listItem","name":"Designing MemberPress Profiles"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/clubsuite\/#listItem","name":"ClubSuite\u2122"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/#listItem","position":6,"name":"Designing MemberPress Profiles","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/fr\/doc-categories\/clubdirectory\/#listItem","name":"ClubDirectory\u2122"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/fr\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/#webpage","url":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/","name":"Designing MemberPress Profiles","description":"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/memberpress.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/fr\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2025-11-21T10:22:38-05:00","dateModified":"2025-12-05T02:48:16-05:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/fr\/#website","url":"https:\/\/memberpress.com\/fr\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/memberpress.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"MemberPress","og:type":"article","og:title":"Designing MemberPress Profiles","og:description":"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes","og:url":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2025-11-21T15:22:38+00:00","article:modified_time":"2025-12-05T07:48:16+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Designing MemberPress Profiles","twitter:description":"You can design MemberPress profiles using premade Starter Patterns or create your own custom design. MemberPress Profiles are Gutenberg-based, which means you can design profiles with profile-specific blocks and any other Gutenberg block. This document will explain how you can design MemberPress profiles to fit your webesite and branding, Using Profile Starter Patterns MemberPress includes","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"76458","title":"#post_title","description":"#post_excerpt","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-12-05 07:52:33","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-11-24 15:22:08","updated":"2026-03-03 14:49:46"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/add-ons\/\" title=\"Add-ons\">Add-ons<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/community\/\" title=\"Community\">Community<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/clubsuite\/\" title=\"ClubSuite\u2122\">ClubSuite\u2122<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/fr\/doc-categories\/clubdirectory\/\" title=\"ClubDirectory\u2122\">ClubDirectory\u2122<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tDesigning MemberPress Profiles\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/fr"},{"label":"Add-ons","link":"https:\/\/memberpress.com\/fr\/doc-categories\/add-ons\/"},{"label":"Community","link":"https:\/\/memberpress.com\/fr\/doc-categories\/community\/"},{"label":"ClubSuite\u2122","link":"https:\/\/memberpress.com\/fr\/doc-categories\/clubsuite\/"},{"label":"ClubDirectory\u2122","link":"https:\/\/memberpress.com\/fr\/doc-categories\/clubdirectory\/"},{"label":"Designing MemberPress Profiles","link":"https:\/\/memberpress.com\/fr\/docs\/designing-member-profiles\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/76458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/comments?post=76458"}],"version-history":[{"count":3,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/76458\/revisions"}],"predecessor-version":[{"id":76585,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb\/76458\/revisions\/76585"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/media?parent=76458"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-category?post=76458"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/fr\/wp-json\/wp\/v2\/ht-kb-tag?post=76458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}