{"id":61516,"date":"2024-02-13T07:37:52","date_gmt":"2024-02-13T12:37:52","guid":{"rendered":"https:\/\/memberpress.com\/docs\/do-users-need-to-login-to-memberpress-separately\/"},"modified":"2024-02-13T17:19:06","modified_gmt":"2024-02-13T22:19:06","slug":"do-users-need-to-login-to-memberpress-separately","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/","title":{"rendered":"Os usu\u00e1rios precisam fazer login no MemberPress separadamente?"},"content":{"rendered":"<p>\n\tN\u00e3o. O MemberPress usa o padr\u00e3o <em>Tabela wp_users<\/em> para armazenar as informa\u00e7\u00f5es dos seus usu\u00e1rios. Isso significa que, quando um usu\u00e1rio faz login no seu site, ele est\u00e1 fazendo login em todo o site.<\/p>\n<p>\n\tQuando um usu\u00e1rio est\u00e1 conectado, usamos o MemberPress <a href=\"http:\/\/docs.memberpress.com\/article\/152-rules-overview\" target=\"_blank\" rel=\"noopener\">regras<\/a> para verificar o n\u00edvel de acesso do usu\u00e1rio ao seu conte\u00fado protegido.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>N\u00e3o. O MemberPress usa a tabela padr\u00e3o wp_users para armazenar as informa\u00e7\u00f5es dos seus usu\u00e1rios. Isso significa que, quando um usu\u00e1rio faz login no seu site, ele est\u00e1 fazendo login em todo o site. Depois que o usu\u00e1rio faz login, usamos as regras do MemberPress para verificar o n\u00edvel de acesso desse usu\u00e1rio ao seu conte\u00fado protegido.\u00a0<\/p>","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1288],"ht-kb-tag":[],"class_list":{"0":"post-61516","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-plugin-faqs","7":"entry"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nope. MemberPress uses the standard wp_users table to store your users&#039; information. That means that when a user logs into your site, they&#039;re logging into the whole site. Once a user is logged in, we use MemberPress rules to verify that user&#039;s level of access to your protected content.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Do users need to login to MemberPress separately? | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"Nope. MemberPress uses the standard wp_users table to store your users&#039; information. That means that when a user logs into your site, they&#039;re logging into the whole site. Once a user is logged in, we use MemberPress rules to verify that user&#039;s level of access to your protected content.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T12:37:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-13T22:19:06+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Do users need to login to MemberPress separately? | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nope. MemberPress uses the standard wp_users table to store your users&#039; information. That means that when a user logs into your site, they&#039;re logging into the whole site. Once a user is logged in, we use MemberPress rules to verify that user&#039;s level of access to your protected content.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-users-need-to-login-to-memberpress-separately\\\/#article\",\"name\":\"Do users need to login to MemberPress separately? | MemberPress\",\"headline\":\"Do users need to login to MemberPress separately?\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#articleImage\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"datePublished\":\"2024-02-13T07:37:52-05:00\",\"dateModified\":\"2024-02-13T17:19:06-05:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-users-need-to-login-to-memberpress-separately\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-users-need-to-login-to-memberpress-separately\\\/#webpage\"},\"articleSection\":\"Plugin FAQs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-users-need-to-login-to-memberpress-separately\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/pt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/faqs\\\/#listItem\",\"name\":\"FAQs\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/faqs\\\/#listItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/faqs\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/plugin-faqs\\\/#listItem\",\"name\":\"Plugin FAQs\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/plugin-faqs\\\/#listItem\",\"position\":3,\"name\":\"Plugin FAQs\",\"item\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/plugin-faqs\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-users-need-to-login-to-memberpress-separately\\\/#listItem\",\"name\":\"Do users need to login to MemberPress separately?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/faqs\\\/#listItem\",\"name\":\"FAQs\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-users-need-to-login-to-memberpress-separately\\\/#listItem\",\"position\":4,\"name\":\"Do users need to login to MemberPress separately?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/plugin-faqs\\\/#listItem\",\"name\":\"Plugin FAQs\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-users-need-to-login-to-memberpress-separately\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-users-need-to-login-to-memberpress-separately\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-users-need-to-login-to-memberpress-separately\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-users-need-to-login-to-memberpress-separately\\\/\",\"name\":\"Do users need to login to MemberPress separately? | MemberPress\",\"description\":\"Nope. MemberPress uses the standard wp_users table to store your users' information. That means that when a user logs into your site, they're logging into the whole site. Once a user is logged in, we use MemberPress rules to verify that user's level of access to your protected content.\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-users-need-to-login-to-memberpress-separately\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-02-13T07:37:52-05:00\",\"dateModified\":\"2024-02-13T17:19:06-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Do users need to login to MemberPress separately? | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Os usu\u00e1rios precisam fazer login no MemberPress separadamente? | MemberPress","description":"N\u00e3o. O MemberPress usa a tabela wp_users padr\u00e3o para armazenar as informa\u00e7\u00f5es de seus usu\u00e1rios. Isso significa que quando um usu\u00e1rio faz login no seu site, ele est\u00e1 fazendo login no site inteiro. Quando um usu\u00e1rio est\u00e1 conectado, usamos as regras do MemberPress para verificar o n\u00edvel de acesso desse usu\u00e1rio ao seu conte\u00fado protegido.","canonical_url":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/#article","name":"Do users need to login to MemberPress separately? | MemberPress","headline":"Do users need to login to MemberPress separately?","author":{"@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/pt\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/pt\/#articleImage","width":1650,"height":1275,"caption":"memberpress logo icon"},"datePublished":"2024-02-13T07:37:52-05:00","dateModified":"2024-02-13T17:19:06-05:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/#webpage"},"articleSection":"Plugin FAQs"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/pt","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/#listItem","name":"FAQs"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/#listItem","position":2,"name":"FAQs","item":"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/#listItem","name":"Plugin FAQs"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/#listItem","position":3,"name":"Plugin FAQs","item":"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/#listItem","name":"Do users need to login to MemberPress separately?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/#listItem","name":"FAQs"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/#listItem","position":4,"name":"Do users need to login to MemberPress separately?","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/#listItem","name":"Plugin FAQs"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/pt\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/pt\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/#webpage","url":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/","name":"Do users need to login to MemberPress separately? | MemberPress","description":"Nope. MemberPress uses the standard wp_users table to store your users' information. That means that when a user logs into your site, they're logging into the whole site. Once a user is logged in, we use MemberPress rules to verify that user's level of access to your protected content.","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/memberpress.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-02-13T07:37:52-05:00","dateModified":"2024-02-13T17:19:06-05:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/pt\/#website","url":"https:\/\/memberpress.com\/pt\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/memberpress.com\/pt\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"MemberPress","og:type":"article","og:title":"Do users need to login to MemberPress separately? | MemberPress","og:description":"Nope. MemberPress uses the standard wp_users table to store your users' information. That means that when a user logs into your site, they're logging into the whole site. Once a user is logged in, we use MemberPress rules to verify that user's level of access to your protected content.","og:url":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-02-13T12:37:52+00:00","article:modified_time":"2024-02-13T22:19:06+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Do users need to login to MemberPress separately? | MemberPress","twitter:description":"Nope. MemberPress uses the standard wp_users table to store your users' information. That means that when a user logs into your site, they're logging into the whole site. Once a user is logged in, we use MemberPress rules to verify that user's level of access to your protected content.","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"61516","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-09 21:38:11","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2024-02-13 12:37:52","updated":"2026-03-03 14:53:49"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/pt\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/\" title=\"FAQs\">FAQs<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/\" title=\"Plugin FAQs\">Plugin FAQs<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tDo users need to login to MemberPress separately?\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/pt"},{"label":"FAQs","link":"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/"},{"label":"Plugin FAQs","link":"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/"},{"label":"Do users need to login to MemberPress separately?","link":"https:\/\/memberpress.com\/pt\/docs\/do-users-need-to-login-to-memberpress-separately\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb\/61516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/comments?post=61516"}],"version-history":[{"count":0,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb\/61516\/revisions"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/media?parent=61516"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb-category?post=61516"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb-tag?post=61516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}