{"id":61520,"date":"2024-02-13T07:38:00","date_gmt":"2024-02-13T12:38:00","guid":{"rendered":"https:\/\/memberpress.com\/docs\/reminders-case-examples\/"},"modified":"2024-02-13T17:19:05","modified_gmt":"2024-02-13T22:19:05","slug":"reminders-case-examples","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/","title":{"rendered":"Exemplos de casos de lembretes"},"content":{"rendered":"<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\">\n\t Antes de ler esta p\u00e1gina, n\u00e3o deixe de consultar nosso <a href=\"http:\/\/docs.memberpress.com\/article\/147-creating-reminders\" target=\"_blank\" rel=\"noopener\">Cria\u00e7\u00e3o de um lembrete<\/a> para obter uma boa vis\u00e3o geral das configura\u00e7\u00f5es explicadas nesta p\u00e1gina.<\/p><p>\n\t Abaixo est\u00e3o alguns exemplos de casos de como realizar tarefas espec\u00edficas com o MemberPress Reminders. Clique no exemplo de caso abaixo para ser levado diretamente a ele:<\/p><ul class=\"callout\">\n\t<li><a href=\"#drip\">Lembretes de conte\u00fado de gotejamento<\/a><\/li>\t<li><a href=\"#abandoned\">Recuperar um usu\u00e1rio ap\u00f3s um checkout abandonado<\/a><\/li>\t<li><a href=\"#failed\">Como evitar falhas de pagamento causadas por cart\u00f5es de cr\u00e9dito vencidos<\/a><\/li>\t<li><a href=\"#instructions\">Fornecimento de instru\u00e7\u00f5es adicionais ap\u00f3s a assinatura<\/a><\/li>\t<li><a href=\"#upsell\">Upsells estrat\u00e9gicos<\/a><\/li>\t<li><a href=\"#win\">E-mails de retorno do usu\u00e1rio<\/a><\/li><\/ul><h2 id=\"drip\">Lembretes de conte\u00fado de gotejamento<\/h2><p>\n\t Quando <a href=\"http:\/\/docs.memberpress.com\/article\/186-dripping-and-expiring-content\" target=\"_blank\" rel=\"noopener\">conte\u00fado de gotejamento com MemberPress<\/a>, voc\u00ea pode notificar seus usu\u00e1rios quando o conte\u00fado por gotejamento estiver dispon\u00edvel. Isso pode ser feito facilmente criando um lembrete espec\u00edfico para cada sequ\u00eancia de gotejamento que voc\u00ea tiver. Isso pode ser feito usando o lembrete \u2018ap\u00f3s a inscri\u00e7\u00e3o dos membros'.<\/p><p>\n\t Assim, por exemplo, se voc\u00ea tiver um conte\u00fado que \u00e9 distribu\u00eddo todos os meses, voc\u00ea o configuraria da seguinte forma:<\/p><ol>\n\t<li>Crie um lembrete \u2018ap\u00f3s a inscri\u00e7\u00e3o do membro' para cada m\u00eas.\n\t<ol>\n\t\t<li>Isso \u00e9 feito definindo o primeiro para ter um gatilho de \u20181 m\u00eas', o segundo \u20182 meses', etc.<\/li>\t<\/ol><\/li>\t<li>(Opcional) Desative o e-mail do administrador para cada lembrete para evitar o recebimento desses avisos.\u00a0<\/li>\t<li>Use o recurso \u2018Enviar apenas para associa\u00e7\u00f5es espec\u00edficas' na se\u00e7\u00e3o \u2018E-mails' de cada lembrete para configur\u00e1-los para enviar apenas aos assinantes da associa\u00e7\u00e3o correta.<\/li>\t<li>Edite cada e-mail de lembrete enviado ao usu\u00e1rio com qualquer informa\u00e7\u00e3o relevante, links diretos, etc.\u00a0<\/li>\t<li>Certifique-se de salvar cada e-mail de lembrete usando o bot\u00e3o \u2018Atualizar' na p\u00e1gina de edi\u00e7\u00e3o de cada lembrete.<\/li><\/ol><p>\n\t \u00c9 isso a\u00ed!<\/p><p>\n\t<em>Observa\u00e7\u00e3o importante: esses lembretes ser\u00e3o <strong>n\u00e3o<\/strong> ser\u00e3o interrompidos se a assinatura de um usu\u00e1rio for cancelada ou pausada, portanto, n\u00e3o adicione conte\u00fado ativo somente para usu\u00e1rios aos seus e-mails. Em vez disso, use links para conte\u00fado protegido, de modo que, se houver um lapso na assinatura do usu\u00e1rio, ele n\u00e3o ter\u00e1 acesso a nenhum conte\u00fado protegido.\u00a0<\/em><\/p><p>\n\t<a class=\"callout dashed\" href=\"#top\">Voltar ao topo<\/a><\/p><h2 id=\"abandoned\">Recuperar um usu\u00e1rio ap\u00f3s um checkout abandonado<\/h2><p>\u00a0Se voc\u00ea configurar o MemberPress para usar um processo de registro em duas etapas, \u00e9 poss\u00edvel que os usu\u00e1rios abandonem o checkout depois de enviar suas informa\u00e7\u00f5es de usu\u00e1rio, mas antes de inserir os detalhes de pagamento. Muitas vezes, enviar um e-mail a um usu\u00e1rio ap\u00f3s esse evento pode incentiv\u00e1-lo a voltar, pedir mais informa\u00e7\u00f5es ou fazer outras coisas para ajudar a convert\u00ea-lo em assinante pagante. Observe que, mesmo que voc\u00ea configure o MemberPress para usar um <a href=\"\/pt\/Enable a Single Page Checkout (and invoice)\/\" target=\"_blank\" rel=\"noopener\">checkout de p\u00e1gina \u00fanica<\/a>Se voc\u00ea usar o PayPal (plataforma padr\u00e3o ou comercial) ou o Stripe Checkout como gateway de pagamento, poder\u00e1 configurar o mesmo lembrete.<\/p><p>\n\t Configurar um lembrete \u2018ap\u00f3s abandono da inscri\u00e7\u00e3o' \u00e9 a solu\u00e7\u00e3o para isso!<\/p><p>\n\t Ao configurar esse lembrete, observe estas pr\u00e1ticas recomendadas:<\/p><ul>\n\t<li>N\u00e3o defina esse lembrete para menos de 12 horas ap\u00f3s o evento de acionamento. Isso ocorre porque o usu\u00e1rio pode retornar em breve por conta pr\u00f3pria, etc.<\/li>\t<li>Edite o e-mail para proporcionar uma experi\u00eancia mais pessoal aos seus usu\u00e1rios.\u00a0<\/li>\t<li>Embora o e-mail padr\u00e3o forne\u00e7a algumas instru\u00e7\u00f5es b\u00e1sicas sobre esse processo, esse e-mail de lembrete foi criado para ser enviado enquanto o usu\u00e1rio ainda estiver conectado (o que acontece automaticamente ap\u00f3s a primeira etapa de registro). Portanto, voc\u00ea pode querer especificar que o usu\u00e1rio deve fazer login primeiro <em>e depois<\/em> clicar no link que colocamos no e-mail, caso tenham sido desconectados automaticamente. Adicionar um link direto para a sua p\u00e1gina de login pode facilitar muito essa tarefa para o usu\u00e1rio.<\/li>\t<li>Considere adicionar algum incentivo para que eles retornem e concluam o registro, como: <a href=\"http:\/\/docs.memberpress.com\/category\/131-creating-and-managing-coupons\" target=\"_blank\" rel=\"noopener\">um cupom<\/a>etc.\u00a0<\/li><\/ul><p>\n\t<a class=\"callout dashed\" href=\"#top\">Voltar ao topo<\/a><\/p><h2 id=\"failed\">Como evitar falhas de pagamento causadas por cart\u00f5es de cr\u00e9dito vencidos<\/h2><p>\n\t Um motivo comum para um usu\u00e1rio ter uma falha na assinatura \u00e9 um pagamento n\u00e3o realizado devido ao vencimento do cart\u00e3o de cr\u00e9dito. Para evitar a perda de pagamentos e, potencialmente, de seus clientes, considere usar nosso lembrete \u2018antes do vencimento do cart\u00e3o de cr\u00e9dito'. Certifique-se de seguir algumas dessas pr\u00e1ticas recomendadas ao criar esse lembrete:<\/p><ul>\n\t<li>Defina o acionador (por exemplo, 2 semanas, 3 meses etc.) adequadamente para os termos de pre\u00e7os de sua associa\u00e7\u00e3o, geralmente com o mesmo per\u00edodo de tempo de suas cobran\u00e7as.\u00a0\n\t<ul>\n\t\t<li>Por exemplo, se sua assinatura for mensal, use um lembrete desse tipo, acionado com a configura\u00e7\u00e3o \u20181 m\u00eas'.<\/li>\t<\/ul><\/li>\t<li>N\u00e3o utilize a fun\u00e7\u00e3o \u2018Enviar apenas para associa\u00e7\u00f5es espec\u00edficas' na se\u00e7\u00e3o \u2018E-mails', pois provavelmente desejar\u00e1 que este lembrete seja enviado para todas as suas associa\u00e7\u00f5es.\u00a0<\/li>\t<li>Considere dar mais \u00eanfase \u00e0 qualidade do conte\u00fado do seu site \u2013 se eles n\u00e3o atualizarem as informa\u00e7\u00f5es do cart\u00e3o de cr\u00e9dito, perder\u00e3o o acesso a todo o conte\u00fado assinado!<\/li><\/ul><p>\n\t<em>Observa\u00e7\u00e3o importante: este lembrete n\u00e3o funcionar\u00e1 se o usu\u00e1rio se inscreveu atrav\u00e9s de uma conta PayPal. Isso ocorre porque ele pagou com a conta, mas o MemberPress n\u00e3o tem como acessar essa conta e saber a data de validade dos cart\u00f5es de cr\u00e9dito cadastrados.\u00a0<\/em><\/p><p>\n\t<a class=\"callout dashed\" href=\"#top\">Voltar ao topo<\/a><\/p><h2 id=\"instructions\">Fornecimento de instru\u00e7\u00f5es adicionais ap\u00f3s a assinatura<\/h2><p>\n\t Talvez seja necess\u00e1rio fornecer instru\u00e7\u00f5es adicionais que o usu\u00e1rio precisa saber depois de se inscrever, mas que voc\u00ea n\u00e3o deseja incluir nas boas-vindas ao usu\u00e1rio <a href=\"http:\/\/docs.memberpress.com\/article\/43-emails\" target=\"_blank\" rel=\"noopener\">e-mail<\/a>. Tais como:\u00a0<\/p><ul>\n\t<li>Seu site tem instru\u00e7\u00f5es adicionais de configura\u00e7\u00e3o para que o usu\u00e1rio possa come\u00e7ar.\u00a0<\/li>\t<li>Voc\u00ea est\u00e1 oferecendo conte\u00fado ou atividades fora do site que o usu\u00e1rio precisa conhecer.<\/li>\t<li>Voc\u00ea deseja enviar ao usu\u00e1rio mais informa\u00e7\u00f5es sobre o que ele tem acesso com sua assinatura.\u00a0<\/li><\/ul><p>\n\t Por qualquer uma dessas raz\u00f5es e outras mais, voc\u00ea pode enviar a cada usu\u00e1rio um e-mail com essas informa\u00e7\u00f5es simplesmente usando um \u00fanico lembrete \u2018ap\u00f3s a inscri\u00e7\u00e3o do membro' para cada associa\u00e7\u00e3o relevante em seu site.\u00a0<\/p><p>\n\t Certifique-se de editar o lembrete adequadamente e selecionar a associa\u00e7\u00e3o correta no recurso \u2018Enviar apenas para associa\u00e7\u00f5es espec\u00edficas' na se\u00e7\u00e3o \u2018E-mails'.<\/p><p>\n\t<a class=\"callout dashed\" href=\"#top\">Voltar ao topo<\/a><\/p><h2 id=\"upsell\">Upsells estrat\u00e9gicos<\/h2><p>\n\t No momento, o MemberPress n\u00e3o tem nenhum recurso espec\u00edfico de upsell, mas voc\u00ea pode usar facilmente nossos Lembretes para fazer algo semelhante.\u00a0<\/p><p>\n\t Para isso, recomendamos usar nossos lembretes \u2018antes do vencimento da assinatura' ou \u2018ap\u00f3s o vencimento da assinatura'. Aqui est\u00e3o algumas pr\u00e1ticas recomendadas a serem consideradas ao usar esses e-mails de lembrete para oferecer vendas adicionais.<\/p><ul>\n\t<li>Tenha em mente o tipo de lembrete que voc\u00ea usa. Dependendo da sua configura\u00e7\u00e3o, pode ser melhor enviar o e-mail antes que a assinatura do usu\u00e1rio expire e, para outros, pode ser depois que ela j\u00e1 tiver expirado.\u00a0<\/li>\t<li>Defina o gatilho para o que seria o seu \u201cmomento m\u00e1gico\u201d para obter as melhores convers\u00f5es. Geralmente, isso \u00e9 cedo o suficiente para dar tempo ao usu\u00e1rio para considerar, mas <em>n\u00e3o <\/em>tarde demais, ent\u00e3o o usu\u00e1rio j\u00e1 n\u00e3o se importa mais.\u00a0<\/li>\t<li>Considere adicionar um <a href=\"http:\/\/docs.memberpress.com\/category\/131-creating-and-managing-coupons\" target=\"_blank\" rel=\"noopener\">c\u00f3digo de cupom<\/a> para o e-mail de lembrete do usu\u00e1rio para oferecer um desconto especial.\u00a0\n\t<ul>\n\t\t<li>Se voc\u00ea fizer isso, certifique-se de revisar os artigos sobre \u2018c\u00f3digos de cupom' no link acima para garantir que voc\u00ea entenda corretamente como nossos cupons funcionam.\u00a0<\/li>\t\t<li>Lembre-se de que voc\u00ea precisar\u00e1 atualizar esse c\u00f3digo de cupom periodicamente se optar por definir uma data de validade ou um limite de uso para o cupom (o que \u00e9 recomendado, pois os c\u00f3digos de cupom podem ser facilmente compartilhados).\u00a0<\/li>\t<\/ul><\/li>\t<li>(Opcional) Desative o e-mail do administrador para cada lembrete desse tipo para evitar o recebimento desses avisos.\u00a0<\/li>\t<li>Adicione alguma forma de contato (seu ou de outra pessoa) ou p\u00e1gina que o usu\u00e1rio possa contatar ou usar para saber mais sobre por que ele deve assinar sua associa\u00e7\u00e3o de upsell.\u00a0<\/li><\/ul><p>\n\t<a class=\"callout dashed\" href=\"#top\">Voltar ao topo<\/a><\/p><h2 id=\"win\">E-mails de retorno do usu\u00e1rio<\/h2><p>\n\t Os e-mails de reconquista s\u00e3o e-mails usados para \u2018reconquistar' ou incentivar um usu\u00e1rio a voltar ao seu site, geralmente enviados ap\u00f3s algum tipo de data de validade ser atingida ( \n\t<a href=\"https:\/\/www.klaviyo.com\/blog\/winback-email-campaign-examples\" target=\"_blank\" rel=\"noopener\">Saiba mais aqui<\/a>).<\/p><p>\n\t No MemberPress, isso pode ser feito facilmente com nosso e-mail de lembrete \u2018Ap\u00f3s o vencimento da assinatura'. Basta considerar algumas das seguintes pr\u00e1ticas recomendadas ao criar um e-mail de lembrete \u2018Recupera\u00e7\u00e3o':<\/p><ul>\n\t<li>Certifique-se de editar o e-mail com todos os seus melhores motivos para que o usu\u00e1rio retorne \u00e0 sua associa\u00e7\u00e3o.\u00a0<\/li>\t<li>Defina o gatilho adequadamente. Voc\u00ea n\u00e3o quer parecer muito carente, enviando-o logo ap\u00f3s a expira\u00e7\u00e3o da assinatura, mas tamb\u00e9m n\u00e3o quer que a data de expira\u00e7\u00e3o pare\u00e7a apenas uma reflex\u00e3o tardia.<\/li>\t<li>Considere adicionar algum tipo de <a href=\"http:\/\/docs.memberpress.com\/category\/131-creating-and-managing-coupons\">c\u00f3digo de cupom<\/a> ou oferta especial para motivar o usu\u00e1rio a retornar.\u00a0\n\t<ul>\n\t\t<li>Se voc\u00ea usar um cupom, certifique-se de ler os artigos sobre \u2018c\u00f3digos de cupom' no link acima para entender corretamente como nossos cupons funcionam.\u00a0<\/li>\t\t<li>Lembre-se de que voc\u00ea precisar\u00e1 atualizar esse c\u00f3digo de cupom periodicamente se optar por definir um limite de validade ou de uso para o cupom (o que \u00e9 aconselh\u00e1vel, pois os c\u00f3digos de cupom podem ser facilmente compartilhados).\u00a0<\/li>\t<\/ul><\/li>\t<li>(Opcional) Ative o e-mail do administrador para cada lembrete desse tipo se voc\u00ea estiver interessado em ficar de olho na taxa de sucesso desse lembrete. Ou desative o e-mail do administrador se preferir n\u00e3o ser incomodado por ele. \u00a0<\/li><\/ul><p>\n\t<a class=\"callout dashed\" href=\"#top\">Voltar ao topo<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content Reminders Getting a User Back After Abandoned Checkout Avoiding Failed Payments Caused by Expired Credit Cards Providing Additional After-Signup Instructions Strategic Upsells User Win-Back Emails [\u2026]<\/p>\n","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1321],"ht-kb-tag":[],"class_list":{"0":"post-61520","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-reminders","7":"entry"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Reminders Case Examples | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T12:38:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-13T22:19:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Reminders Case Examples | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/reminders-case-examples\\\/#article\",\"name\":\"Reminders Case Examples | MemberPress\",\"headline\":\"Reminders Case Examples\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#articleImage\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"datePublished\":\"2024-02-13T07:38:00-05:00\",\"dateModified\":\"2024-02-13T17:19:05-05:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/reminders-case-examples\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/reminders-case-examples\\\/#webpage\"},\"articleSection\":\"Reminders\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/reminders-case-examples\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/pt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/general\\\/#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/general\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/emails-and-notifications\\\/#listItem\",\"name\":\"Emails and Notifications\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/emails-and-notifications\\\/#listItem\",\"position\":3,\"name\":\"Emails and Notifications\",\"item\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/emails-and-notifications\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/reminders\\\/#listItem\",\"name\":\"Reminders\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/reminders\\\/#listItem\",\"position\":4,\"name\":\"Reminders\",\"item\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/reminders\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/reminders-case-examples\\\/#listItem\",\"name\":\"Reminders Case Examples\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/emails-and-notifications\\\/#listItem\",\"name\":\"Emails and Notifications\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/reminders-case-examples\\\/#listItem\",\"position\":5,\"name\":\"Reminders Case Examples\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/reminders\\\/#listItem\",\"name\":\"Reminders\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/reminders-case-examples\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/reminders-case-examples\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/reminders-case-examples\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/reminders-case-examples\\\/\",\"name\":\"Reminders Case Examples | MemberPress\",\"description\":\"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/reminders-case-examples\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-02-13T07:38:00-05:00\",\"dateModified\":\"2024-02-13T17:19:05-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Reminders Case Examples | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Exemplos de casos de lembretes | MemberPress","description":"Antes de ler esta p\u00e1gina, n\u00e3o deixe de consultar a p\u00e1gina Criando um lembrete para ter uma boa vis\u00e3o geral das configura\u00e7\u00f5es explicadas nesta p\u00e1gina. Abaixo est\u00e3o alguns exemplos de casos sobre como realizar tarefas espec\u00edficas com o MemberPress Reminders. Clique no exemplo de caso abaixo para ser levado diretamente a ele: Pingando conte\u00fado","canonical_url":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/#article","name":"Reminders Case Examples | MemberPress","headline":"Reminders Case Examples","author":{"@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/pt\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/pt\/#articleImage","width":1650,"height":1275,"caption":"memberpress logo icon"},"datePublished":"2024-02-13T07:38:00-05:00","dateModified":"2024-02-13T17:19:05-05:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/#webpage"},"articleSection":"Reminders"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/pt","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/general\/#listItem","position":2,"name":"General","item":"https:\/\/memberpress.com\/pt\/doc-categories\/general\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/emails-and-notifications\/#listItem","name":"Emails and Notifications"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/emails-and-notifications\/#listItem","position":3,"name":"Emails and Notifications","item":"https:\/\/memberpress.com\/pt\/doc-categories\/emails-and-notifications\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/reminders\/#listItem","name":"Reminders"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/reminders\/#listItem","position":4,"name":"Reminders","item":"https:\/\/memberpress.com\/pt\/doc-categories\/reminders\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/#listItem","name":"Reminders Case Examples"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/emails-and-notifications\/#listItem","name":"Emails and Notifications"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/#listItem","position":5,"name":"Reminders Case Examples","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/reminders\/#listItem","name":"Reminders"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/pt\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/pt\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/#webpage","url":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/","name":"Reminders Case Examples | MemberPress","description":"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/memberpress.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-02-13T07:38:00-05:00","dateModified":"2024-02-13T17:19:05-05:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/pt\/#website","url":"https:\/\/memberpress.com\/pt\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/memberpress.com\/pt\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"MemberPress","og:type":"article","og:title":"Reminders Case Examples | MemberPress","og:description":"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content","og:url":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-02-13T12:38:00+00:00","article:modified_time":"2024-02-13T22:19:05+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Reminders Case Examples | MemberPress","twitter:description":"Before you read this page, be sure to review our Creating a Reminder page for a good overview of the settings explained on this page. Below are a couple of case examples of how to accomplish specific tasks with MemberPress Reminders. Click on the case example below to be taken directly to it: Dripping Content","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"61520","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-09 21:38:12","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2024-02-13 12:38:01","updated":"2026-03-03 14:53:49"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/pt\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/pt\/doc-categories\/general\/\" title=\"General\">General<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/pt\/doc-categories\/emails-and-notifications\/\" title=\"Emails and Notifications\">Emails and Notifications<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/pt\/doc-categories\/reminders\/\" title=\"Reminders\">Reminders<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tReminders Case Examples\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/pt"},{"label":"General","link":"https:\/\/memberpress.com\/pt\/doc-categories\/general\/"},{"label":"Emails and Notifications","link":"https:\/\/memberpress.com\/pt\/doc-categories\/emails-and-notifications\/"},{"label":"Reminders","link":"https:\/\/memberpress.com\/pt\/doc-categories\/reminders\/"},{"label":"Reminders Case Examples","link":"https:\/\/memberpress.com\/pt\/docs\/reminders-case-examples\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb\/61520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/comments?post=61520"}],"version-history":[{"count":0,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb\/61520\/revisions"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/media?parent=61520"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb-category?post=61520"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb-tag?post=61520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}