{"id":62376,"date":"2024-02-13T09:32:35","date_gmt":"2024-02-13T14:32:35","guid":{"rendered":"https:\/\/memberpress.com\/docs\/do-you-have-a-demo\/"},"modified":"2024-02-13T17:17:59","modified_gmt":"2024-02-13T22:17:59","slug":"do-you-have-a-demo","status":"publish","type":"ht_kb","link":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/","title":{"rendered":"Voc\u00ea tem uma demonstra\u00e7\u00e3o?"},"content":{"rendered":"<p>Sim! Voc\u00ea encontrar\u00e1 a demonstra\u00e7\u00e3o do MemberPress, juntamente com informa\u00e7\u00f5es adicionais sobre o plug-in, em nosso <a href=\"https:\/\/memberpress.com\/pt\/demo\/\" target=\"_blank\" rel=\"noopener\">p\u00e1gina de demonstra\u00e7\u00e3o<\/a>. <\/p>\n<p>Para ver algumas das coisas incr\u00edveis que outros empreendedores est\u00e3o fazendo com o MemberPress, confira nosso artigo, <a href=\"https:\/\/memberpress.com\/pt\/blog\/memberpress-website-examples\/\" target=\"_blank\" rel=\"noopener\">Mais de 100 exemplos de sites de associa\u00e7\u00e3o<\/a>.<\/p>\n<p>E lembre-se: sua compra \u00e9 sempre coberta por nossa garantia incondicional de reembolso de 14 dias.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sim! Voc\u00ea encontrar\u00e1 a demonstra\u00e7\u00e3o do MemberPress, juntamente com informa\u00e7\u00f5es adicionais sobre o plug-in, em nossa p\u00e1gina de demonstra\u00e7\u00e3o. Para ver algumas das coisas incr\u00edveis que outros empreendedores est\u00e3o fazendo com o MemberPress, confira nosso artigo, Mais de 100 exemplos de sites de assinatura. E lembre-se, sua compra est\u00e1 sempre coberta por nossa garantia incondicional de reembolso de 14 dias.<\/p>","protected":false},"author":62252,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_strive_checklists":"\"\"","_strive_active_checklist":"62291e2bb2422","footnotes":""},"ht-kb-category":[1288],"ht-kb-tag":[],"class_list":{"0":"post-62376","1":"ht_kb","2":"type-ht_kb","3":"status-publish","4":"format-standard","6":"ht_kb_category-plugin-faqs","7":"entry"},"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Yes! You&#039;ll find the MemberPress Demo, along with additional information about the plugin, on our demo page. To see some of the amazing things other entrepreneurs are doing with MemberPress, check out our article, 100+ Membership Site Examples. And remember, your purchase is always covered by our 14-day, unconditional money-back guarantee.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nikola M\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MemberPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Do you have a demo? | MemberPress\" \/>\n\t\t<meta property=\"og:description\" content=\"Yes! You&#039;ll find the MemberPress Demo, along with additional information about the plugin, on our demo page. To see some of the amazing things other entrepreneurs are doing with MemberPress, check out our article, 100+ Membership Site Examples. And remember, your purchase is always covered by our 14-day, unconditional money-back guarantee.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T14:32:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-13T22:17:59+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/memberpress\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@memberpress\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Do you have a demo? | MemberPress\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Yes! You&#039;ll find the MemberPress Demo, along with additional information about the plugin, on our demo page. To see some of the amazing things other entrepreneurs are doing with MemberPress, check out our article, 100+ Membership Site Examples. And remember, your purchase is always covered by our 14-day, unconditional money-back guarantee.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-you-have-a-demo\\\/#article\",\"name\":\"Do you have a demo? | MemberPress\",\"headline\":\"Do you have a demo?\",\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#articleImage\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"datePublished\":\"2024-02-13T09:32:35-05:00\",\"dateModified\":\"2024-02-13T17:17:59-05:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-you-have-a-demo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-you-have-a-demo\\\/#webpage\"},\"articleSection\":\"Plugin FAQs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-you-have-a-demo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/memberpress.com\\\/pt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/faqs\\\/#listItem\",\"name\":\"FAQs\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/faqs\\\/#listItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/faqs\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/plugin-faqs\\\/#listItem\",\"name\":\"Plugin FAQs\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/plugin-faqs\\\/#listItem\",\"position\":3,\"name\":\"Plugin FAQs\",\"item\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/plugin-faqs\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-you-have-a-demo\\\/#listItem\",\"name\":\"Do you have a demo?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/faqs\\\/#listItem\",\"name\":\"FAQs\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-you-have-a-demo\\\/#listItem\",\"position\":4,\"name\":\"Do you have a demo?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/doc-categories\\\/plugin-faqs\\\/#listItem\",\"name\":\"Plugin FAQs\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#organization\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mp-icon-RGB_Icon-01.jpg\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-you-have-a-demo\\\/#organizationLogo\",\"width\":1650,\"height\":1275,\"caption\":\"memberpress logo icon\"},\"image\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-you-have-a-demo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/memberpress\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/memberpressplugin\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MemberPressPlugin\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/memberpress\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/\",\"name\":\"Nikola M\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/memberpress.com\\\/wp-content\\\/litespeed\\\/avatar\\\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-you-have-a-demo\\\/#webpage\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-you-have-a-demo\\\/\",\"name\":\"Do you have a demo? | MemberPress\",\"description\":\"Yes! You'll find the MemberPress Demo, along with additional information about the plugin, on our demo page. To see some of the amazing things other entrepreneurs are doing with MemberPress, check out our article, 100+ Membership Site Examples. And remember, your purchase is always covered by our 14-day, unconditional money-back guarantee.\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/docs\\\/do-you-have-a-demo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/blog\\\/author\\\/nikolacaseproof-com\\\/#author\"},\"datePublished\":\"2024-02-13T09:32:35-05:00\",\"dateModified\":\"2024-02-13T17:17:59-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/\",\"name\":\"MemberPress\",\"description\":\"The All-In-One WordPress Membership Plugin\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/memberpress.com\\\/pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Do you have a demo? | MemberPress<\/title>\n\n","aioseo_head_json":{"title":"Voc\u00ea tem uma demonstra\u00e7\u00e3o? | MemberPress","description":"Sim! Voc\u00ea encontrar\u00e1 a demonstra\u00e7\u00e3o do MemberPress, juntamente com informa\u00e7\u00f5es adicionais sobre o plug-in, em nossa p\u00e1gina de demonstra\u00e7\u00e3o. Para ver algumas das coisas incr\u00edveis que outros empreendedores est\u00e3o fazendo com o MemberPress, confira nosso artigo, Mais de 100 exemplos de sites de associa\u00e7\u00e3o. E lembre-se: sua compra \u00e9 sempre coberta por nossa garantia incondicional de reembolso de 14 dias.","canonical_url":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/#article","name":"Do you have a demo? | MemberPress","headline":"Do you have a demo?","author":{"@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author"},"publisher":{"@id":"https:\/\/memberpress.com\/pt\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/pt\/#articleImage","width":1650,"height":1275,"caption":"memberpress logo icon"},"datePublished":"2024-02-13T09:32:35-05:00","dateModified":"2024-02-13T17:17:59-05:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/#webpage"},"isPartOf":{"@id":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/#webpage"},"articleSection":"Plugin FAQs"},{"@type":"BreadcrumbList","@id":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt#listItem","position":1,"name":"Home","item":"https:\/\/memberpress.com\/pt","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/#listItem","name":"FAQs"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/#listItem","position":2,"name":"FAQs","item":"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/#listItem","name":"Plugin FAQs"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/#listItem","position":3,"name":"Plugin FAQs","item":"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/","nextItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/#listItem","name":"Do you have a demo?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/#listItem","name":"FAQs"}},{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/#listItem","position":4,"name":"Do you have a demo?","previousItem":{"@type":"ListItem","@id":"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/#listItem","name":"Plugin FAQs"}}]},{"@type":"Organization","@id":"https:\/\/memberpress.com\/pt\/#organization","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","url":"https:\/\/memberpress.com\/pt\/","logo":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","@id":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/#organizationLogo","width":1650,"height":1275,"caption":"memberpress logo icon"},"image":{"@id":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/memberpress\/","https:\/\/www.pinterest.com\/memberpressplugin\/","https:\/\/www.youtube.com\/c\/MemberPressPlugin","https:\/\/www.linkedin.com\/company\/memberpress\/"]},{"@type":"Person","@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author","url":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/","name":"Nikola M","image":{"@type":"ImageObject","url":"https:\/\/memberpress.com\/wp-content\/litespeed\/avatar\/1edf820c48f9c430f380efe81887b154.jpg?ver=1778165144"}},{"@type":"WebPage","@id":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/#webpage","url":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/","name":"Do you have a demo? | MemberPress","description":"Yes! You'll find the MemberPress Demo, along with additional information about the plugin, on our demo page. To see some of the amazing things other entrepreneurs are doing with MemberPress, check out our article, 100+ Membership Site Examples. And remember, your purchase is always covered by our 14-day, unconditional money-back guarantee.","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/memberpress.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/#breadcrumblist"},"author":{"@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author"},"creator":{"@id":"https:\/\/memberpress.com\/pt\/blog\/author\/nikolacaseproof-com\/#author"},"datePublished":"2024-02-13T09:32:35-05:00","dateModified":"2024-02-13T17:17:59-05:00"},{"@type":"WebSite","@id":"https:\/\/memberpress.com\/pt\/#website","url":"https:\/\/memberpress.com\/pt\/","name":"MemberPress","description":"The All-In-One WordPress Membership Plugin","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/memberpress.com\/pt\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"MemberPress","og:type":"article","og:title":"Do you have a demo? | MemberPress","og:description":"Yes! You'll find the MemberPress Demo, along with additional information about the plugin, on our demo page. To see some of the amazing things other entrepreneurs are doing with MemberPress, check out our article, 100+ Membership Site Examples. And remember, your purchase is always covered by our 14-day, unconditional money-back guarantee.","og:url":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/","og:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:secure_url":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg","og:image:width":1650,"og:image:height":1275,"article:published_time":"2024-02-13T14:32:35+00:00","article:modified_time":"2024-02-13T22:17:59+00:00","article:publisher":"https:\/\/www.facebook.com\/memberpress\/","twitter:card":"summary_large_image","twitter:site":"@memberpress","twitter:title":"Do you have a demo? | MemberPress","twitter:description":"Yes! You'll find the MemberPress Demo, along with additional information about the plugin, on our demo page. To see some of the amazing things other entrepreneurs are doing with MemberPress, check out our article, 100+ Membership Site Examples. And remember, your purchase is always covered by our 14-day, unconditional money-back guarantee.","twitter:image":"https:\/\/memberpress.com\/wp-content\/uploads\/2022\/10\/mp-icon-RGB_Icon-01.jpg"},"aioseo_meta_data":{"post_id":"62376","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-09 21:59:10","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2024-02-13 14:32:36","updated":"2026-03-03 14:52:42"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/pt\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/\" title=\"FAQs\">FAQs<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/\" title=\"Plugin FAQs\">Plugin FAQs<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tDo you have a demo?\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/memberpress.com\/pt"},{"label":"FAQs","link":"https:\/\/memberpress.com\/pt\/doc-categories\/faqs\/"},{"label":"Plugin FAQs","link":"https:\/\/memberpress.com\/pt\/doc-categories\/plugin-faqs\/"},{"label":"Do you have a demo?","link":"https:\/\/memberpress.com\/pt\/docs\/do-you-have-a-demo\/"}],"_links":{"self":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb\/62376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/users\/62252"}],"replies":[{"embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/comments?post=62376"}],"version-history":[{"count":0,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb\/62376\/revisions"}],"wp:attachment":[{"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/media?parent=62376"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb-category?post=62376"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/memberpress.com\/pt\/wp-json\/wp\/v2\/ht-kb-tag?post=62376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}